{"id":18632,"date":"2014-07-28T11:16:54","date_gmt":"2014-07-28T09:16:54","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=18632"},"modified":"2014-07-28T13:23:50","modified_gmt":"2014-07-28T11:23:50","slug":"tempodestate-2014-mercoledi-i-senza-tempo-a-tuturano","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/tempodestate-2014-mercoledi-i-senza-tempo-a-tuturano\/","title":{"rendered":"#tempodestate 2014: mercoled\u00ec i &#8220;Senza Tempo&#8221; a Tuturano"},"content":{"rendered":"<p>Nell\u2019ambito della programmazione estiva organizzata dal Comune di Brindisi, con la collaborazione tecnica della Fondazione Nuovo Teatro Verdi, mercoled\u00ec 30 luglio, alle ore 21,00, a Tuturano, in Piazza Regina Margherita, si esibir\u00e0 la band dei \u201cSenza Tempo\u201d.<br \/>\nLa musica, si sa, pu\u00f2 essere una favolosa macchina del tempo. Ed infatti i \u201cSenza Tempo\u201d presentano un viaggio su spartiti attraverso l\u2019immaginario musicale che ci tiene legati agli anni Sessanta e Settanta. Quegli anni ci hanno consegnato la pi\u00f9 potente stagione creativa della storia della musica italiana contemporanea e lo spettacolo ne vuole evocare l\u2019immagine gioiosa e gloriosa.<br \/>\nA latere del concerto ci sar\u00e0 anche una ricca degustazione di prodotti tipici locali.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMUNICATO STAMPA AMMINISTRAZIONE COMUNALE DI BRINDISI<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell\u2019ambito della programmazione estiva organizzata dal Comune di Brindisi, con la collaborazione tecnica della Fondazione Nuovo Teatro Verdi, mercoled\u00ec 30 luglio, alle ore 21,00, a Tuturano, in Piazza Regina Margherita, si esibir\u00e0 la band dei \u201cSenza Tempo\u201d. La musica, si sa, pu\u00f2 essere una favolosa macchina del tempo. Ed infatti i \u201cSenza Tempo\u201d presentano un viaggio su spartiti attraverso l\u2019immaginario musicale che ci tiene legati agli anni Sessanta e Settanta. Quegli anni ci hanno consegnato la pi\u00f9 potente stagione creativa della storia della musica italiana contemporanea e lo spettacolo ne vuole evocare l\u2019immagine gioiosa e gloriosa. A latere del concerto ci sar\u00e0 anche una ricca degustazione di prodotti tipici locali. &nbsp; COMUNICATO STAMPA AMMINISTRAZIONE COMUNALE DI BRINDISI<\/p>\n","protected":false},"author":2,"featured_media":17989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2332],"class_list":["post-18632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-tempodestate"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/18632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=18632"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/18632\/revisions"}],"predecessor-version":[{"id":18633,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/18632\/revisions\/18633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/17989"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=18632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=18632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=18632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}