{"id":18850,"date":"2014-07-30T18:03:43","date_gmt":"2014-07-30T16:03:43","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=18850"},"modified":"2014-07-30T18:03:43","modified_gmt":"2014-07-30T16:03:43","slug":"pd-e-gd-attivano-sportello-informativo-sul-progetto-garanzia-giovani","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/pd-e-gd-attivano-sportello-informativo-sul-progetto-garanzia-giovani\/","title":{"rendered":"PD e GD attivano sportello informativo sul progetto &#8220;Garanzia Giovani&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/garanzia-giovani.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-14923\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/garanzia-giovani-300x178.jpg\" alt=\"garanzia-giovani\" width=\"300\" height=\"178\" data-id=\"14923\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/garanzia-giovani-300x178.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/06\/garanzia-giovani.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Rivolto a tutti i giovani tra i <b>15 e 29 anni<\/b>, <b>&#8220;Garanzia Giovani&#8221; <\/b>\u00e8 lo strumento attraverso cui l&#8217;Unione Europea vuole garantire ai soggetti privi di occupazione o fuori dal sistema di istruzione formale e della formazione professionale, un percorso di reinserimento nel sistema di istruzione e formazione o di inserimento nel mondo del lavoro attraverso le misure previste dal Programma (orientamento, tirocini, servizio civile, sostegno all&#8217;autoimpiego e mobilit\u00e0 professionale transnazionale e territoriale).<\/p>\n<p>&nbsp;<\/p>\n<p>I <b>Giovani Democratici di Brindisi <\/b>(GD) e il <b>Dipartimento Politiche Giovanili del PD Brindisi<\/b> istituiscono all\u2019interno del Circolo Cittadino in Via Conserva n\u00b06 (Angolo Corso Umberto \u2013 Piazzetta Fornaro) uno <b>Sportello Informativo <\/b>per aiutare i giovani brindisini ad approcciarsi a questa nuova opportunit\u00e0 ed al mondo del lavoro in generale.<\/p>\n<p>&nbsp;<\/p>\n<p>Un team di esperti fornir\u00e0 il proprio aiuto registrando all\u2019interno del portale i dati dei giovani brindisini in modo da poter aderire alla Garanzia Giovani, inoltre verranno dati consigli per come compilare bene un CV, una lettera di presentazione e come approcciarsi ai primi colloqui di lavoro.<\/p>\n<p>&nbsp;<\/p>\n<p>Con la creazione di questo Sportello informativo, i GD vogliono creare uno spazio all\u2019interno del Circolo Cittadino che sia da collegamento tra le varie realt\u00e0 brindisine e i giovani, un <b>Open Space<\/b> che sia in grado di dare spazio a varie opportunit\u00e0 creando un luogo di effervescenza culturale e giovanile che dia sfogo alla creativit\u00e0 dei giovani brindisini e che sia di supporto ai ragazzi per ogni genere di problematica, che vada dalla scuola, all\u2019universit\u00e0 passando appunto dal mondo del lavoro.<\/p>\n<p>&nbsp;<\/p>\n<p>Un nuovo modo di pensare la Politica, una politica che non si chiude, ma che \u00e8 capace di rompere gli schemi, di aprirsi e di fare qualcosa di concreto per i giovani.<\/p>\n<p>Ora tocca ai giovani brindisini, raccogliere questa sfida. Veniteci a trovare o contattateci<\/p>\n<p>&nbsp;<\/p>\n<p><b>Circolo Cittadino:<\/b> Via Conserva 6 dalle 10:30 alle 12:00 e dalle 17:30 alle 20:00 (<span style=\"text-decoration: underline;\">Dal Luned\u00ec, Mercoled\u00ec e Venerd\u00ec, gli orari potranno subire delle variazioni che verranno comunicati tramite avvisi sulla pagina facebook GD Brindisi o tramite affissione su portone del Circolo<\/span>)<br \/>\nMail: Gd_Brindisi@hotmail.it o antonio.melcore@hotmail.it<\/p>\n<p>Sito Web: http:\/\/everygameblog.wix.com\/gd-sito<\/p>\n<p>Cell: 388\/1130368<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rivolto a tutti i giovani tra i 15 e 29 anni, &#8220;Garanzia Giovani&#8221; \u00e8 lo strumento attraverso cui l&#8217;Unione Europea vuole garantire ai soggetti privi di occupazione o fuori dal sistema di istruzione formale e della formazione professionale, un percorso di reinserimento nel sistema di istruzione e formazione o di inserimento nel mondo del lavoro attraverso le misure previste dal Programma (orientamento, tirocini, servizio civile, sostegno all&#8217;autoimpiego e mobilit\u00e0 professionale transnazionale e territoriale). &nbsp; I Giovani Democratici di Brindisi (GD) e il Dipartimento Politiche Giovanili del PD Brindisi istituiscono all\u2019interno del Circolo Cittadino in Via Conserva n\u00b06 (Angolo Corso Umberto \u2013 Piazzetta Fornaro) uno Sportello Informativo per aiutare i giovani brindisini ad approcciarsi a questa nuova opportunit\u00e0 ed al mondo del lavoro in generale. &nbsp; Un team di esperti fornir\u00e0 il proprio aiuto registrando all\u2019interno del portale i dati dei giovani brindisini in modo da poter aderire alla Garanzia Giovani, inoltre verranno dati consigli per come compilare bene un CV, una lettera di presentazione e come approcciarsi ai primi colloqui&#8230;<\/p>\n","protected":false},"author":2,"featured_media":14503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2052,1614,43],"class_list":["post-18850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-garanzia-giovani","tag-giovani-democratici","tag-pd"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/18850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=18850"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/18850\/revisions"}],"predecessor-version":[{"id":18853,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/18850\/revisions\/18853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/14503"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=18850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=18850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=18850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}