{"id":18966,"date":"2014-08-01T09:07:17","date_gmt":"2014-08-01T07:07:17","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=18966"},"modified":"2014-08-01T08:12:26","modified_gmt":"2014-08-01T06:12:26","slug":"aperte-le-iscrizioni-per-lo-streetball-3vs3-di-rosa-marina","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/aperte-le-iscrizioni-per-lo-streetball-3vs3-di-rosa-marina\/","title":{"rendered":"Aperte le iscrizioni per lo streetball 3vs3 di Rosa Marina"},"content":{"rendered":"<p>In attesa della nuova stagione, che vedr\u00e0 la Cestistica Ostuni impegnata nel campionato di Serie C (girone H), la societ\u00e0 giallobl\u00f9, con la collaborazione del Consorzio Cala di Rosa Marina, organizza un torneo maschile di basket 3 contro 3, per grandi e piccoli. Nel weekend dell\u20198-9-10 agosto, nella splendida cornice di Cala di Rosa Marina, a due passi dalla spiaggia, chi vorr\u00e0 potr\u00e0 misurarsi con amici e avversari nella prima edizione di questa competizione, ideata proprio per essere riproposta nei prossimi anni e diventare un punto di riferimento per gli appassionati di pallacanestro della zona, un appuntamento fisso per l\u2019estate ostunese.<br \/>\nIl torneo sar\u00e0 diviso in due categorie: under (per i nati dopo il 1\u00b0 gennaio 1996) e free (senza limiti di et\u00e0). L\u2019organizzazione \u00e8 a cura della Cestistica Ostuni e del Consorzio Cala di Rosa Marina, con la collaborazione del White Ostuni Beach Club: in palio tanti premi messi a disposizione da diversi sponsor, che hanno voluto gentilmente legare il loro marchio a quello di C3StreetBall.<br \/>\nIl costo di iscrizione \u00e8 di 40 euro a squadra per la categoria under e di 60 euro a squadra per la categoria free. Tanti i premi previsti, daquello di MVP al miglior giovane, dal capocannoniere al vincitore della gara di tiro da 3 punti, fino a quello in denaro per la vincitrice della finalissima (abbinato ad una giornata relax presso il White Ostuni Beach Club) ed altre iniziative legate al Consorzio di Cala di Rosa Marina. Per maggiori informazioni e per le iscrizioni, \u00e8 attiva una pagina Facebook (C3streetball \u2013 Basket 3vs3) alla quale ci si pu\u00f2 rivolgere in qualsiasi momento. In alternativa, si pu\u00f2 contattare direttamente l\u2019addetto stampa della Cestistica, Domenico Zurlo, all\u2019indirizzo e-mail zurlovic@hotmail.com.<br \/>\nIntanto la Fip ha ufficializzato il calendario provvisorio del girone H della prossima Serie C, che vedr\u00e0 impegnata la Cestistica Ostuni insieme ad altre 14 squadre. Si parte il 28 settembre ad Agropoli, mentre il debutto casalingo, contro Castellammare di Stabia, sar\u00e0 una settimana dopo, il 5 ottobre. Quattro i derby pugliesi, contro San Severo (alla 4\u00b0 giornata, 16 ottobre a Ostuni, 22 gennaio al PalaCastellana), Trani (11\u00b0 giornata, 30 novembre a Ostuni e 15 marzo a Trani), Nard\u00f2 (12\u00b0 giornata, 7 dicembre in Salento e 22 marzo al PalaGentile) e Cerignola (13\u00b0 giornata, 14 dicembre a Ostuni e 29 marzo al PalaDileo).<br \/>\nSar\u00e0 un girone complicato, con tante squadre campane e molte squadre attrezzate alla promozione in Serie B: la formula di quest\u2019anno prevede che le prime 4 squadre classificate, insieme alle prime 4 degli altri gironi, andranno a disputare un girone all\u2019italiana di playoff. La prima sar\u00e0 promossa in Serie B, le seconde disputeranno un ulteriore spareggio: per tutte le altre, si apriranno le porte della Serie C unica regionale. La societ\u00e0 giallobl\u00f9 sta lavorando al meglio per costruire una squadra competitiva, che sappia giocarsela con tutte e che faccia esaltare, anche quest\u2019anno, il pubblico del PalaGentile.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMUNICATO STAMPA CESTISTICA OSTUNI<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In attesa della nuova stagione, che vedr\u00e0 la Cestistica Ostuni impegnata nel campionato di Serie C (girone H), la societ\u00e0 giallobl\u00f9, con la collaborazione del Consorzio Cala di Rosa Marina, organizza un torneo maschile di basket 3 contro 3, per grandi e piccoli. Nel weekend dell\u20198-9-10 agosto, nella splendida cornice di Cala di Rosa Marina, a due passi dalla spiaggia, chi vorr\u00e0 potr\u00e0 misurarsi con amici e avversari nella prima edizione di questa competizione, ideata proprio per essere riproposta nei prossimi anni e diventare un punto di riferimento per gli appassionati di pallacanestro della zona, un appuntamento fisso per l\u2019estate ostunese. Il torneo sar\u00e0 diviso in due categorie: under (per i nati dopo il 1\u00b0 gennaio 1996) e free (senza limiti di et\u00e0). L\u2019organizzazione \u00e8 a cura della Cestistica Ostuni e del Consorzio Cala di Rosa Marina, con la collaborazione del White Ostuni Beach Club: in palio tanti premi messi a disposizione da diversi sponsor, che hanno voluto gentilmente legare il loro marchio a quello di C3StreetBall. Il costo di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":18967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[506,2297],"class_list":["post-18966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket","tag-cestistica-ostuni","tag-rosa-marina"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/18966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=18966"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/18966\/revisions"}],"predecessor-version":[{"id":18968,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/18966\/revisions\/18968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/18967"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=18966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=18966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=18966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}