{"id":19248,"date":"2014-08-05T18:22:11","date_gmt":"2014-08-05T16:22:11","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=19248"},"modified":"2014-08-05T18:22:11","modified_gmt":"2014-08-05T16:22:11","slug":"scoperta-spiaggia-abusiva-allinterno-del-parco-dune-costiere-2","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/scoperta-spiaggia-abusiva-allinterno-del-parco-dune-costiere-2\/","title":{"rendered":"Scoperta spiaggia abusiva all&#8217;interno del Parco Dune Costiere"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/spiaggia-abusiva-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-19250\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/spiaggia-abusiva-2-293x300.jpg\" alt=\"spiaggia abusiva 2\" width=\"293\" height=\"300\" data-id=\"19250\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/spiaggia-abusiva-2-293x300.jpg 293w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/spiaggia-abusiva-2-1000x1024.jpg 1000w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/spiaggia-abusiva-2-60x60.jpg 60w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/spiaggia-abusiva-2.jpg 1869w\" sizes=\"auto, (max-width: 293px) 100vw, 293px\" \/><\/a>Una importante operazione di polizia marittima \u00e8 stata portata a segno all&#8217;interno dell&#8217;area protetta del \u201cParco delle Dune Costiere di Torre Canne e Torre S. Leonardo\u201d in localit\u00e0\u00a0Fiume Piccolo\u00a0del Comune di Ostuni, grazie all\u2019intervento dei militari della sezione di Polizia Marittima della Capitaneria di Porto di Brindisi, diretti e coordinati dal Capitano di Vascello Mario Valente.<\/p>\n<p>&nbsp;<\/p>\n<p>In tale area costiera vige la convenzione stipulata tra il Parco Regionale delle Dune Costiere e la Guardia Costiera, accordo avente quale obiettivo primario il potenziamento dell\u2019attivit\u00e0 di prevenzione dei diversi fenomeni di abusivismo demaniale e danneggiamento ambientale ai danni del litorale costiero, \u00a0in favore dei numerosi fruitori del parco soprattutto nella stagione estiva.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;attivit\u00e0 investigativa, ha portato alla denuncia di un soggetto che occupava abusivamente una superficie\u00a0 di circa 115 mq, mediante il posizionamento di ombrelloni e lettini costituendo una vera e propria spiaggia attrezzata, peraltro sprovvista di attrezzature di carattere tecnico nonch\u00e8 di sicurezza, previste dalle ordinanze balneari della Regione Puglia e della Capitaneria di Porto di Brindisi.<\/p>\n<p>&nbsp;<\/p>\n<p>I militari intervenuti, hanno posto sotto sequestro penale le suddette attrezzature e deferito all\u2019Autorit\u00e0 Giudiziaria l\u2019autore del reato.<\/p>\n<p>&nbsp;<\/p>\n<p>Nella stessa zona sono proseguiti i controlli dove i militari hanno sanzionato due venditori ambulanti sprovvisti di autorizzazione del Comune rivierasco; mentre per lo stesso motivo \u00e8 stato sanzionato l\u2019amministratore di una struttura turistica che effettuava noleggio di sdraio e ombrelloni.<\/p>\n<p>Invece a ridosso delle dune costiere sul pubblico demanio marittimo sono stati sanzionati diversi automobilisti per aver parcheggiato le autovetture in zona vietata dal Codice della Navigazione.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Il <strong>Comandante della Capitaneria di Porto di Brindisi<\/strong>\u00a0sensibilizza tutti gli operatori del settore turistico balneare e i fruitori del mare a porre attenzione sul rispetto delle norme <\/em>previste dalle ordinanze balneari della Regione Puglia e della Capitaneria di Porto di Brindisi<em>.\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una importante operazione di polizia marittima \u00e8 stata portata a segno all&#8217;interno dell&#8217;area protetta del \u201cParco delle Dune Costiere di Torre Canne e Torre S. Leonardo\u201d in localit\u00e0\u00a0Fiume Piccolo\u00a0del Comune di Ostuni, grazie all\u2019intervento dei militari della sezione di Polizia Marittima della Capitaneria di Porto di Brindisi, diretti e coordinati dal Capitano di Vascello Mario Valente. &nbsp; In tale area costiera vige la convenzione stipulata tra il Parco Regionale delle Dune Costiere e la Guardia Costiera, accordo avente quale obiettivo primario il potenziamento dell\u2019attivit\u00e0 di prevenzione dei diversi fenomeni di abusivismo demaniale e danneggiamento ambientale ai danni del litorale costiero, \u00a0in favore dei numerosi fruitori del parco soprattutto nella stagione estiva. &nbsp; L&#8217;attivit\u00e0 investigativa, ha portato alla denuncia di un soggetto che occupava abusivamente una superficie\u00a0 di circa 115 mq, mediante il posizionamento di ombrelloni e lettini costituendo una vera e propria spiaggia attrezzata, peraltro sprovvista di attrezzature di carattere tecnico nonch\u00e8 di sicurezza, previste dalle ordinanze balneari della Regione Puglia e della Capitaneria di Porto di Brindisi. &nbsp; I&#8230;<\/p>\n","protected":false},"author":2,"featured_media":19249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[53,640],"class_list":["post-19248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-ostuni","tag-parco-dune-costiere"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/19248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=19248"}],"version-history":[{"count":0,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/19248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/19249"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=19248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=19248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=19248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}