{"id":198284,"date":"2022-02-01T16:35:37","date_gmt":"2022-02-01T15:35:37","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=198284"},"modified":"2022-02-01T17:45:19","modified_gmt":"2022-02-01T16:45:19","slug":"pericardite-miocardite-e-cisti-della-valvola-polmonare-due-studi-dellunita-operativa-di-diagnostica-per-immagini-del-perrino","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/pericardite-miocardite-e-cisti-della-valvola-polmonare-due-studi-dellunita-operativa-di-diagnostica-per-immagini-del-perrino\/","title":{"rendered":"Pericardite, miocardite e cisti della valvola polmonare: due studi dell&#8217;Unit\u00e0 operativa di Diagnostica per immagini del Perrino"},"content":{"rendered":"<p>Il ruolo dell&#8217;elettrocardiogramma e della risonanza magnetica per la distinzione precoce tra pericardite e miocardite \u00e8 al centro di uno studio dell&#8217;Unit\u00e0 operativa complessa di Diagnostica per immagini dell&#8217;ospedale Perrino di Brindisi, condotto in collaborazione con l&#8217;Allegheny General Hospital &#8211; University of Pennsylvania di Pittsburgh e pubblicato su &#8220;Heart and Lung\u201d.<\/p>\n<p>&#8220;La distinzione tra le due patologie &#8211; spiega Eluisa Muscogiuri, direttore dell&#8217;Unit\u00e0 operativa &#8211; \u00e8 un aspetto molto importante in quanto le implicazioni terapeutiche sono diverse, soprattutto nell&#8217;era del Covid 19 e del vaccino, condizioni entrambe associate a pericarditi e miocarditi&#8221;.<\/p>\n<p>Tra le attivit\u00e0 scientifiche dell&#8217;Unit\u00e0 di Diagnostica per immagini anche uno studio che mette in risalto il potere diagnostico della risonanza magnetica cardiaca per la corretta definizione di una massa rilevata sulla valvola polmonare, inizialmente interpretata come trombosi alla Tc e successivamente definita come cisti idatidea (da Echinococco).<\/p>\n<p>Con la risonanza, inoltre, sono state identificate ulteriori cisti localizzate all&#8217;interno del miocardio: \u00e8 il primo caso descritto in letteratura di interessamento cardiaco multiplo da cisti idatidea con coinvolgimento diretto della valvola polmonare.<\/p>\n<p>&#8220;ll lavoro &#8211; aggiunge Muscogiuri &#8211; \u00e8 stato realizzato in collaborazione con il reparto di Cardiologia del Perrino, cos\u00ec come quello su miocardite e pericardite, ed \u00e8 in corso di pubblicazione sul Journal of Heart Valve Disease. Sar\u00e0 presentato in webinar dal collega Francesco Mangini al congresso internazionale della Scmr, Society for Cardiovascular Magnetic Resonance, che si terr\u00e0 in Florida dal 2 al 5 febbraio&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>UFFICIO STAMPA ASL BR<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il ruolo dell&#8217;elettrocardiogramma e della risonanza magnetica per la distinzione precoce tra pericardite e miocardite \u00e8 al centro di uno studio dell&#8217;Unit\u00e0 operativa complessa di Diagnostica per immagini dell&#8217;ospedale Perrino di Brindisi, condotto in collaborazione con l&#8217;Allegheny General Hospital &#8211; University of Pennsylvania di Pittsburgh e pubblicato su &#8220;Heart and Lung\u201d. &#8220;La distinzione tra le due patologie &#8211; spiega Eluisa Muscogiuri, direttore dell&#8217;Unit\u00e0 operativa &#8211; \u00e8 un aspetto molto importante in quanto le implicazioni terapeutiche sono diverse, soprattutto nell&#8217;era del Covid 19 e del vaccino, condizioni entrambe associate a pericarditi e miocarditi&#8221;. Tra le attivit\u00e0 scientifiche dell&#8217;Unit\u00e0 di Diagnostica per immagini anche uno studio che mette in risalto il potere diagnostico della risonanza magnetica cardiaca per la corretta definizione di una massa rilevata sulla valvola polmonare, inizialmente interpretata come trombosi alla Tc e successivamente definita come cisti idatidea (da Echinococco). Con la risonanza, inoltre, sono state identificate ulteriori cisti localizzate all&#8217;interno del miocardio: \u00e8 il primo caso descritto in letteratura di interessamento cardiaco multiplo da cisti idatidea con coinvolgimento diretto&#8230;<\/p>\n","protected":false},"author":2,"featured_media":198285,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-198284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/198284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=198284"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/198284\/revisions"}],"predecessor-version":[{"id":198286,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/198284\/revisions\/198286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/198285"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=198284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=198284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=198284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}