{"id":19832,"date":"2014-08-14T11:03:18","date_gmt":"2014-08-14T09:03:18","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=19832"},"modified":"2014-08-14T11:03:18","modified_gmt":"2014-08-14T09:03:18","slug":"tempodestate-2014-domani-peppe-barra-domenica-animazione-per-bambini","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/tempodestate-2014-domani-peppe-barra-domenica-animazione-per-bambini\/","title":{"rendered":"#tempodestate 2014: domani Peppe Barra, domenica animazione per bambini"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/Peppe-Barra.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-19828\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/Peppe-Barra-300x200.jpg\" alt=\"Peppe Barra\" width=\"300\" height=\"200\" data-id=\"19828\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/Peppe-Barra-300x200.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/Peppe-Barra-1024x682.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Nell\u2019ambito delle manifestazioni estive inserite nel calendario allestito dall\u2019Amministrazione comunale, con la collaborazione tecnica della Fondazione Nuovo Teatro Verdi, sabato 16 agosto Peppe Barra arriva a Brindisi per animare l\u2019affascinante scenario della Scalinata di Virgilio con i suoi \u201cCanti e racconti\u201d e le originali interpretazioni che hanno fatto la storia della musica partenopea. Peppe Barra \u00e8 considerato uno dei protagonisti pi\u00f9 eclettici della scena napoletana e personaggio di rilievo della cultura del Novecento, protagonista del recupero della tradizione popolare musicale e teatrale.<br \/>\nAccanto all\u2019artista, in apertura del suo concerto, anche il gruppo di ricerca popolare brindisino \u201cCanto antico della nostra terra\u201d che pu\u00f2 dire di aver dato, sin dal 1974, anno della sua nascita, gli strumenti, l\u2019entusiasmo e gli stimoli per una sempre maggiore diffusione di gruppi che si occupano di tradizioni popolari brindisine e della Terra d&#8217;Otranto. Il gruppo presenter\u00e0 alcuni dei brani pi\u00f9 belli e noti del suo repertorio: da Mannaggia Lu Rimu a Tangu, ultima canzone scritta da Ennio Masiello, poeta in vernacolo e cultore delle tradizioni popolari.<\/p>\n<p>&nbsp;<\/p>\n<p>Nell\u2019ambito delle manifestazioni inserite nel calendario allestito dall\u2019Amministrazione comunale, con la collaborazione tecnica della Fondazione Nuovo Teatro Verdi, domenica 17 agosto, c\u2019\u00e8 spazio anche per l\u2019animazione dedicata ai bambini.<br \/>\nA partire dalle ore 19,30, infatti, i giardinetti di piazza Vittorio Emanuele II si trasformano per un giorno nel magico mondo dei palloncini e delle bolle di sapone. Tanti giochi di animazione e attivit\u00e0 ludico-creative dedicati ai pi\u00f9 piccoli che diventano protagonisti di una serata a tema dal titolo \u201cL\u2019aria prende forma\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell\u2019ambito delle manifestazioni estive inserite nel calendario allestito dall\u2019Amministrazione comunale, con la collaborazione tecnica della Fondazione Nuovo Teatro Verdi, sabato 16 agosto Peppe Barra arriva a Brindisi per animare l\u2019affascinante scenario della Scalinata di Virgilio con i suoi \u201cCanti e racconti\u201d e le originali interpretazioni che hanno fatto la storia della musica partenopea. Peppe Barra \u00e8 considerato uno dei protagonisti pi\u00f9 eclettici della scena napoletana e personaggio di rilievo della cultura del Novecento, protagonista del recupero della tradizione popolare musicale e teatrale. Accanto all\u2019artista, in apertura del suo concerto, anche il gruppo di ricerca popolare brindisino \u201cCanto antico della nostra terra\u201d che pu\u00f2 dire di aver dato, sin dal 1974, anno della sua nascita, gli strumenti, l\u2019entusiasmo e gli stimoli per una sempre maggiore diffusione di gruppi che si occupano di tradizioni popolari brindisine e della Terra d&#8217;Otranto. Il gruppo presenter\u00e0 alcuni dei brani pi\u00f9 belli e noti del suo repertorio: da Mannaggia Lu Rimu a Tangu, ultima canzone scritta da Ennio Masiello, poeta in vernacolo e cultore delle tradizioni&#8230;<\/p>\n","protected":false},"author":2,"featured_media":17989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2375],"class_list":["post-19832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-tempodestate-2014"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/19832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=19832"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/19832\/revisions"}],"predecessor-version":[{"id":19836,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/19832\/revisions\/19836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/17989"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=19832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=19832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=19832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}