{"id":198350,"date":"2022-02-03T16:39:05","date_gmt":"2022-02-03T15:39:05","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=198350"},"modified":"2022-02-03T16:39:05","modified_gmt":"2022-02-03T15:39:05","slug":"emiliano-nomina-assessori-palese-sanita-e-lopane-turismo-delega-alla-cultura-a-di-bari-m5s","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/emiliano-nomina-assessori-palese-sanita-e-lopane-turismo-delega-alla-cultura-a-di-bari-m5s\/","title":{"rendered":"Emiliano nomina assessori Palese (Sanit\u00e0) e Lopane (Turismo). Delega alla Cultura a Di Bari (M5S)"},"content":{"rendered":"<p>Il presidente della Regione Puglia Michele Emiliano ha nominato due nuovi componenti della Giunta: Rocco Palese con delega alla &#8220;Sanit\u00e0, Benessere animale, Controlli Interni, Controlli connessi alla gestione emergenza COVID-19&#8221; e Gianfranco Lopane con delega al &#8220;Turismo, Sviluppo e impresa turistica&#8221;.<\/p>\n<p>Inoltre il presidente ha nominato la consigliera regionale Grazia Di Bari, Consigliera delegata per le politiche culturali, il patrimonio materiale e immateriale e la valorizzazione dei borghi.<\/p>\n<p>&#8220;Esperienza, conoscenza  del territorio, capacit\u00e0 di ascolto e coinvolgimento di tutte le componenti sociali, sindacali e politiche per realizzare il nostro programma di governo e perseguire il bene comune: sono queste le ragioni alla base del conferimento delle nuove deleghe. I miei auguri di buon lavoro ai due nuovi assessori e alla consigliera&#8221; dichiara il presidente Emiliano.<\/p>\n<p>La Consigliera delegata, per l&#8217;esecuzione dell\u2019incarico, potra\u0300 avvalersi dei mezzi e delle competenze di ARTI Puglia, Fondazione Apulia Film Commission, del Dipartimento Turismo, Economia della cultura e valorizzazione del territorio, nonch\u00e9 della collaborazione, per quanto possa occorrere, degli altri Dipartimenti e Agenzie della Regione Puglia, con potere di organizzare e porre in essere quanto alla stessa demandata mediante specifici gruppi di lavoro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il presidente della Regione Puglia Michele Emiliano ha nominato due nuovi componenti della Giunta: Rocco Palese con delega alla &#8220;Sanit\u00e0, Benessere animale, Controlli Interni, Controlli connessi alla gestione emergenza COVID-19&#8221; e Gianfranco Lopane con delega al &#8220;Turismo, Sviluppo e impresa turistica&#8221;. Inoltre il presidente ha nominato la consigliera regionale Grazia Di Bari, Consigliera delegata per le politiche culturali, il patrimonio materiale e immateriale e la valorizzazione dei borghi. &#8220;Esperienza, conoscenza del territorio, capacit\u00e0 di ascolto e coinvolgimento di tutte le componenti sociali, sindacali e politiche per realizzare il nostro programma di governo e perseguire il bene comune: sono queste le ragioni alla base del conferimento delle nuove deleghe. I miei auguri di buon lavoro ai due nuovi assessori e alla consigliera&#8221; dichiara il presidente Emiliano. La Consigliera delegata, per l&#8217;esecuzione dell\u2019incarico, potra\u0300 avvalersi dei mezzi e delle competenze di ARTI Puglia, Fondazione Apulia Film Commission, del Dipartimento Turismo, Economia della cultura e valorizzazione del territorio, nonch\u00e9 della collaborazione, per quanto possa occorrere, degli altri Dipartimenti e Agenzie della Regione Puglia,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":190584,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-198350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/198350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=198350"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/198350\/revisions"}],"predecessor-version":[{"id":198351,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/198350\/revisions\/198351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/190584"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=198350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=198350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=198350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}