{"id":198506,"date":"2022-02-08T17:33:50","date_gmt":"2022-02-08T16:33:50","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=198506"},"modified":"2022-02-08T17:33:50","modified_gmt":"2022-02-08T16:33:50","slug":"giovedi-10-a-mesagne-una-giornata-in-memoria-di-giovanni-palatucci","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/giovedi-10-a-mesagne-una-giornata-in-memoria-di-giovanni-palatucci\/","title":{"rendered":"Gioved\u00ec 10 a Mesagne una giornata in memoria di Giovanni Palatucci"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/02\/semi-di-memoria-1-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" class=\"alignleft size-medium wp-image-198508\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/02\/semi-di-memoria-1-212x300.jpg 212w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/02\/semi-di-memoria-1.jpg 595w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><br \/>\nGioved\u00ec 10 febbraio, la Questura di Brindisi e il 1\u00b0 C.D. \u201cG. Carducci\u201d di Mesagne organizzano con il patrocinio del Comune di Mesagne un momento dedicato ai temi della Memoria. Questo evento si colloca infatti in continuit\u00e0 con l\u2019appena trascorso \u201cGiorno della Memoria\u201d, un appuntamento che vede impegnati ogni anno le alunne e gli alunni di tutte le scuole ad elaborare contributi e riflessioni per non dimenticare.<br \/>\nQuest\u2019anno i lavori, realizzati non solo dai bambini del Primo Circolo ma anche da studenti e ragazzi delle altre scuole del territorio, vogliono proprio testimoniare questo: la memoria \u00e8 un valore che va \u201ccoltivato\u201d affinch\u00e9 cresca dentro ognuno di noi e possa essere tramandato. Simbolo di questo senso profondo \u00e8 la piantumazione nel giardino della scuola Carducci di un albero di ulivo, a conclusione della mattinata durante la quale si alterneranno momenti musicali, video e dibattiti.<br \/>\nTra le testimonianze, anche il ricordo di Giovanni Palatucci, questore reggente di Fiume e Medaglia d\u2019oro al Merito civile per le sue eroiche azioni in difesa di cittadini ebrei. Accanto all\u2019ulivo verr\u00e0 infatti scoperta in suo ricordo una tela commemorativa, donata per l\u2019occasione dal Lions Club di Mesagne, al fine di perpetuare la memoria e coltivare il senso della giustizia e dell\u2019uguaglianza tra gli uomini.<br \/>\nLa Preside del primo Circolo, prof.ssa Patrizia Carra, annuncer\u00e0 in quella sede l\u2019avvio della procedura per la realizzazione della prima \u201cpietra d\u2019inciampo\u201d nella citt\u00e0 di Mesagne da collocare nella scuola in ricordo del Direttore Didattico Antonio Scalera, che ha vissuto il dramma della deportazione.<br \/>\nDopo i saluti istituzionali del Sindaco di Mesagne e del Questore di Brindisi, dialogheranno con gli alunni il Dirigente del Commissariato di PS di Mesagne dott. Giuseppe Massaro e il Coordinatore del Centro ebraico di cultura Avv. Cosimo Pagliara.<br \/>\nL\u2019evento che per motivi di sicurezza si svolger\u00e0 alla presenza di una ristretta rappresentanza degli studenti, sar\u00e0 seguito nelle scuole di Mesagne attraverso la diretta streaming sulla pagina Facebook di QuiMesagne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gioved\u00ec 10 febbraio, la Questura di Brindisi e il 1\u00b0 C.D. \u201cG. Carducci\u201d di Mesagne organizzano con il patrocinio del Comune di Mesagne un momento dedicato ai temi della Memoria. Questo evento si colloca infatti in continuit\u00e0 con l\u2019appena trascorso \u201cGiorno della Memoria\u201d, un appuntamento che vede impegnati ogni anno le alunne e gli alunni di tutte le scuole ad elaborare contributi e riflessioni per non dimenticare. Quest\u2019anno i lavori, realizzati non solo dai bambini del Primo Circolo ma anche da studenti e ragazzi delle altre scuole del territorio, vogliono proprio testimoniare questo: la memoria \u00e8 un valore che va \u201ccoltivato\u201d affinch\u00e9 cresca dentro ognuno di noi e possa essere tramandato. Simbolo di questo senso profondo \u00e8 la piantumazione nel giardino della scuola Carducci di un albero di ulivo, a conclusione della mattinata durante la quale si alterneranno momenti musicali, video e dibattiti. Tra le testimonianze, anche il ricordo di Giovanni Palatucci, questore reggente di Fiume e Medaglia d\u2019oro al Merito civile per le sue eroiche azioni in difesa di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":198507,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-198506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/198506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=198506"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/198506\/revisions"}],"predecessor-version":[{"id":198509,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/198506\/revisions\/198509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/198507"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=198506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=198506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=198506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}