{"id":198633,"date":"2022-02-10T18:00:43","date_gmt":"2022-02-10T17:00:43","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=198633"},"modified":"2022-02-11T18:22:59","modified_gmt":"2022-02-11T17:22:59","slug":"amo-a-fasano-il-mese-di-febbraio-dedicato-allamore-in-tutte-le-sue-forme","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/amo-a-fasano-il-mese-di-febbraio-dedicato-allamore-in-tutte-le-sue-forme\/","title":{"rendered":"Amo a Fasano: il mese di febbraio dedicato all\u2019amore in tutte le sue forme"},"content":{"rendered":"<p>Addobbi luminosi in piazza Ciaia, musica a tema, un contest fotografico, la mostra dei disegni degli studenti, progetti e iniziative di associazioni del territorio e il coinvolgimento delle attivit\u00e0 produttive. Perch\u00e9 l\u2019amore non \u00e8 (solo) sentire le farfalle nello stomaco, ma un sentimento che pu\u00f2 (e deve) essere declinato in pi\u00f9 forme: amore per la musica, per la vita e la salute, per la poesia, per le arti, per il territorio, per il cibo, oltre che per il partner. <\/p>\n<p>\u00c8 l\u2019edizione 2022 di \u00abAmo a Fasano\u00bb, promossa dall\u2019amministrazione comunale in occasione della festa di San Valentino. Una iniziativa che si svolger\u00e0 per tutto febbraio all\u2019insegna di un obiettivo: creare momenti di interesse pubblico fino a fine mese, anche per incentivare i consumi commerciali sul territorio. E proprio i commercianti sono stati coinvolti, in collaborazione con Confcommercio e Confesercenti, nella realizzazione di un video (a cura dell\u2019ufficio Comunicazione del Comune) per invogliare a comprare a Fasano i doni di san Valentino. <\/p>\n<p>Tra le iniziative promosse dall\u2019amministrazione c\u2019\u00e8 la mostra fotografica \u00abL\u2019Amore e le sue declinazioni\u00bb con foto dedicate alle varie sfaccettature dell\u2019amore. Le immagini saranno pubblicate sulla pagina Facebook \u00abAmo a Fasano\u00bb. A tutti i partecipanti sar\u00e0 consegnato un attestato di partecipazione, mentre le immagini che riceveranno il maggior numero di like saranno premiate con una targa.<\/p>\n<p>Inoltre gli studenti di scuole dell\u2019Infanzia e Primaria sono stati coinvolti in una mostra grafica sul tema \u00abL\u2019amore\u00bb e ogni partecipante sar\u00e0 premiato con un attestato. <\/p>\n<p>Il cuore di Fasano, insomma, batter\u00e0, per tutto il mese. Piazza Ciaia, infatti, \u00e8 stata addobbata con installazioni a tema che riportano anche i versi di alcune famosissime canzoni d\u2019amore. C\u2019\u00e8 De Gregori con \u00abLa Leva Calcistica del \u201968\u00bb, Jovanotti con \u00abA te\u00bb, Antonello Venditti con \u00abAmici Mai\u00bb, Rino Gaetano con \u00abA Mano a mano\u00bb. <\/p>\n<p>\u00abAmore significa anche e soprattutto amore per la nostra citt\u00e0 e per il nostro territorio \u2013 dice il sindaco Francesco Zaccaria \u2013 per questo motivo, come ogni anno, abbiamo voluto riproporre e rinnovare una iniziativa che \u00e8 innanzitutto occasione per incentivare ad acquistare a Fasano. Ringrazio i commercianti che hanno fatto squadra e gli assessorati alle Attivit\u00e0 Produttive, Istruzione e Politiche Sociali, Infanzia e Cultura che hanno fatto rete insieme ad associazioni e studenti con entusiasmo e passione, gli ingredienti, appunto, dell\u2019amore, in tutte le sue forme\u00bb. <\/p>\n<p>\u00abSan Valentino ci consente di realizzare un duplice obiettivo \u2013 spiega l\u2019assessore alle Attivit\u00e0 Produttive Giuseppe Galeota \u2013: rendere Fasano attrativa attraverso installazioni a tema e offrire una opportunit\u00e0 ulteriore di visibilit\u00e0 ai commercianti in un mese che coincide con l\u2019ultima parte dei saldi invernali.  Attraverso il calendario di iniziative promosso vogliamo sensibilizzare ai buoni sentimenti, \u00abAmo a Fasano\u00bb \u00e8 un invito a manifestarli e a riceverli perch\u00e9 anche attraverso queste manifestazioni di amore, nel senso universale del termine, riusciremo a superare i momenti pi\u00f9 difficili legati alla pandemia. Ringrazio gli assessori Caroli e Martucci, lo staff Comunicazione, la ditta Luminarie D\u2019arredo per gli allestimenti, la dirigente del settore Attivit\u00e0 Produttive Beba Caldarazzo, il coordinamento delle associazioni di Fasano guidato da Mariateresa Maggi e le associazioni di categoria della Confcommercio e Confesercenti guidate da Donato Pistola e Sante Cofano\u00bb. <\/p>\n<p>\u00abIl mese dedicato a San Valentino diventa occasione per riflettere e affrontare diversi argomenti relativi alle relazioni sociali, agli affetti e alla nostra quotidianit\u00e0 \u2013 dice l\u2019assessore alla Cultura, alle Politiche dell\u2019Infanzia e alle Politiche Sociali Cinzia Caroli \u2013.  Come assessorato alla Cultura abbiamo cercato di promuovere innanzitutto un pezzo a teatro dal titolo &#8220;Due&#8221;. Il  lavoro ruota attorno a una semplice domanda che per\u00f2 ha appassionato nel tempo poeti, scrittori, cantanti e filosofi: esiste l&#8217; anima granella? Lo spettacolo \u00e8 offerto dall&#8217;amministrazione ed \u00e8 quindi gratuito per i cittadini. Inoltre promuoveremo allestimenti e il Carnevale d&#8217;epoca tanto apprezzato e atteso in citt\u00e0. Sar\u00e0 un mese in cui poter tornare  a vivere la bellezza ed il piacere dello stare insieme\u00bb. <\/p>\n<p>\u00abAbbiamo voluto coinvolgere le scuole nella raffigurazione dell\u2019amore, perch\u00e9  il disegno \u00e8 il modo pi\u00f9 naturale di espressione dei bambini, che comprende fattori intellettivi e affettivi \u2013 dice l\u2019assessore all\u2019Istruzione Donatella Martucci \u2013. Attraverso i disegni i bambini sanno dare forma alle loro emozioni e ci portano nel loro mondo fatto di fantasia, di stupore, di amicizia e di sentimenti autentici\u00bb.<\/p>\n<p>link YouTube<br \/>\n<iframe loading=\"lazy\" title=\"Spot - Amo a Fasano\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/vp3ziqZYOMY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Ufficio Stampa<br \/>\nCitt\u00e0 di Fasano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Addobbi luminosi in piazza Ciaia, musica a tema, un contest fotografico, la mostra dei disegni degli studenti, progetti e iniziative di associazioni del territorio e il coinvolgimento delle attivit\u00e0 produttive. Perch\u00e9 l\u2019amore non \u00e8 (solo) sentire le farfalle nello stomaco, ma un sentimento che pu\u00f2 (e deve) essere declinato in pi\u00f9 forme: amore per la musica, per la vita e la salute, per la poesia, per le arti, per il territorio, per il cibo, oltre che per il partner. \u00c8 l\u2019edizione 2022 di \u00abAmo a Fasano\u00bb, promossa dall\u2019amministrazione comunale in occasione della festa di San Valentino. Una iniziativa che si svolger\u00e0 per tutto febbraio all\u2019insegna di un obiettivo: creare momenti di interesse pubblico fino a fine mese, anche per incentivare i consumi commerciali sul territorio. E proprio i commercianti sono stati coinvolti, in collaborazione con Confcommercio e Confesercenti, nella realizzazione di un video (a cura dell\u2019ufficio Comunicazione del Comune) per invogliare a comprare a Fasano i doni di san Valentino. Tra le iniziative promosse dall\u2019amministrazione c\u2019\u00e8 la mostra fotografica \u00abL\u2019Amore&#8230;<\/p>\n","protected":false},"author":2,"featured_media":198634,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-198633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/198633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=198633"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/198633\/revisions"}],"predecessor-version":[{"id":198635,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/198633\/revisions\/198635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/198634"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=198633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=198633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=198633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}