{"id":19877,"date":"2014-08-14T21:45:58","date_gmt":"2014-08-14T19:45:58","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=19877"},"modified":"2014-08-22T23:14:40","modified_gmt":"2014-08-22T21:14:40","slug":"il-22-agosto-a-brindisi-torna-la-notte-della-tarantavis","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/il-22-agosto-a-brindisi-torna-la-notte-della-tarantavis\/","title":{"rendered":"Il 22 Agosto a Brindisi torna &#8220;La Notte della TarantAvis&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/LocandinaTarantAvis2014definitiva.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-19878 size-medium\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/LocandinaTarantAvis2014definitiva-212x300.jpg\" alt=\"LocandinaTarantAvis2014definitiva\" width=\"212\" height=\"300\" data-id=\"19878\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/LocandinaTarantAvis2014definitiva-212x300.jpg 212w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/LocandinaTarantAvis2014definitiva-723x1024.jpg 723w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a>Il Gruppo Giovani dell\u2019Avis Comunale di Brindisi presenta, per Venerd\u00ec 22 Agosto 2014, la V^ edizione de \u201cLa notte della TARANTAVIS\u201d, una serata all\u2019insegna della musica e della solidariet\u00e0.<br \/>\nLa manifestazione &#8211; davvero importante per la citt\u00e0 di Brindisi &#8211; si terr\u00e0 in Piazza Vittoria e si articoler\u00e0 in due fasi: a partire dalle ore 18:00 sar\u00e0 possibile donare il sangue, grazie alla presenza della confortevole autoemoteca dell\u2019Avis e dell\u2019equipe del SIMT dell\u2019Ospedale \u201cA. Perrino\u201d; a partire dalle ore 21:00, poi, a degna conclusione della manifestazione, ci sar\u00e0 una degustazione di friselle e di vino accompagnata dal concerto del gruppo di musica popolare \u201cBeddu ci Balla\u201d, con l\u2019intervento del gruppo di ballerini brindisino \u201cAddu\u2019 sciamu sciamu\u201d.<\/p>\n<p>Al fine di incentivare maggiormente tutti coloro che decideranno di impiegare il proprio tempo per compiere una buona azione verso il prossimo, ogni donatore parteciper\u00e0 all\u2019estrazione dei premi messi in palio per la Campagna Estiva Avis 2014, oltre naturalmente ad approfittare dell\u2019offerta di friselle e vino fornite dalla \u201cCantina Due Palme\u201d, al fine di vivere una serata in allegria.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019evento &#8211; che si svolger\u00e0 con il patrocinio del Comune di Brindisi &#8211; \u00e8 stato quest&#8217;anno inserito all\u2019interno del cartellone dell\u2019Estate Brindisina; media partner dell&#8217;iniziativa saranno Studio 100 Tv, Ciccioriccio, Brundisium.net e Puglia Tv, tutti ancora una volta al fianco dell\u2019Avis Comunale di Brindisi.<\/p>\n<p>TARANTAVIS sar\u00e0 una serata all\u2019insegna della solidariet\u00e0 e della tradizione, unendo il dono del sangue alla valorizzazione del patrimonio enogastronomico e culturale locale: adoperando in particolare i suoni e colori della pizzica, arte tradizionale e profana di intrattenimento e corteggiamento, ma soprattutto musica sacra e medicinale, in grado di guarire i \u201ctarantati\u201d del Salento, attraverso una danza coinvolgente e, soprattutto, simbolica.<\/p>\n<p>Sar\u00e0 proprio la musica a rivestire un ruolo da protagonista, unificando, attraverso vibrazione ed energia, esperienze e mondi diversi, fino ad evolversi in terapia musicale e coreutica, riconosciuta oggi in tutto il mondo.<br \/>\nDurante la serata, sar\u00e0 inoltre possibile ritirare materiale informativo sulla donazione di sangue intero e di emocomponenti, sull\u2019Avis di Brindisi e sul Gruppo Giovani.<\/p>\n<p>Al fine di poter donare il sangue sar\u00e0 necessario essere in buona salute, non aver assunto farmaci (antinfiammatori ed antibiotici) nei giorni antecedenti alla donazione ed aver consumato un pranzo leggero, con esclusione di latte e derivati (formaggi, mozzarelle, panna, dolci con creme, ecc.).<\/p>\n<p>Tutti i soci Avis, i donatori, anche quelli occasionali, ed in generale la cittadinanza tutta sono invitati a partecipare!<br \/>\nIl Gruppo Giovani dell\u2019Avis Comunale di Brindisi vi aspetta!<\/p>\n<p><em>Per ulteriori informazioni, contattare l\u2019Avis Comunale di Brindisi, in Piazza A. Di Summa presso l\u2019ex Ospedale, al numero 0831523232, consultare il sito internet\u00a0www.aviscomunalebrindisi.it\u00a0o inviare un\u2019e-mail agli indirizzi di posta elettronica: brindisi.comunale@avis.it e gruppogiovanibrindisi@avis.it<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Gruppo Giovani dell\u2019Avis Comunale di Brindisi presenta, per Venerd\u00ec 22 Agosto 2014, la V^ edizione de \u201cLa notte della TARANTAVIS\u201d, una serata all\u2019insegna della musica e della solidariet\u00e0. La manifestazione &#8211; davvero importante per la citt\u00e0 di Brindisi &#8211; si terr\u00e0 in Piazza Vittoria e si articoler\u00e0 in due fasi: a partire dalle ore 18:00 sar\u00e0 possibile donare il sangue, grazie alla presenza della confortevole autoemoteca dell\u2019Avis e dell\u2019equipe del SIMT dell\u2019Ospedale \u201cA. Perrino\u201d; a partire dalle ore 21:00, poi, a degna conclusione della manifestazione, ci sar\u00e0 una degustazione di friselle e di vino accompagnata dal concerto del gruppo di musica popolare \u201cBeddu ci Balla\u201d, con l\u2019intervento del gruppo di ballerini brindisino \u201cAddu\u2019 sciamu sciamu\u201d. Al fine di incentivare maggiormente tutti coloro che decideranno di impiegare il proprio tempo per compiere una buona azione verso il prossimo, ogni donatore parteciper\u00e0 all\u2019estrazione dei premi messi in palio per la Campagna Estiva Avis 2014, oltre naturalmente ad approfittare dell\u2019offerta di friselle e vino fornite dalla \u201cCantina Due Palme\u201d, al fine di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":19879,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2332,453,2467],"class_list":["post-19877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-tempodestate","tag-avis","tag-tarantavis"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/19877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=19877"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/19877\/revisions"}],"predecessor-version":[{"id":19880,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/19877\/revisions\/19880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/19879"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=19877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=19877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=19877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}