{"id":199026,"date":"2022-02-23T10:35:56","date_gmt":"2022-02-23T09:35:56","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=199026"},"modified":"2022-02-23T19:40:51","modified_gmt":"2022-02-23T18:40:51","slug":"casa-degli-aquiloni-al-via-il-progetto-di-caritas-diocesana-e-migrantes-brindisi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/casa-degli-aquiloni-al-via-il-progetto-di-caritas-diocesana-e-migrantes-brindisi\/","title":{"rendered":"Casa degli Aquiloni: al via il progetto di Caritas Diocesana e Migrantes Brindisi"},"content":{"rendered":"<p>Prende avvio il progetto \u201cCasa degli Aquiloni\u201d, nato dalla collaborazione tra Caritas diocesana e Associazione Migrantes Brindisi, e in parte finanziato con i fondi dell\u20198&#215;1000 alla Chiesa Cattolica. Il progetto vuole provare a dare delle risposte concrete all\u2019emergenza abitativa che tocca tanti migranti, partendo da un\u2019esperienza di accoglienza e condivisione gia\u0300 in atto dal 2017, quella appunto della Casa degli Aquiloni.<br \/>\nIl progetto, che avra\u0300 la durata di circa un anno, si pone una serie di obiettivi specifici: implementare la Casa degli Aquiloni fornendo un apporto nuovo alla sensibilizzazione della citta\u0300 e della diocesi sul tema dell\u2019emergenza abitativa; accompagnare e sostenere gruppi di persone disponibili ad impegnarsi in prima persona nella generazione di nuove esperienze di accoglienza; creare un &#8220;Osservatorio&#8221;, un laboratorio che possa costantemente monitorare la situazione della citta\u0300, cogliere i bisogni piu\u0300 urgenti, condividere buone prassi esistenti per diffondere la cultura di un\u2019accoglienza sempre volta a favorire la realizzazione del proprio personale, unico e irripetibile progetto di vita.<br \/>\nPer don Andrea Giampietro, direttore della Caritas diocesana di Brindisi-Ostuni, il progetto e\u0300 un\u2019opportunita\u0300, \u201cperche\u0301 mira all\u2019integrazione degli stranieri nel contesto locale, andando oltre le consuete forme di assistenzialismo. Spesso &#8211; continua don Andrea Giampietro \u2013 siamo vittime del pregiudizio o della paura dello straniero: entrambi possono essere superati solo conoscendo direttamente chi chiede aiuto. La \u201cCasa degli Aquiloni\u201d e\u0300 un\u2019occasione per aprirsi a una forma di volontariato che vada oltre l\u2019assistenza materiale; inoltre, attraverso l\u2019osservatorio, ne potranno giovare anche le istituzioni locali, per fare interventi mirati per il bene di tutti i cittadini\u201d.<br \/>\n\u201cE\u0300 con orgoglio e con gioia che ci apprestiamo a presentare l\u2019esperienza della Casa degli Aquiloni\u201d, afferma Sabina Bombacigno vice presidente dell\u2019associazione Migrantes. \u201cDal 2017 ad oggi piu\u0300 di 50 migranti hanno potuto trovare nella nostra casa un riparo, un\u2019ospitalita\u0300 o una residenza grazie alla quale poter rinnovare i propri documenti, un gruppo di volontari con cui condividere il cammino. Insieme gestiamo la struttura, insieme individuiamo i percorsi da compiere per la realizzazione di se\u0301, insieme troviamo le soluzioni ai problemi quotidiani, affinche\u0301 ad un certo punto del cammino ciascuno possa essere in grado di continuare il proprio percorso da solo. Casa degli Aquiloni e\u0300 una sfida ai luoghi comuni e si rivela ogni giorno un\u2019esperienza avvincente e vincente. Disseminandola ci auguriamo che possa diventare generativa di un\u2019accoglienza diffusa, inclusiva e di autentica promozione umana\u201d.<\/p>\n<p>COMUNICATO-STAMPA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prende avvio il progetto \u201cCasa degli Aquiloni\u201d, nato dalla collaborazione tra Caritas diocesana e Associazione Migrantes Brindisi, e in parte finanziato con i fondi dell\u20198&#215;1000 alla Chiesa Cattolica. Il progetto vuole provare a dare delle risposte concrete all\u2019emergenza abitativa che tocca tanti migranti, partendo da un\u2019esperienza di accoglienza e condivisione gia\u0300 in atto dal 2017, quella appunto della Casa degli Aquiloni. Il progetto, che avra\u0300 la durata di circa un anno, si pone una serie di obiettivi specifici: implementare la Casa degli Aquiloni fornendo un apporto nuovo alla sensibilizzazione della citta\u0300 e della diocesi sul tema dell\u2019emergenza abitativa; accompagnare e sostenere gruppi di persone disponibili ad impegnarsi in prima persona nella generazione di nuove esperienze di accoglienza; creare un &#8220;Osservatorio&#8221;, un laboratorio che possa costantemente monitorare la situazione della citta\u0300, cogliere i bisogni piu\u0300 urgenti, condividere buone prassi esistenti per diffondere la cultura di un\u2019accoglienza sempre volta a favorire la realizzazione del proprio personale, unico e irripetibile progetto di vita. Per don Andrea Giampietro, direttore della Caritas diocesana di Brindisi-Ostuni,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":199027,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-199026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=199026"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199026\/revisions"}],"predecessor-version":[{"id":199028,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199026\/revisions\/199028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/199027"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=199026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=199026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=199026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}