{"id":199138,"date":"2022-02-25T17:38:18","date_gmt":"2022-02-25T16:38:18","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=199138"},"modified":"2022-02-25T17:44:59","modified_gmt":"2022-02-25T16:44:59","slug":"impianto-eolico-off-shore-tra-brindisi-e-san-cataldo-bruno-opportunita-imperdibile-per-il-territorio-lambiente-leconomia-e-il-lavoro-spero-in-una-rapida-approvazione-de","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/impianto-eolico-off-shore-tra-brindisi-e-san-cataldo-bruno-opportunita-imperdibile-per-il-territorio-lambiente-leconomia-e-il-lavoro-spero-in-una-rapida-approvazione-de\/","title":{"rendered":"Impianto eolico off-shore tra Brindisi e San Cataldo, Bruno: \u201cOpportunit\u00e0 imperdibile per il territorio, l\u2019ambiente, l\u2019economia e il lavoro\u201d"},"content":{"rendered":"<p>Di seguito la nota del Il progetto da 3,5 miliardi di euro per la realizzazione di un parco eolico in mare tra le coste di Brindisi e San Cataldo, deve essere approvato e nel pi\u00f9 breve tempo possibile.<\/p>\n<p>E\u2019 un\u2019occasione per il nostro territorio, l\u2019ambiente, la transizione ecologica e l\u2019incremento dell\u2019autonomia energetica che non possiamo perdere e attorno al quale dobbiamo fare squadra.<\/p>\n<p>La proposta di installazione delle 98 pale eoliche in mare aperto presentata da Falck Renewables potrebbe avere importantissime ricadute economiche sul tessuto produttivo locale e dare numerosi posti di lavoro sia in fase di realizzazione (si prevedono 4.000 occupati) sia di gestione.<\/p>\n<p>In questi anni, e ancor pi\u00f9 in questi mesi, le difficolt\u00e0 economiche e lavorative per il nostro territorio sono emerse tutte ed \u00e8 sbagliato voltarsi dall\u2019altra parte.<\/p>\n<p>E i tempi che ci aspettano, anche alla luce di quanto riferito oggi in aula dal premier Mario Draghi, con la conversione del nostro sistema industriale verso lidi pi\u00f9 \u201cverdi\u201d e a minore impatto, non giocano di certo a favore di un territorio che per decenni ha basato parte della propria economia su sistemi di sviluppo altamente inquinanti.<\/p>\n<p>Le 98 pale eoliche, se realizzate, lo saranno a una distanza compresa fra i 9 e i 20 chilometri. La lontananza dalla costa e la curvatura terrestre le renderanno quindi poco visibili e per nulla impattanti. Soprattutto se questo loro eventuale impatto viene paragonato a quello, devastante, degli altri sistemi di produzione energetica che conosciamo e che tutto il mondo sta abbandonando.<\/p>\n<p>Attualmente il progetto preliminare \u00e8 in fase di studio di impatto ambientale presso il Ministero per la transizione ecologica. Mi auguro che saremo compatti e propositivi nel chiedere che la burocrazia non rallenti o addirittura blocchi un\u2019opportunit\u00e0 per il nostro territorio, per l\u2019ambiente e il futuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Di seguito la nota del Il progetto da 3,5 miliardi di euro per la realizzazione di un parco eolico in mare tra le coste di Brindisi e San Cataldo, deve essere approvato e nel pi\u00f9 breve tempo possibile. E\u2019 un\u2019occasione per il nostro territorio, l\u2019ambiente, la transizione ecologica e l\u2019incremento dell\u2019autonomia energetica che non possiamo perdere e attorno al quale dobbiamo fare squadra. La proposta di installazione delle 98 pale eoliche in mare aperto presentata da Falck Renewables potrebbe avere importantissime ricadute economiche sul tessuto produttivo locale e dare numerosi posti di lavoro sia in fase di realizzazione (si prevedono 4.000 occupati) sia di gestione. In questi anni, e ancor pi\u00f9 in questi mesi, le difficolt\u00e0 economiche e lavorative per il nostro territorio sono emerse tutte ed \u00e8 sbagliato voltarsi dall\u2019altra parte. E i tempi che ci aspettano, anche alla luce di quanto riferito oggi in aula dal premier Mario Draghi, con la conversione del nostro sistema industriale verso lidi pi\u00f9 \u201cverdi\u201d e a minore impatto, non giocano di certo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":199141,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-199138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=199138"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199138\/revisions"}],"predecessor-version":[{"id":199145,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199138\/revisions\/199145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/199141"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=199138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=199138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=199138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}