{"id":199244,"date":"2022-02-28T16:42:42","date_gmt":"2022-02-28T15:42:42","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=199244"},"modified":"2022-02-28T20:49:08","modified_gmt":"2022-02-28T19:49:08","slug":"amati-rigassificatore-a-cerano-o-capobianco-impossibile-credibile-ipotesi-attigue-a-molo-petrolchimico","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/amati-rigassificatore-a-cerano-o-capobianco-impossibile-credibile-ipotesi-attigue-a-molo-petrolchimico\/","title":{"rendered":"Amati: \u201cRigassificatore a Cerano o Capobianco? Impossibile. Credibile ipotesi attigue a molo petrolchimico&#8221;"},"content":{"rendered":"<p>\u201c\u00c8 impossibile che a Cerano possa installarsi un rigassificatore, cos\u00ec come \u00e8 impossibile spostare in quel sito il serbatoio GNL. E pure l\u2019ipotesi del rigassificatore a Capobianco non \u00e8 plausibile, perch\u00e9 eliminerebbe lo spazio utile all\u2019unico grosso investimento in arrivo, cio\u00e8 quello per la realizzazione dei parchi eolici offshore al largo di Brindisi e Lecce.<br \/>\nSalvo che i tecnici non avanzino proposte plausibili, cerchiamo di non inquinare il dibattito pubblico con false illusioni.<br \/>\nAbbiamo il dovere della concretezza, per cui un rigassificatore a Brindisi sarebbe credibile solo in un\u2019area attigua al molo del petrolchimico, che per\u00f2 va raddoppiato al pi\u00f9 presto. Ne deriverebbero senza grosse complicazioni tre effetti positivi: lo spostamento del GPL da Costa Morena, la salvaguardia dell\u2019investimento per i parchi eolici offshore e l\u2019accoglienza di un nuovo investimento di rigassificazione. E tutto ci\u00f2 nello schema di una Brindisi che ha voglia di ripartire dando le spalle alle parole vane\u201d. <\/p>\n<p>Lo dichiara il presidente della Commissione bilancio e programmazione Fabiano Amati. <\/p>\n<p>\u201cDopo la notizia sulla riconversione del sito Enel di Cerano \u00e8 partito un dibattito pubblico sul futuro che se non centrato sui profili tecnici rischia di prendere improduttive pieghe polemiche. Come al solito.<br \/>\nIl sito di Cerano \u00e8 troppo lontano dai moli esistenti nel porto di Brindisi &#8211; tra i 14 e 20 km &#8211; per poter pensare sia alla realizzazione di un rigassificatore in quell\u2019area che allo spostamento del serbatoio GNL. L\u2019unica possibilit\u00e0 per rendere possibile tale ipotesi sarebbe quella di costruire un nuovo molo accostato al sito di Cerano per l\u2019approdo delle navi gasiere, per\u00f2 con tutto il suo carico d\u2019impatto ambientale a fronte di ipotesi alternative meno impattanti.<br \/>\nNeppure il sito di Capobianco mi sembra allo stato plausibile, perch\u00e9 interessato dalla zona franca doganale e destinato all\u2019unico grosso investimento di cui si sta parlando con concretezza e che speriamo non sia sabotato dalla politica del no-a-tutto: la realizzazione dei parchi eolici offshore al largo della costa di Brindisi e del sud Salento.<br \/>\nSe dunque le condizioni geo-politiche attuali, con tutto il loro carico di terrore, ci stanno portando finalmente a valutare i rigassificatori come nuova prospettiva industriale per fronteggiare anche le crisi occupazionali in corso, non resta che studiare l\u2019ipotesi di realizzazione dell\u2019impianto di rigassificazione nelle aree attigue al molo del petrolchimico, cominciando da subito il procedimento del suo raddoppio peraltro gi\u00e0 programmato per le attuali iniziative economiche e per la delocalizzazione dalla banchina di Costa Morena del deposito GPL.<br \/>\nTale iniziativa progettuale, a mio parere degna di un dibattito pubblico privo di ideologie e fondato su idee tecnicamente plausibili, comporterebbe nel giro di due-tre anni un grosso rilancio economico, connotato nel suo complesso dal seguente scenario: raddoppio del molo del petrolchimico; realizzazione di un serbatoio GNL a Costa Morena; delocalizzazione da Costa Morena del deposito GPL a tutto vantaggio del potenziale crocieristico del porto medio; insediamento a Capobianco del cantiere per la realizzazione dei parchi eolici offshore di Brindisi e Lecce; rigassificatore nelle aree attigue alle infrastrutturazioni portuali servite dal molo del petrolchimico.<br \/>\nUn programma che se realizzato terrebbe assieme tutte le esigenze e tutte le possibilit\u00e0 che allo stato il mondo industriale moderno offre, compresa l\u2019industria del turismo, in piena compatibilit\u00e0 con la transizione energetica e il desiderio di emanciparsi da un passato purtroppo connotato dalla congiunzione mortifera tra inquinamento e progresso, che a questo punto della storia solo l\u2019inerzia, l\u2019ideologia e le relative chiusure mentali ci potranno costringere a sopportare anche per il futuro\u201d.\/comunicato<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c\u00c8 impossibile che a Cerano possa installarsi un rigassificatore, cos\u00ec come \u00e8 impossibile spostare in quel sito il serbatoio GNL. E pure l\u2019ipotesi del rigassificatore a Capobianco non \u00e8 plausibile, perch\u00e9 eliminerebbe lo spazio utile all\u2019unico grosso investimento in arrivo, cio\u00e8 quello per la realizzazione dei parchi eolici offshore al largo di Brindisi e Lecce. Salvo che i tecnici non avanzino proposte plausibili, cerchiamo di non inquinare il dibattito pubblico con false illusioni. Abbiamo il dovere della concretezza, per cui un rigassificatore a Brindisi sarebbe credibile solo in un\u2019area attigua al molo del petrolchimico, che per\u00f2 va raddoppiato al pi\u00f9 presto. Ne deriverebbero senza grosse complicazioni tre effetti positivi: lo spostamento del GPL da Costa Morena, la salvaguardia dell\u2019investimento per i parchi eolici offshore e l\u2019accoglienza di un nuovo investimento di rigassificazione. E tutto ci\u00f2 nello schema di una Brindisi che ha voglia di ripartire dando le spalle alle parole vane\u201d. Lo dichiara il presidente della Commissione bilancio e programmazione Fabiano Amati. \u201cDopo la notizia sulla riconversione del sito Enel&#8230;<\/p>\n","protected":false},"author":2,"featured_media":183200,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-199244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=199244"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199244\/revisions"}],"predecessor-version":[{"id":199247,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199244\/revisions\/199247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/183200"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=199244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=199244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=199244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}