{"id":199391,"date":"2022-03-04T11:48:37","date_gmt":"2022-03-04T10:48:37","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=199391"},"modified":"2022-03-04T10:55:43","modified_gmt":"2022-03-04T09:55:43","slug":"inverno-cinematografico-domani-e-domenica-sebastiano-somma-allimpero-per-presentare-una-sconosciuta","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/inverno-cinematografico-domani-e-domenica-sebastiano-somma-allimpero-per-presentare-una-sconosciuta\/","title":{"rendered":"Inverno Cinematografico: domani e domenica Sebastiano Somma all&#8217;Impero per presentare &#8220;Una sconosciuta&#8221;"},"content":{"rendered":"<p>La rassegna \u201cInverno Cinematografico\u201d al Cinema Teatro Impero di Brindisi continua il 5 e 6 marzo con \u201cUna sconosciuta\u201d, per la regia di Fabrizio Guarducci con Sebastiano Somma, spettacoli ore 18 e 20.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;attore Sebastiano Somma sar\u00e0 presente a entrambi gli spettacoli di sabato 5 marzo per presentare il film e incontrare il pubblico.<\/p>\n<p>&nbsp;<\/p>\n<p>Il film \u00e8 ambientato in una cittadina dal glorioso passato, ormai desertificata, nella quale appare improvvisamente un\u2019affascinante donna misteriosa, bellissima. La sua presenza suscita le pi\u00f9 diverse reazioni e commenti fra i cittadini ed gli avventori del bar che \u00e8 solita frequentare in orari precisi. Il suo silenzio, enigmatico, riesce a tirar fuori spontaneamente dalle persone lati a loro stessi sconosciuti. Senza parlare, con il solo sorriso e la forza dello sguardo, invita coloro che vengono in contatto con lei a una serena riflessione introspettiva. E a trovare dentro se stessi una risposta alle loro domande. Improvvisamente, come era arrivata nella cittadina, senza che nessuno sapesse da dove, dopo aver restituito emozioni e risvegliato la vita della piccola comunit\u00e0, della Sconosciuta si perdono le tracce.<\/p>\n<p>&nbsp;<\/p>\n<p>Lentamente ma in maniera quasi inesorabile, la citt\u00e0 torna alla vita di sempre e i suoi abitanti riprendono a incontrarsi e dialogare. Resta in primo piano la figura della Sconosciuta che, con la sola sua presenza, ha illuminato di senso la comunit\u00e0. Ma chi \u00e8 la misteriosa figura femminile? Quale pu\u00f2 essere la sua storia? Quale il suo segreto?<\/p>\n<p>Trailer: https:\/\/bit.ly\/35CMAWb<\/p>\n<p>&nbsp;<\/p>\n<p>Costo biglietti: 6,00 \u20ac intero \/ 4,50 \u20ac ridotto (under 8 e over 65y), il botteghino apre mezz&#8217;ora prima della prima proiezione.<\/p>\n<p>L\u2019accesso agli spettacoli sar\u00e0 consentito solo ai soggetti muniti di Green Pass rafforzato e mascherina FFP2.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La rassegna \u201cInverno Cinematografico\u201d al Cinema Teatro Impero di Brindisi continua il 5 e 6 marzo con \u201cUna sconosciuta\u201d, per la regia di Fabrizio Guarducci con Sebastiano Somma, spettacoli ore 18 e 20. &nbsp; L&#8217;attore Sebastiano Somma sar\u00e0 presente a entrambi gli spettacoli di sabato 5 marzo per presentare il film e incontrare il pubblico. &nbsp; Il film \u00e8 ambientato in una cittadina dal glorioso passato, ormai desertificata, nella quale appare improvvisamente un\u2019affascinante donna misteriosa, bellissima. La sua presenza suscita le pi\u00f9 diverse reazioni e commenti fra i cittadini ed gli avventori del bar che \u00e8 solita frequentare in orari precisi. Il suo silenzio, enigmatico, riesce a tirar fuori spontaneamente dalle persone lati a loro stessi sconosciuti. Senza parlare, con il solo sorriso e la forza dello sguardo, invita coloro che vengono in contatto con lei a una serena riflessione introspettiva. E a trovare dentro se stessi una risposta alle loro domande. Improvvisamente, come era arrivata nella cittadina, senza che nessuno sapesse da dove, dopo aver restituito emozioni e risvegliato&#8230;<\/p>\n","protected":false},"author":2,"featured_media":134890,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-199391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=199391"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199391\/revisions"}],"predecessor-version":[{"id":199395,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199391\/revisions\/199395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/134890"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=199391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=199391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=199391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}