{"id":199647,"date":"2022-03-09T13:39:35","date_gmt":"2022-03-09T12:39:35","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=199647"},"modified":"2022-03-09T13:39:35","modified_gmt":"2022-03-09T12:39:35","slug":"confesercenti-incontra-lassessore-vitali","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/confesercenti-incontra-lassessore-vitali\/","title":{"rendered":"Confesercenti incontra l&#8217;Assessore Vitali"},"content":{"rendered":"<p>Alla presenza del Presidente Michele Piccirillo, del Direttore Angelo Colella e dei quadri dirigenti di Confesercenti Brindisi, si \u00e8 svolto un incontro con l\u2019Assessore alle Attivit\u00e0 Produttive del Comune di Brindisi Massimo Vitali.<br \/>\nTale incontro era stato chiesto dalla Confesercenti per fare il punto dello stato in cui versa il settore- commercio nel capoluogo e per rivolgere un appello all\u2019Amministrazione Comunale affinch\u00e9 intervenga su alcuni temi di scottante attualit\u00e0.<\/p>\n<p>All\u2019Assessore Vitali \u00e8 stata illustrata una fotografia della crisi del commercio, a partire dai 50 esercizi commerciali che hanno chiuso i battenti sui corsi principali, facendo lievitare la desertificazione del centro. Non \u00e8 un caso, infatti, che proprio i corsi principali (e pi\u00f9 in generale il centro storico) siano stati considerati \u201czona da sottoporre a misure di incentivo e di sostegno\u201d nel Documento Strategico del Commercio di Brindisi e inseriti come area di riferimento del Distretto Urbano del Commercio \u201cBrundisium\u201d<\/p>\n<p>.<br \/>\nAll\u2019Ass. Vitali la Confesercenti ha chiesto di considerare quanto previsto dalla Legge regionale 24\/2015 che per le aree da sottoporre a misure di incentivo e di sostegno prevede misure di agevolazione tributaria e sostegno finanziario, la realizzazione di opere infrastrutturali, di arredo urbano e di riorganizzazione della logistica urbana, l\u2019attivazione o la modifica di servizi urbani e l\u2019attuazione di azioni di promozione dell\u2019area.<\/p>\n<p>Fino ad oggi, infatti, le politiche di intervento poste in essere dall\u2019Amministrazione Comunale non hanno sortito gli effetti desiderati e quindi \u00e8 necessario procedere con maggiore determinazione, anche in considerazione di un aggravarsi della situazione economica.<br \/>\nIn particolare, si chiede all\u2019ente locale di attuare agevolazioni tributarie (in particolare per chi si insedia in locali sfitti), interventi di miglioramento de decoro urbano (vetrofonie su locali chiusi, pulizia degli spazi pubblici, installazione di bagni pubblici), la promozione (d\u2019intesa con il D.U.C) di iniziative di animazione e marketing territoriale (anche attraverso l\u2019utilizzo della tassa di soggiorno), il potenziamento del numero complessivo di posti-auto a ridosso e nel centro storico, la proroga dell\u2019esenzione della Tosap oltre il 31 marzo o comunque una sostanziale riduzione della tariffa.<\/p>\n<p>La Confesercenti, infine, ha invitato l\u2019Assessore Vitali a considerare lo squilibrio esistente a Brindisi tra media\/grande distribuzione (che occupa 125.501 metri quadrati) rispetto ai negozi di vicinato (che occupano 70.372 metri quadrati) ed il calo demografico (siamo passati da 87.820 abitanti del 2016 a 83.690 del 2020).<\/p>\n<p>Da qui l\u2019esigenza \u2013 ampiamente condivisa dall\u2019Assessore Vitali \u2013 di stabilire un confronto costante tra Amministrazione Comunale e Associazioni di categoria per individuare soluzioni praticabili ai problemi del settore commercio nella citt\u00e0 di Brindisi.<\/p>\n<p>&nbsp;<\/p>\n<p>COMUNICATO STAMPA CONFESERCENTI BRINDISI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alla presenza del Presidente Michele Piccirillo, del Direttore Angelo Colella e dei quadri dirigenti di Confesercenti Brindisi, si \u00e8 svolto un incontro con l\u2019Assessore alle Attivit\u00e0 Produttive del Comune di Brindisi Massimo Vitali. Tale incontro era stato chiesto dalla Confesercenti per fare il punto dello stato in cui versa il settore- commercio nel capoluogo e per rivolgere un appello all\u2019Amministrazione Comunale affinch\u00e9 intervenga su alcuni temi di scottante attualit\u00e0. All\u2019Assessore Vitali \u00e8 stata illustrata una fotografia della crisi del commercio, a partire dai 50 esercizi commerciali che hanno chiuso i battenti sui corsi principali, facendo lievitare la desertificazione del centro. Non \u00e8 un caso, infatti, che proprio i corsi principali (e pi\u00f9 in generale il centro storico) siano stati considerati \u201czona da sottoporre a misure di incentivo e di sostegno\u201d nel Documento Strategico del Commercio di Brindisi e inseriti come area di riferimento del Distretto Urbano del Commercio \u201cBrundisium\u201d . All\u2019Ass. Vitali la Confesercenti ha chiesto di considerare quanto previsto dalla Legge regionale 24\/2015 che per le aree da sottoporre&#8230;<\/p>\n","protected":false},"author":2,"featured_media":199649,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-199647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=199647"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199647\/revisions"}],"predecessor-version":[{"id":199651,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199647\/revisions\/199651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/199649"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=199647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=199647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=199647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}