{"id":199659,"date":"2022-03-09T15:18:49","date_gmt":"2022-03-09T14:18:49","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=199659"},"modified":"2022-03-09T15:22:11","modified_gmt":"2022-03-09T14:22:11","slug":"non-una-di-meno-brindisi-8-marzo-e-tentato-femminicidio-a-brindisi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/non-una-di-meno-brindisi-8-marzo-e-tentato-femminicidio-a-brindisi\/","title":{"rendered":"Non Una di Meno Brindisi: 8 Marzo e tentato femminicidio a Brindisi"},"content":{"rendered":"<p>Questo 8 marzo 2022 si \u00e8 svolto con un sit-in in piazza Vittoria a Brindisi, nonostante la pioggia incombente, in adesione allo sciopero globale femminista e transfemminista proclamato da Non Una Di Meno.<br \/>\n&nbsp;<br \/>\nLe tante energie e voci variegate  delle centinaia di    studentesse, studenti e anche docenti di gran parte delle   scuole brindisne, come il Morvillo, il Palumbo, il Giorgi, il Maiorana, il Fermi-Monticelli, l&#8217;Alberghiero,  che hanno partecipato  con i loro  striscioni, disegni, cartelli, interventi e letture  si sono mescolate alle altre e altri partecipanti, le attiviste e gli attivisti delle associazioni che hanno aderito con  il loro importante contributo, lavoratrici, sindacaliste, casalinghe, pensionate, e anche molti uomini,  tutte e tutt insieme per  rompere l&#8217;isolamento dopo due anni di pandemia, in cui sono peggiorate pesantemente le condizioni di vita e salute  delle donne e per  riprendere la parola e l&#8217;azione collettiva e pubblica.<br \/>\n&nbsp;<br \/>\nIn caso di maltempo avevamo prenotato le sale di Palazzo Nervegna per potere tenere  un&#8217;assemblea al coperto, sulle problematiche del lavoro, della  salute, della  scuola, della violenza di genere,  dei diritti delle persone LGBTQIA+ e soprattutto  contro la guerra in Ucraina, ma la forte affluenza di persone ci ha fatto ritornare in piazza Vittoria  per poter svolgere in sicurezza  la manifestazione.<br \/>\n&nbsp;<br \/>\nQui abbiamo rispettato un minuto di silenzio in ricordo di Sara Viva Sorge, giovane infermiera di San Vito dei Normanni, deceduta in un incidente stradale dopo una gravosa settimana di lavoro anche con turni di notte, di Lorenzo Parelli e Giuseppe Lenoci, studenti morti nello svolgimento dello stage formativo, delle 118 donne vittime di femminicidio e transcidio nel 2021  e delle vittime della guerra in Ucraina.<br \/>\n&nbsp;<br \/>\nCos\u00ec abbiamo potuto almeno in parte proseguire con alcuni interventi di attiviste, studentesse e studenti. L\u2019intensificazione della pioggia ha imposto la conclusione  della manifestazione, ma conserviamo l\u2019energia e la determinazione per continuare insieme la lotta.<br \/>\n&nbsp;<br \/>\nVerso la fine del sit-in abbiamo saputo che nella nostra citt\u00e0,  una donna anziana sta lottando tra la vita e la morte all\u2019ospedale Perrino perch\u00e9 \u00e8  stata accoltellata alla gola nel sonno dal marito 72enne, che poi si \u00e8 suicidato. Lo denunciamo ancora una volta: la violenza patriarcale si annida ovunque. LOTTIAMO CONTRO LA VIOLENZA SULLE ANZIANE, DUE VOLTE VITTIME: COME DONNE E COME PERSONE VULNERABILI, l\u2019abbiamo scritto su un cartello con l\u2019urlo che oggi 8 marzo abbiamo portato in piazza.<br \/>\n&nbsp;<br \/>\nAggiungiamo che il femminicidio, tentato o riuscito, \u00e8 il tragico epilogo di un continuum di violenza.<br \/>\nE\u2019 necessario  prevenire, riconoscere e  valutare il rischio di femminicidio ed affrontare in modo risolutivo la violenza di genere per salvare la vita delle donne e impedire che i figli e le figlie siano vittime di violenza assistita, o peggio ancora testimoni  dell\u2019omicidio della madre e spesso del suicidio del padre assassino, divenendo \u201corfani speciali\u201d. Speriamo nella salvezza della donna ferita, ma sappiamo che una grande tragedia ha investito una famiglia e una comunit\u00e0.<br \/>\n&nbsp;<br \/>\nA Brindisi esistono centri antiviolenza dove potersi rivolgere per  ricevere, nel rispetto della riservatezza e della privacy,  informazioni, consulenze ed assistenza per  affrontare la violenza sin dalla sua insorgenza e  quando se ne avvertono le prime avvisaglie.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Non Una di Meno Brindisi<\/strong><\/p>\n<p>Al sit-in hanno aderito:<br \/>\nAssociazione Io Donna, Coordinamento Donne ANPI, Coordinamento Donne SPI-CGIL, CGIL BR, Filcams-CGIL BR, La Collettiva TFQ BR, APS Ostello Nautico BR, Gruppo Uomini in Cammino BR, Community HUB APS, WG Academy HRD, FIAB BR, Auser BR, Associazione FR\/Azione Tuturano, Fiorediloto Torre S.Susanna, Commissione Pari Opportunit\u00e0 Comune Brindisi, Giovani Democratici provincia di BR, Sportello Bancario e Sovraindebitamento ADOC BR, Confederazione Cobas BR, Commissione Pari Opportunit\u00e0 Comune di Cisternino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questo 8 marzo 2022 si \u00e8 svolto con un sit-in in piazza Vittoria a Brindisi, nonostante la pioggia incombente, in adesione allo sciopero globale femminista e transfemminista proclamato da Non Una Di Meno. &nbsp; Le tante energie e voci variegate delle centinaia di studentesse, studenti e anche docenti di gran parte delle scuole brindisne, come il Morvillo, il Palumbo, il Giorgi, il Maiorana, il Fermi-Monticelli, l&#8217;Alberghiero, che hanno partecipato con i loro striscioni, disegni, cartelli, interventi e letture si sono mescolate alle altre e altri partecipanti, le attiviste e gli attivisti delle associazioni che hanno aderito con il loro importante contributo, lavoratrici, sindacaliste, casalinghe, pensionate, e anche molti uomini, tutte e tutt insieme per rompere l&#8217;isolamento dopo due anni di pandemia, in cui sono peggiorate pesantemente le condizioni di vita e salute delle donne e per riprendere la parola e l&#8217;azione collettiva e pubblica. &nbsp; In caso di maltempo avevamo prenotato le sale di Palazzo Nervegna per potere tenere un&#8217;assemblea al coperto, sulle problematiche del lavoro, della salute, della scuola,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":199660,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-199659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=199659"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199659\/revisions"}],"predecessor-version":[{"id":199667,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199659\/revisions\/199667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/199660"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=199659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=199659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=199659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}