{"id":199785,"date":"2022-03-11T18:03:37","date_gmt":"2022-03-11T17:03:37","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=199785"},"modified":"2022-03-15T19:52:42","modified_gmt":"2022-03-15T18:52:42","slug":"viaggio-nel-museo-archeologico-di-mesagne-presentato-oggi-al-castello-il-virtual-tour","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/viaggio-nel-museo-archeologico-di-mesagne-presentato-oggi-al-castello-il-virtual-tour\/","title":{"rendered":"Viaggio nel Museo Archeologico di Mesagne: presentato oggi al Castello il Virtual Tour"},"content":{"rendered":"<p>Nell\u2019Auditorium del Castello di Mesagne \u00e8 stato presentato stamattina il Virtual Tour promosso dall\u2019Amministrazione Comunale e patrocinato dalla regione Puglia che consentir\u00e0 di accedere virtualmente al Museo del Territorio \u201cUgo Granafei\u201d e al complesso archeologico di Vico Quercia.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cLo strumento \u00e8 senz\u2019altro un\u2019opportunit\u00e0 di promozione del ricco patrimonio storico custodito nel Museo cittadino, ma rappresenta anche un\u2019esperienza emozionale che alimenta la curiosit\u00e0 del visitatore, invitandolo a raggiungere fisicamente la meta esplorata\u201d, ha spiegato il sindaco della citt\u00e0 di Mesagne, Antonio Matarrelli, intervenendo alla conferenza stampa di presentazione del progetto svoltasi stamattina presso l\u2019auditorium del Castello di Mesagne.<\/p>\n<p>&nbsp;<\/p>\n<p>Hanno partecipato all\u2019iniziativa Marco Cal\u00f2, consulente alle Politiche Culturali e coordinatore per \u201cMesagne2024\u201d, e Antonio Calabrese, consulente comunale alla Disabilit\u00e0, Pari Opportunit\u00e0 e Cittadinanza Attiva. Entrambi hanno sottolineato il valore di un canale digitale di cui tutti possono avvalersi, attraverso i pi\u00f9 comuni e diffusi mezzi di comunicazione, e che si inserisce tra gli strumenti utili a favorire la fruizione universale dei beni, secondo una prospettiva di accesso illimitato offerto a ciascuno e, in particolare, alle persone con disabilit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Gli interventi in presenza del soprintendente Archeologia Puglia per le province di Brindisi e Lecce, Francesca Riccio, e di Luigi De Luca, dirigente Poli Biblio-Museali della Regione Puglia, hanno introdotto le finalit\u00e0 del progetto illustrato dalla dottoressa Alessia Galiano, direttore del Museo \u201cUgo Granafei\u201d di Mesagne, che ha infine dato la parola ai referenti della ditta \u201cVideonice\u201d, realizzatrice di progetto. \u201cHo colto l\u2019occasione per effettuare un piccolo tour non virtuale nella citt\u00e0 di Mesagne, che sa intessere proficui rapporti con altri soggetti, istituzionali e non, portatori di interessi del territorio. Ed \u00e8 questa un\u2019attitudine importante per la gestione del patrimonio culturale, che include archeologia, paesaggio, architettura, tutti aspetti mirabilmente fusi nella storia di questa cittadina. Anche questo mi sembra un punto a vostro favore\u201d, ha dichiarato il soprintendente Riccio.<\/p>\n<p>&nbsp;<\/p>\n<p>Julie Ant, visual artist di origine mesagnese che risiede e lavora a Milano, ha curato l\u2019ideazione dell\u2019animazione in 3D contenuta nel virtual dedicato a uno degli elementi pi\u00f9 caratteristici tra quelli esposti al pianoterra del Museo, vale a dire il cratere rinvenuto nel 1988, insieme ad altri 32 elementi, in pieno centro abitato a Mesagne. Il virtual tour completo \u00e8 disponibile sul sito istituzionale dell&#8217;Ente, per accedere \u00e8 possibile collegarsi al link <a href=\"http:\/\/www2.comune.mesagne.br.it\/virtualtour\/\">http:\/\/www2.comune.mesagne.br.it\/virtualtour\/<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>Mentre il fermento culturale nella citt\u00e0 messapica cresce con iniziative sempre nuove, la citt\u00e0 si prepara al verdetto finale con il quale il MiC il prossimo mercoled\u00ec 16 marzo alle 11 proclamer\u00e0 la Capitale italiana della Cultura per l&#8217;anno 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell\u2019Auditorium del Castello di Mesagne \u00e8 stato presentato stamattina il Virtual Tour promosso dall\u2019Amministrazione Comunale e patrocinato dalla regione Puglia che consentir\u00e0 di accedere virtualmente al Museo del Territorio \u201cUgo Granafei\u201d e al complesso archeologico di Vico Quercia. &nbsp; \u201cLo strumento \u00e8 senz\u2019altro un\u2019opportunit\u00e0 di promozione del ricco patrimonio storico custodito nel Museo cittadino, ma rappresenta anche un\u2019esperienza emozionale che alimenta la curiosit\u00e0 del visitatore, invitandolo a raggiungere fisicamente la meta esplorata\u201d, ha spiegato il sindaco della citt\u00e0 di Mesagne, Antonio Matarrelli, intervenendo alla conferenza stampa di presentazione del progetto svoltasi stamattina presso l\u2019auditorium del Castello di Mesagne. &nbsp; Hanno partecipato all\u2019iniziativa Marco Cal\u00f2, consulente alle Politiche Culturali e coordinatore per \u201cMesagne2024\u201d, e Antonio Calabrese, consulente comunale alla Disabilit\u00e0, Pari Opportunit\u00e0 e Cittadinanza Attiva. Entrambi hanno sottolineato il valore di un canale digitale di cui tutti possono avvalersi, attraverso i pi\u00f9 comuni e diffusi mezzi di comunicazione, e che si inserisce tra gli strumenti utili a favorire la fruizione universale dei beni, secondo una prospettiva di accesso illimitato offerto a&#8230;<\/p>\n","protected":false},"author":2,"featured_media":199787,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-199785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=199785"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199785\/revisions"}],"predecessor-version":[{"id":199788,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199785\/revisions\/199788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/199787"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=199785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=199785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=199785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}