{"id":199914,"date":"2022-03-14T14:47:04","date_gmt":"2022-03-14T13:47:04","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=199914"},"modified":"2022-03-14T17:48:04","modified_gmt":"2022-03-14T16:48:04","slug":"sanita-brindisi-caroli-fdi-disservizi-carenze-e-risarcimenti-ora-a-denunciare-non-e-solo-fdi-ma-anche-la-cgil","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/sanita-brindisi-caroli-fdi-disservizi-carenze-e-risarcimenti-ora-a-denunciare-non-e-solo-fdi-ma-anche-la-cgil\/","title":{"rendered":"Sanita\u2019 Brindisi. Caroli (fdi): disservizi, carenze e risarcimenti, ora a denunciare non \u00e8 solo Fdi ma anche la Cgil"},"content":{"rendered":"\n<p>Di seguito una nota  del consigliere regionale di Fratelli d\u2019Italia, Luigi Caroli:<\/p>\n<p>\u201cListe d&#8217;attesa, carenza di personale sanitario ma anche un lungo elenco di opere incompiute che sono costate alla Asl di Brindisi ben 900mila euro a titolo di risarcimento in favore delle imprese che non hanno potuto svolgere il proprio lavoro: sembra la sintesi di un nostro comunicato-denuncia e, invece, no. A denunciare i disservizi e le carenze della ASL di Brindisi \u00e8 la CGIL, un sindacato che sicuramente non pu\u00f2 essere annoverato fra quelli vicini al centrodestra e che ha sempre sostenuto, elettoralmente, i governi di centrosinistra che sono coloro che da oltre 16 anni organizzano e gestiscono la Sanit\u00e0 in Puglia. Una situazione generalmente disastrosa, ma che nella provincia di Brindisi \u00e8 allarmante.<\/p>\n<p>\u201cIn modo particolare l\u2019edilizia sanitaria messa in evidenza nella lettera della CGIL accerta quanto da noi sostenuto pi\u00f9 volte: inadempienze e ritardo di lavori. Il caso di Francavilla Fontana \u00e8 decisamente emblematico: un risarcimento di 900mila euro alle ditte appaltatrici perch\u00e9 impossibilitate a svolgere i lavori. Risorse pubbliche sprecate due volte. Ma tutti i casi riportati &#8211; dall\u2019ospedale di Mesagne, passando dal Perrino di Brindisi, finendo alle criticit\u00e0 di Fasano e San Pietro Vernotico \u2013 meritano un approfondimento e un interessamento da parte del nuovo direttore generale Roseto, che solleciteremo in un\u2019audizione alla quale convocheremo anche il segretario della CGIL, Antonio Macchia.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Di seguito una nota del consigliere regionale di Fratelli d\u2019Italia, Luigi Caroli: \u201cListe d&#8217;attesa, carenza di personale sanitario ma anche un lungo elenco di opere incompiute che sono costate alla Asl di Brindisi ben 900mila euro a titolo di risarcimento in favore delle imprese che non hanno potuto svolgere il proprio lavoro: sembra la sintesi di un nostro comunicato-denuncia e, invece, no. A denunciare i disservizi e le carenze della ASL di Brindisi \u00e8 la CGIL, un sindacato che sicuramente non pu\u00f2 essere annoverato fra quelli vicini al centrodestra e che ha sempre sostenuto, elettoralmente, i governi di centrosinistra che sono coloro che da oltre 16 anni organizzano e gestiscono la Sanit\u00e0 in Puglia. Una situazione generalmente disastrosa, ma che nella provincia di Brindisi \u00e8 allarmante. \u201cIn modo particolare l\u2019edilizia sanitaria messa in evidenza nella lettera della CGIL accerta quanto da noi sostenuto pi\u00f9 volte: inadempienze e ritardo di lavori. Il caso di Francavilla Fontana \u00e8 decisamente emblematico: un risarcimento di 900mila euro alle ditte appaltatrici perch\u00e9 impossibilitate a svolgere&#8230;<\/p>\n","protected":false},"author":2,"featured_media":174244,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-199914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=199914"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199914\/revisions"}],"predecessor-version":[{"id":199915,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/199914\/revisions\/199915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/174244"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=199914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=199914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=199914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}