{"id":200297,"date":"2022-03-26T15:14:43","date_gmt":"2022-03-26T14:14:43","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=200297"},"modified":"2022-03-26T15:14:43","modified_gmt":"2022-03-26T14:14:43","slug":"bbc-con-europa-verde-piena-convergenza-su-tutti-i-temi-che-ispirano-il-nostro-movimento","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/bbc-con-europa-verde-piena-convergenza-su-tutti-i-temi-che-ispirano-il-nostro-movimento\/","title":{"rendered":"BBC: &#8220;con Europa Verde piena convergenza su tutti i temi che ispirano il nostro movimento&#8221;"},"content":{"rendered":"<p>Brindisi Bene Comune, nella sala Conferenze di palazzo Nervegna piena di cittadine e cittadini interessati al proprio futuro, ha sancito il suo ingresso nella grande famiglia dei Verdi europei aderendo al partito Europa Verde-Verdi. L&#8217;adesione alla Federazione \u00e8 stata decisa ed attuata per la convergenza su tutti i temi che da sempre ispirano il nostro movimento. Ambiente, salute, lavoro e sviluppo declinati secondo il principio inderogabile dell&#8217;equit\u00e0 sociale sono i temi che ispirano la nostra azione politica e li abbiamo ritrovati coniugati con la stessa visione e progettualit\u00e0 nel gruppo cui abbiamo dato l&#8217;adesione. Per realizzare un programma politico di tale rilevanza si \u00e8 reso necessario poter interloquire ad un livello istituzionale pi\u00f9 alto di quello accessibile ad una Lista civica. La presenza in Citt\u00e0 ed in collegamento streaming dei parlamentari Eleonora Evi ed Angelo Bonelli hanno definito in modo esplicito l&#8217;attenzione al nostro territorio ed alle sue annose istanze, spesso relegate ad un ruolo secondario rispetto ai bisogni di un governo centrale che ha sempre preso e preteso, dando in cambio assai poco. Tutti gli interventi sono stati centrati oltre che sulla grave contingenza della guerra, sulle conseguenze che le miopi scelte politiche del passato in ambito energetico, hanno determinato per gli italiani e le italiane. La nostra Consigliera Luana Mia Pirelli ha evidenziato come, appunto, le scelte sono determinanti nello sviluppo del territorio, ricordando che laddove ora sorge l&#8217;area marina protetta di Torre Guaceto, 40 anni fa il Governo di Roma aveva individuato il sito per costruire una Centrale nucleare. E&#8217; stato dunque rivendicato un nuovo piano di sviluppo energetico che garantisca condizioni di vita dignitosa alle popolazioni dove l&#8217;energia si produce. Questa ed altre le sfide lanciate al Governo Draghi ed in particolare al Ministro Cingolani dal Sindaco Riccardo Rossi, che noi facciamo nostre.<\/p>\n<p>&nbsp;<\/p>\n<p>BRINDISI BENE COMUNE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brindisi Bene Comune, nella sala Conferenze di palazzo Nervegna piena di cittadine e cittadini interessati al proprio futuro, ha sancito il suo ingresso nella grande famiglia dei Verdi europei aderendo al partito Europa Verde-Verdi. L&#8217;adesione alla Federazione \u00e8 stata decisa ed attuata per la convergenza su tutti i temi che da sempre ispirano il nostro movimento. Ambiente, salute, lavoro e sviluppo declinati secondo il principio inderogabile dell&#8217;equit\u00e0 sociale sono i temi che ispirano la nostra azione politica e li abbiamo ritrovati coniugati con la stessa visione e progettualit\u00e0 nel gruppo cui abbiamo dato l&#8217;adesione. Per realizzare un programma politico di tale rilevanza si \u00e8 reso necessario poter interloquire ad un livello istituzionale pi\u00f9 alto di quello accessibile ad una Lista civica. La presenza in Citt\u00e0 ed in collegamento streaming dei parlamentari Eleonora Evi ed Angelo Bonelli hanno definito in modo esplicito l&#8217;attenzione al nostro territorio ed alle sue annose istanze, spesso relegate ad un ruolo secondario rispetto ai bisogni di un governo centrale che ha sempre preso e preteso, dando&#8230;<\/p>\n","protected":false},"author":2,"featured_media":200298,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-200297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=200297"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200297\/revisions"}],"predecessor-version":[{"id":200299,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200297\/revisions\/200299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/200298"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=200297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=200297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=200297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}