{"id":200312,"date":"2022-03-26T20:34:55","date_gmt":"2022-03-26T19:34:55","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=200312"},"modified":"2022-03-26T20:34:55","modified_gmt":"2022-03-26T19:34:55","slug":"confesercenti-sui-corsi-principali-di-brindisi-compaiono-i-soliti-gazebo-ma-nessuno-sa-chi-ha-concesso-lautorizzazione","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/confesercenti-sui-corsi-principali-di-brindisi-compaiono-i-soliti-gazebo-ma-nessuno-sa-chi-ha-concesso-lautorizzazione\/","title":{"rendered":"Confesercenti: &#8220;sui corsi principali di Brindisi compaiono i soliti gazebo, ma nessuno sa chi ha concesso l&#8217;autorizzazione&#8221;"},"content":{"rendered":"<p>Al di fuori da ogni logica di programmazione, anche in questo fine settimana sui corsi principali di Brindisi sono comparsi dei gazebo per la vendita di merci varie. E\u2019 una forma inaccettabile di concorrenza nei confronti dei commercianti a posto fisso, tanto pi\u00f9 se si considera che la presenza di queste strutture non coincide con feste particolari (Natale, Pasqua, ecc\u2026) e non ha alcuna finalit\u00e0 particolare, se non quella di danneggiare l\u2019intero comparto in una giornata importante come il sabato.<\/p>\n<p>&nbsp;<\/p>\n<p>E\u2019 evidente, pertanto, che siamo alle prese con la solita improvvisazione, tanto pi\u00f9 se si considera che l\u2019Assessore alle Attivit\u00e0 Produttive non avrebbe sottoscritto alcuna autorizzazione. Un fatto gravissimo, che contribuisce a rendere inefficace pure l\u2019azione del Distretto Urbano del Commercio.<\/p>\n<p>&nbsp;<\/p>\n<p>La Confesercenti, anche nel corso dell\u2019incontro avuto con lo stesso Assessore Vitali, ha confermato la piena disponibilit\u00e0 a collaborare per mettere in campo interventi finalizzati ad una valorizzazione commerciale del centro di Brindisi. Fino a questo momento, per\u00f2, non si \u00e8 fatto nulla di concreto e la nostra proposta di disponibilit\u00e0 al costante dialogo \u00e8 stata rispedita al mittente.<\/p>\n<p>&nbsp;<\/p>\n<p>E\u2019 cos\u00ec che si contribuisce ad affossare il commercio di Brindisi!<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Michele Piccirillo \u2013 Presidente Confesercenti Brindisi<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al di fuori da ogni logica di programmazione, anche in questo fine settimana sui corsi principali di Brindisi sono comparsi dei gazebo per la vendita di merci varie. E\u2019 una forma inaccettabile di concorrenza nei confronti dei commercianti a posto fisso, tanto pi\u00f9 se si considera che la presenza di queste strutture non coincide con feste particolari (Natale, Pasqua, ecc\u2026) e non ha alcuna finalit\u00e0 particolare, se non quella di danneggiare l\u2019intero comparto in una giornata importante come il sabato. &nbsp; E\u2019 evidente, pertanto, che siamo alle prese con la solita improvvisazione, tanto pi\u00f9 se si considera che l\u2019Assessore alle Attivit\u00e0 Produttive non avrebbe sottoscritto alcuna autorizzazione. Un fatto gravissimo, che contribuisce a rendere inefficace pure l\u2019azione del Distretto Urbano del Commercio. &nbsp; La Confesercenti, anche nel corso dell\u2019incontro avuto con lo stesso Assessore Vitali, ha confermato la piena disponibilit\u00e0 a collaborare per mettere in campo interventi finalizzati ad una valorizzazione commerciale del centro di Brindisi. Fino a questo momento, per\u00f2, non si \u00e8 fatto nulla di concreto e la&#8230;<\/p>\n","protected":false},"author":2,"featured_media":200315,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-200312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=200312"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200312\/revisions"}],"predecessor-version":[{"id":200319,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200312\/revisions\/200319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/200315"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=200312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=200312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=200312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}