{"id":200424,"date":"2022-03-29T11:20:22","date_gmt":"2022-03-29T09:20:22","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=200424"},"modified":"2022-03-29T11:20:22","modified_gmt":"2022-03-29T09:20:22","slug":"dall1-aprile-raccolta-dei-rifiuti-indifferenziati-solo-martedi-e-sabato","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/dall1-aprile-raccolta-dei-rifiuti-indifferenziati-solo-martedi-e-sabato\/","title":{"rendered":"Dall\u20191 aprile raccolta dei rifiuti indifferenziati solo marted\u00ec e sabato"},"content":{"rendered":"<p>Con la fine dello stato di emergenza sanitaria nazionale, viene anche annullato il conferimento straordinario dei rifiuti indifferenziati previsto il gioved\u00ec e disposto proprio in concomitanza della pandemia da Covid 19. <\/p>\n<p>Dunque dall\u20191 aprile il materiale indifferenziato verr\u00e0 ritirato da Ecotecnica solo  marted\u00ec e sabato. Il resto del calendario della raccolta previsto per gli altri materiali resta invariato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la fine dello stato di emergenza sanitaria nazionale, viene anche annullato il conferimento straordinario dei rifiuti indifferenziati previsto il gioved\u00ec e disposto proprio in concomitanza della pandemia da Covid 19. Dunque dall\u20191 aprile il materiale indifferenziato verr\u00e0 ritirato da Ecotecnica solo marted\u00ec e sabato. Il resto del calendario della raccolta previsto per gli altri materiali resta invariato.<\/p>\n","protected":false},"author":2,"featured_media":200425,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-200424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=200424"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200424\/revisions"}],"predecessor-version":[{"id":200426,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200424\/revisions\/200426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/200425"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=200424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=200424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=200424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}