{"id":200471,"date":"2022-03-29T15:07:51","date_gmt":"2022-03-29T13:07:51","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=200471"},"modified":"2022-04-08T15:36:43","modified_gmt":"2022-04-08T13:36:43","slug":"e-uscito-male-male-male-il-nuovo-travolgente-singolo-di-ignazio-deg","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/e-uscito-male-male-male-il-nuovo-travolgente-singolo-di-ignazio-deg\/","title":{"rendered":"\u00c8 uscito \u00abMale Male Male\u00bb il nuovo, travolgente singolo di Ignazio Deg"},"content":{"rendered":"<p>\u00c8 su tutte le piattaforme digitali \u201cMale Male Male\u201d, ottavo singolo dell\u2019artista mesagnese Ignazio Deg. A poco meno di un anno dal successo di \u201cCome sale\u201d nel quale affronta il tema dell\u2019omofobia, il poliedrico cantautore salentino torna sulla scena con un mood diversamente malinconico per raccontare la storia di un uomo che ha deciso di liberarsi dalle sue dipendenze, da ci\u00f2 che fa male, da tutto quello che di tossico lo circonda. Compito tutt\u2019altro che semplice perch\u00e9 istigato ogni giorno dal bene che fa male.<br \/>\n\u201cMale Male Male\u201d \u00e8 stato composto a quattro mani insieme all\u2019eclettico Cristiano Cosa, cantautore tarantino che nel 2016 ribalt\u00f2, con le sue performances live, il serale del premiatissimo format televisivo di \u201cAmici\u201d di Maria De Filippi. Il nuovo brando di Ignazio Deg esplode in un beat dinamico con sonorit\u00e0 elettroniche e ricercate che scatenano letteralmente la voglia di ballare. Beat e arrangiamento sono stata realizzati dal noto produttore Max Calo.<\/p>\n<p>Insieme al brano fuori anche il videoclip che l\u2019artista mesagnese ha voluto affidare, ancora una volta, alla Monkey Studio e all\u2019eclettico Diego Colucci; una scelta che ha dato subito i suoi frutti vista l\u2019incredibile impennata di views registrate in soli due giorni. Nel classico Monkey Style, il video \u00e8 pieno di sorprese: il protagonista viene letteralmente sequestrato dalla sua coscienza che lo obbliga alla riflessione attraverso un susseguirsi continuo di flashback che hanno lo scopo di porre l\u2019attenzione sulla coniugazione dei peccati e sulla facilit\u00e0 con la quale li stessi diventino abitudine e quindi diano dipendenza. Diego Colucci riesce a stupire ancora una volta cimentandosi nel difficile compito di raccontare il vizio, anche quello pi\u00f9 proibito, senza mai risultare scontato e soprattutto volgare. Il modo di mettere in scena la storia di \u201cIgnazio Deg\u201d da parte del creativo della Monkey Studio, celebra la realt\u00e0 senza fronzoli, raccontata nuda e cruda, e conquista l\u2019occhio dell\u2019osservatore pi\u00f9 attento che viene travolto dalle metafore e dai messaggi subliminali che Diego ama inserire nelle sue produzioni. Il videoclip \u00e8 stato girato in diverse location comprese nella zona tra Mesagne e Brindisi e ha visto la partecipazione di centinaia di comparse provenienti da tutta la Puglia. Una chicca la splendida e coinvolgente coreografia inserita tra le immagini della clip, curata dal maestro Vito Alfarano della AlphaZTL Compagnia d\u2019Arte Dinamica di Brindisi e dal coreografo cegliese Francesco Biasi.<\/p>\n<p>Video:<br \/>\n <iframe loading=\"lazy\" title=\"Ignazio Deg Male Male Male\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/HIwKY4Gnumc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 su tutte le piattaforme digitali \u201cMale Male Male\u201d, ottavo singolo dell\u2019artista mesagnese Ignazio Deg. A poco meno di un anno dal successo di \u201cCome sale\u201d nel quale affronta il tema dell\u2019omofobia, il poliedrico cantautore salentino torna sulla scena con un mood diversamente malinconico per raccontare la storia di un uomo che ha deciso di liberarsi dalle sue dipendenze, da ci\u00f2 che fa male, da tutto quello che di tossico lo circonda. Compito tutt\u2019altro che semplice perch\u00e9 istigato ogni giorno dal bene che fa male. \u201cMale Male Male\u201d \u00e8 stato composto a quattro mani insieme all\u2019eclettico Cristiano Cosa, cantautore tarantino che nel 2016 ribalt\u00f2, con le sue performances live, il serale del premiatissimo format televisivo di \u201cAmici\u201d di Maria De Filippi. Il nuovo brando di Ignazio Deg esplode in un beat dinamico con sonorit\u00e0 elettroniche e ricercate che scatenano letteralmente la voglia di ballare. Beat e arrangiamento sono stata realizzati dal noto produttore Max Calo. Insieme al brano fuori anche il videoclip che l\u2019artista mesagnese ha voluto affidare, ancora una&#8230;<\/p>\n","protected":false},"author":2,"featured_media":200474,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[189,7],"tags":[],"class_list":["post-200471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica-2","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=200471"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200471\/revisions"}],"predecessor-version":[{"id":200475,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200471\/revisions\/200475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/200474"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=200471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=200471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=200471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}