{"id":200478,"date":"2022-03-29T18:13:18","date_gmt":"2022-03-29T16:13:18","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=200478"},"modified":"2022-03-30T15:17:17","modified_gmt":"2022-03-30T13:17:17","slug":"sport-nei-parchi-premiato-il-progetto-di-san-michele-salentino","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/sport-nei-parchi-premiato-il-progetto-di-san-michele-salentino\/","title":{"rendered":"Sport nei parchi: premiato il progetto di San Michele Salentino"},"content":{"rendered":"<p>Ampliare l\u2019offerta sportiva all\u2019aperto, in particolare a parco Augelluzzi, coinvolgendo le associazioni e societ\u00e0 sportive del territorio e al tempo stesso promuovere attivit\u00e0 gratuite per i cittadini. Sono questi i due temi che trovano riscontro nel finanziamento che l\u2019amministrazione comunale di San Michele Salentino ha ottenuto partecipando al bando nazionale \u201cSport nei parchi\u201d promosso da Sport e Salute S.p.a. e Anci. Il progetto proposto dall\u2019amministrazione, assessorato allo sport guidato da Angela Martucci, \u00e8 stato giudicato meritevole ed \u00e8 entrato nella graduatoria dei progetti che saranno cofinanziati.<\/p>\n<p>Sport e Salute S.p.A e Anci hanno siglato un protocollo d\u2019intesa che attraverso il progetto \u201cSport nei parchi\u201d vuole favorire i Comuni per l\u2019allestimento, il recupero, la fruizione e la gestione di attrezzature, servizi ed attivit\u00e0 sportive nei parchi urbani. Il bando voluto da Sport e Salute e Anci nasce, infatti, in considerazione della particolare situazione sanitaria che ha costretto alla chiusura di palestre e centri sportivi generando una grande richiesta di spazi all\u2019aperto per la ripresa dell\u2019attivit\u00e0 sportiva in sicurezza.<\/p>\n<p>Il Comune di San Michele Salentino ha aderito ad entrambe le linee di intervento, individuando il parco Comunale Augelluzzi dove verranno promossi nuovi modelli di pratica sportiva all\u2019aperto, sia in autonomia che attraverso le associazioni e societ\u00e0 dilettantistiche locali. Progetto, documentazione e relativa procedura di partecipazione sono stati seguiti con le professionalit\u00e0 presenti all\u2019interno della struttura comunale e in particolare dal dott. Fabrizio Guglielmi. Nelle prossime settimane, quindi, sar\u00e0 stipulata una convenzione tra il Comune e Sport e Salute che si occuperanno di stendere un avviso pubblico per l\u2019individuazione delle Asd\/Ssd che effettueranno le attivit\u00e0 sportive nell\u2019area proposta.<\/p>\n<p>\u201cL\u2019Amministrazione continua a impegnarsi in tutti i modi possibili per estendere, migliorare e garantire la possibilit\u00e0 di fare sport per tutti i cittadini \u2013 spiega l\u2019assessora al ramo, Angela Martucci \u2013 ricordo il finanziamento di 100mila ottenuto per la riqualificazione del palazzetto dello sport e i 600mila del bando \u201cSport e Periferie\u201d per rimettere a nuovo il campo sportivo dove sorger\u00e0 un centro sportivo polivalente. Oggi consegniamo alla comunit\u00e0 un ulteriore finanziamento che dar\u00e0 la possibilit\u00e0 ai cittadini di dedicarsi alla pratica sportiva all\u2019aria aperta, in modo particolare a parco Augelluzzi che sar\u00e0, maggiormente, valorizzato grazie, anche, allo sport e alle associazioni e societ\u00e0 sportive locali.\u201d<\/p>\n<p>Il progetto candidato alla linea di intervento numero 2 ha ottenuto 24mila euro, parte co-finanziato, e prevede tre \u201cisole di sport\u201d, un\u2019area dimostrativa per eventi e nuove attrezzature con il coinvolgimento delle Asd\/Ssd del territorio per svolgere durante la settimana la propria attivit\u00e0 e nel week end offrire un programma di attivit\u00e0 gratuite (finanziate da Sport e salute) destinate a diversi target (bambini e ragazzi, donne, over65).<\/p>\n<p>\u201cCi fa onore questo riconoscimento ottenuto grazie al lavoro del dott. Fabrizio Guglielmi e dell\u2019assessore allo sport Angela Martucci \u2013 dichiara il sindaco Giovanni Allegrini. Si apre adesso una fase in cui il Comune e le associazioni sportive del territorio potranno collaborare per produrre un\u2019offerta di sport e salute nel parco comunale per i nostri cittadini. Incentivare le attivit\u00e0 all\u2019aperto \u00e8 il modo pi\u00f9 naturale e coinvolgente per socializzare, recuperando il tempo per le relazioni e le amicizie che questa pandemia da Covid-19 un po\u2019 ci aveva tolto.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ampliare l\u2019offerta sportiva all\u2019aperto, in particolare a parco Augelluzzi, coinvolgendo le associazioni e societ\u00e0 sportive del territorio e al tempo stesso promuovere attivit\u00e0 gratuite per i cittadini. Sono questi i due temi che trovano riscontro nel finanziamento che l\u2019amministrazione comunale di San Michele Salentino ha ottenuto partecipando al bando nazionale \u201cSport nei parchi\u201d promosso da Sport e Salute S.p.a. e Anci. Il progetto proposto dall\u2019amministrazione, assessorato allo sport guidato da Angela Martucci, \u00e8 stato giudicato meritevole ed \u00e8 entrato nella graduatoria dei progetti che saranno cofinanziati. Sport e Salute S.p.A e Anci hanno siglato un protocollo d\u2019intesa che attraverso il progetto \u201cSport nei parchi\u201d vuole favorire i Comuni per l\u2019allestimento, il recupero, la fruizione e la gestione di attrezzature, servizi ed attivit\u00e0 sportive nei parchi urbani. Il bando voluto da Sport e Salute e Anci nasce, infatti, in considerazione della particolare situazione sanitaria che ha costretto alla chiusura di palestre e centri sportivi generando una grande richiesta di spazi all\u2019aperto per la ripresa dell\u2019attivit\u00e0 sportiva in sicurezza. Il Comune di&#8230;<\/p>\n","protected":false},"author":2,"featured_media":182120,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-200478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=200478"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200478\/revisions"}],"predecessor-version":[{"id":200479,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200478\/revisions\/200479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/182120"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=200478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=200478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=200478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}