{"id":200502,"date":"2022-03-31T08:41:47","date_gmt":"2022-03-31T06:41:47","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=200502"},"modified":"2022-03-31T14:47:04","modified_gmt":"2022-03-31T12:47:04","slug":"my-way-allombra-delle-colonne-romane-un-aprile-allinsegna-di-eventi-targati-out-of-district","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/my-way-allombra-delle-colonne-romane-un-aprile-allinsegna-di-eventi-targati-out-of-district\/","title":{"rendered":"My Way: all\u2019ombra delle colonne romane un aprile all\u2019insegna di eventi targati Out of District"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-200504\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/03\/Logo-My-Way-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/03\/Logo-My-Way-300x300.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/03\/Logo-My-Way-150x150.jpg 150w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/03\/Logo-My-Way-600x600.jpg 600w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/03\/Logo-My-Way-60x60.jpg 60w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/03\/Logo-My-Way.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Promuovere il turismo nella splendida citt\u00e0 di Brindisi attraverso la creazione di eventi di interesse pubblico con proposte d&#8217;arte, di musica e cultura del territorio.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c8 il nuovo volto del My Way che presso i propri spazi di via Colonne, 57 in una delle aree pi\u00f9 rappresentative del Capoluogo Adriatico propone la rassegna musicale e artistica presentata da Out Of District, il nuovo progetto intrapreso da 5 DJ: Andrea lpr, Dodo, Paolo De Mitri, Refresh e David.One che sono i resident degli eventi al My Way per gli appuntamenti di aprile.<\/p>\n<p>&nbsp;<\/p>\n<p>Il locale dal panorama suggestivo, ospiter\u00e0 ogni domenica DJ di calibro nazionale; nel particolare la prima domenica, il 3 aprile, avr\u00e0 come ospite Gianni Sabato, il 10 aprile ci sar\u00e0 Kosmico, il 17 aprile sar\u00e0 la volta di Limo e il 24 aprile si chiuder\u00e0 con Luciano Esse. Nomi d\u2019eccezione, tutti resident dei locali underground pi\u00f9 famosi della Puglia come: Lullabay, Guendalina, Sound Department e Transition Lab.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-200503 alignright\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/03\/Aprile2022-My-WayBrindisi-300x276.jpg\" alt=\"\" width=\"300\" height=\"276\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/03\/Aprile2022-My-WayBrindisi-300x276.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/03\/Aprile2022-My-WayBrindisi.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Inoltre, a partire da domenica 3 aprile, all&#8217;interno del My Way ed in concomitanza con il primo degli appuntamenti del calendario proposto da Out of District, sar\u00e0 possibile visitare una mostra d&#8217;arte contemporanea a cura dell&#8217;artista, performer, organizzatrice d&#8217;eventi e curatrice d&#8217;arte Giulia Crastolla, attiva sul panorama brindisino con eventi culturali e artistici nonch\u00e8 ospite di rassegne artistiche in diverse citt\u00e0 italiane.<\/p>\n<p>&nbsp;<\/p>\n<p>Gli artisti proposti sono Galiano Lombardi, Amanda Librale, Vincenzo De Nigris, Edoardo Carlucci, Stefano Piccirillo, Giuseppe Castellana, Alessandro Ribezzi, Giulia Crastolla e Davide Cocozza, artista, docente d&#8217;arte, performer ed arteterapeuta noto in Italia e fuori. Numerose le collaborazioni, tra cui market di vinili a cura di &#8220;Discordia&#8221; da Taranto e l&#8217;esibizione di pole dance con Vertical Gym di Brindisi.<\/p>\n<p>&nbsp;<\/p>\n<p>Diversi i supporter dell&#8217;evento, ricordando come main sponsor Just Weed, Rebelution, Spazio Vintage e End Point, oltre a Severino parrucchieri e Kilowear.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Ufficio Stampa<\/strong><\/em><br \/>\n<em><strong>SummerTime \u2013 Animazione &amp; Spettacolo<\/strong><\/em><br \/>\n<em><strong>Per My Way Brindisi<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Promuovere il turismo nella splendida citt\u00e0 di Brindisi attraverso la creazione di eventi di interesse pubblico con proposte d&#8217;arte, di musica e cultura del territorio. &nbsp; \u00c8 il nuovo volto del My Way che presso i propri spazi di via Colonne, 57 in una delle aree pi\u00f9 rappresentative del Capoluogo Adriatico propone la rassegna musicale e artistica presentata da Out Of District, il nuovo progetto intrapreso da 5 DJ: Andrea lpr, Dodo, Paolo De Mitri, Refresh e David.One che sono i resident degli eventi al My Way per gli appuntamenti di aprile. &nbsp; Il locale dal panorama suggestivo, ospiter\u00e0 ogni domenica DJ di calibro nazionale; nel particolare la prima domenica, il 3 aprile, avr\u00e0 come ospite Gianni Sabato, il 10 aprile ci sar\u00e0 Kosmico, il 17 aprile sar\u00e0 la volta di Limo e il 24 aprile si chiuder\u00e0 con Luciano Esse. Nomi d\u2019eccezione, tutti resident dei locali underground pi\u00f9 famosi della Puglia come: Lullabay, Guendalina, Sound Department e Transition Lab. &nbsp; Inoltre, a partire da domenica 3 aprile, all&#8217;interno del&#8230;<\/p>\n","protected":false},"author":2,"featured_media":200505,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[189,7],"tags":[],"class_list":["post-200502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica-2","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=200502"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200502\/revisions"}],"predecessor-version":[{"id":200507,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200502\/revisions\/200507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/200505"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=200502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=200502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=200502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}