{"id":200928,"date":"2022-04-13T14:38:44","date_gmt":"2022-04-13T12:38:44","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=200928"},"modified":"2022-04-13T14:38:44","modified_gmt":"2022-04-13T12:38:44","slug":"pasqua-e-pasquetta-nei-castelli-forte-a-mare-brindisi-e-castello-dentice-di-frasso-carovigno","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/pasqua-e-pasquetta-nei-castelli-forte-a-mare-brindisi-e-castello-dentice-di-frasso-carovigno\/","title":{"rendered":"Pasqua e Pasquetta nei Castelli Forte a Mare (Brindisi) e Castello Dentice di Frasso (Carovigno)"},"content":{"rendered":"<p>Domenica 17 e luned\u00ec 18 aprile, in occasione delle festivit\u00e0 di Pasqua e Pasquetta, la Aps Le Colonne propone delle visite guidate con aperture e turni straordinari in due splendidi castelli del brindisino, Forte a Mare a Brindisi e il Castello Dentice di Frasso a Carovigno.<\/p>\n<p>&nbsp;<\/p>\n<p>Forte a Mare, suggestiva struttura difensiva sull\u2019isola di Sant\u2019Andrea, accoglier\u00e0 i visitatori secondo i seguenti turni di visita: ore 10,00-11,00-12,00-16,30-17,30 e 18,30.<\/p>\n<p>Le visite, disponibili in varie lingue, sono guidate da personale abilitato e hanno una durata di 50 minuti circa.<\/p>\n<p>La prenotazione \u00e8 obbligatoria ed \u00e8 possibile effettuarla chiamando al numero 3792653244 o inviando una mail a segreterialecolonne@gmail.com.<\/p>\n<p>Il Castello Dentice di Frasso di Carovigno, nato come struttura difensiva probabilmente in epoca normanna e successivamente trasformato in dimora gentilizia, aprir\u00e0 le sue porte dalle ore 10 alle 13,30 e dalle ore 16,30 alle 19,30. Si possono richiedere visite guidate da personale abilitato previa prenotazione obbligatoria.<\/p>\n<p>&nbsp;<\/p>\n<p>Per richiedere informazioni ed effettuare la prenotazione chiamare al numero 3791092451 o inviare una mail a castellodicarovigno@gmail.com.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Comunicato stampa Ass. Le Colonne<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 17 e luned\u00ec 18 aprile, in occasione delle festivit\u00e0 di Pasqua e Pasquetta, la Aps Le Colonne propone delle visite guidate con aperture e turni straordinari in due splendidi castelli del brindisino, Forte a Mare a Brindisi e il Castello Dentice di Frasso a Carovigno. &nbsp; Forte a Mare, suggestiva struttura difensiva sull\u2019isola di Sant\u2019Andrea, accoglier\u00e0 i visitatori secondo i seguenti turni di visita: ore 10,00-11,00-12,00-16,30-17,30 e 18,30. Le visite, disponibili in varie lingue, sono guidate da personale abilitato e hanno una durata di 50 minuti circa. La prenotazione \u00e8 obbligatoria ed \u00e8 possibile effettuarla chiamando al numero 3792653244 o inviando una mail a segreterialecolonne@gmail.com. Il Castello Dentice di Frasso di Carovigno, nato come struttura difensiva probabilmente in epoca normanna e successivamente trasformato in dimora gentilizia, aprir\u00e0 le sue porte dalle ore 10 alle 13,30 e dalle ore 16,30 alle 19,30. Si possono richiedere visite guidate da personale abilitato previa prenotazione obbligatoria. &nbsp; Per richiedere informazioni ed effettuare la prenotazione chiamare al numero 3791092451 o inviare una mail a&#8230;<\/p>\n","protected":false},"author":2,"featured_media":200930,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-200928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=200928"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200928\/revisions"}],"predecessor-version":[{"id":200931,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/200928\/revisions\/200931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/200930"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=200928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=200928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=200928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}