{"id":201006,"date":"2022-04-14T09:12:29","date_gmt":"2022-04-14T07:12:29","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=201006"},"modified":"2022-04-14T09:12:29","modified_gmt":"2022-04-14T07:12:29","slug":"terre-di-fasano-ecco-il-nome-scelto-dalla-comunita-per-la-destinazione-turistica","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/terre-di-fasano-ecco-il-nome-scelto-dalla-comunita-per-la-destinazione-turistica\/","title":{"rendered":"Terre di Fasano: ecco il nome scelto dalla comunit\u00e0 per la destinazione turistica"},"content":{"rendered":"<p> \u00c8 \u00abTerre di Fasano\u00bb il nome scelto dai cittadini fasanesi per la destinazione turistica del territorio. Con 393 voti \u00e8 stato il brand pi\u00f9 votato. Al secondo posto \u00abFasano &#8211; Belvedere di Puglia\u00bb (305 voti) e al terzo \u00abFasano &#8211; The heart of Puglia\u00bb (224). Seguono: \u00abFasano &#8211; Le vie di Egnazia\u00bb (211), \u00abFasano &#8211; Dalla collina al mare\u00bb (196), \u00abFasano &#8211; Terre del Faso\u00bb (179), \u00abFasano &#8211; Colliammare\u00bb (165), \u00abFasano &#8211; MarEColli\u00bb (158), \u00abFasano &#8211; TerrEmozioni\u00bb (152), \u00abFasano &#8211; Terra mezz\u2019aria\u00bb (141).<br \/>\nIl nome designer\u00e0 la zona compresa tra Capitolo, Torre Canne e Selva di Fasano (nello specifico: Capitolo, Pezze di Greco, Pozzo Faceto, Savelletri, Montalbano, Fasano, Selva di Fasano, Laureto, Cocolicchio, Speziale, Canale di Pirro).<br \/>\nLa comunit\u00e0 \u00e8 stata chiamata a votare il brand pi\u00f9 rappresentativo lo scorso weekend in piazza Ciaia in una quatto giorni di eventi animata da talk dedicati ai temi della sostenibilit\u00e0 e della promozione legata al turismo. I cittadini hanno votato il nome nel Punto info posizionato in piazza Ciaia, su smartphone, inquadrando apposito QR code, e online, collegandosi ai link pubblicati sulle pagine Fb Citt\u00e0 di Fasano e Progetti Tpp.<br \/>\nL\u2019iniziativa si inserisce nell\u2019attivit\u00e0 di Place branding avviata da Teatro Pubblico Pugliese \u2013 Consorzio Regionale per le Arti e la Cultura, Comune di Fasano e Marconiweb Srl nell\u2019ambito del Progetto strategico dal titolo TAKE IT SLOW \u00abSmart and Slow Tourism Supporting Adriatic Heritage for Tomorrow\u00bb di cui, inoltre, Regione Puglia &#8211; Dipartimento Turismo, Economia della Cultura e Valorizzazione del Territorio \u00e8 partner Associato.<br \/>\nIl \u00abPlace branding\u00bb o brand turistico, identifica e trasmette un territorio, la sua offerta turistica, i suoi valori e allo stesso tempo posiziona l\u2019offerta in un segmento specifico del mercato cos\u00ec che la domanda da parte del turista sia soddisfatta e quindi possa convertire il suo interesse nella fruizione e nella visita al territorio.<br \/>\nDopo la ricerca di mercato svolta da Marconiweb Srl (agenzia che ha vinto il bando del Tpp) e sviluppata, da una parte, sull\u2019analisi dei dati turistici con accesso ai database regionali e, dall\u2019altra, sui questionari sottoposti a turisti e stakeholder del territorio, alla comunit\u00e0 \u00e8 toccata la scelta finale.<br \/>\n\u00abTerre di Fasano ci trasmette un senso di inclusivit\u00e0 e di pluralit\u00e0 \u2013 dice l\u2019assessore al Turismo Pier Francesco Palmariggi \u2013. Il nostro sviluppo turistico passa soprattutto attraverso le peculiarit\u00e0 di ogni singola porzione di territorio, dalla collina al mare. \u00c8 un messaggio identitario forte e incoraggiante, ampio e globale. Come il metodo che vogliamo utilizzare per promuovere e raccontare Fasano. Allargare i confini della partecipazione \u00e8 sempre la strada pi\u00f9 complicata, ma alla fine d\u00e0 sempre le soddisfazioni migliori. Grazie ai tanti cittadini che stanno supportando questo percorso e che hanno dato il loro prezioso contributo\u00bb.<br \/>\n\u00abIl progetto ha consentito di aggiungere un altro importante tassello alle attivit\u00e0 di promozione della Puglia come destinazione di un turismo lento e realmente sostenibile \u2013 dice Anna Introna, responsabile del coordinamento dei progetti CTE &#8211; Dipartimento Turismo, Economia della Cultura e Valorizzazione Territoriale, Regione Puglia \u2013. Take it slow ha previsto ancora una volta un approccio di lavoro bottom up, una modalit\u00e0 di sicuro pi\u00f9 \u201cslow\u201d perch\u00e9 basata sull\u2019ascolto e il confronto, ma che, siamo convinti, sia l\u2019unica in grado di garantire un\u2019offerta turistica vincente, focalizzata sulle identit\u00e0 dei luoghi, che valorizza le competenze e la visione delle comunit\u00e0 locali e dei numerosi stakeholders strategici, sia pubblici che privati\u00bb.<br \/>\n\u00abOttimo risultato questo del Place branding di Fasano \u2013 dice Lino Manosperta, responsabile ufficio Progetti del Teatro pubblico pugliese \u2013. Una iniziativa fortemente voluta dai 37 componenti la \u201cLocal Community of Practice\u201d (LCP) del progetto per migliorare la promozione del territorio concentrandosi sulla sua riconoscibilit\u00e0\u00bb.<br \/>\n\u00abIl marchio d\u2019area Terre di Fasano rappresenta un importante strumento di promozione territoriale che consentir\u00e0, sfruttando le sinergie dei diversi attori del territorio, di indirizzare le migliori strategie pianificandole in modo efficace \u2013 dice Alfredo Bortone per Marconiweb srl \u2013. Oggi, con l\u2019individuazione del nome si \u00e8 aggiunto un tassello importante, un punto di partenza, per la realizzazione del marchio identitario dell\u2019area compresa tra Selva di Fasano, Capitolo e Torre Canne\u00bb.<\/p>\n<p>\u00abIl processo partecipato di Take It Slow \u00e8 stato condiviso con gli stakeholder che compongono la Consulta del Turismo, durante la prima seduta \u2013 spiega Valerio Palasciano, coordinatore della Consulta \u2013. Tutti i prossimi step di progetto seguiranno la stessa ottica, uniti agli altri temi oggetto di dibattito, con l\u2019obiettivo di creare una strategia di destinazione coerente e condivisa che metta in rete comunit\u00e0 e prodotto turistico\u00bb.<\/p>\n<p>I prossimi step del progetto prevedono: elaborazione grafica del nome, promozione su riviste di settore, perfezionamento grafico dei sette itinerari con schema \u00aba margherita\u00bb.<br \/>\nInoltre la Local community sar\u00e0 dotata di mountain bike elettriche di cui una parte saranno anche per disabili.<br \/>\nSar\u00e0 realizzato un portale per la promozione e gestione degli itinerari e dei servizi connessi e creata una rete di imprese eco-certificate tra quelle aderenti alla LCP per garantire la sostenibilit\u00e0 futura dei risultati del progetto.<br \/>\nTra gli obiettivi c\u2019\u00e8 anche quello di realizzare prodotti artigianali rappresentativi del territorio da usare per il merchandising e l\u2019organizzazione di un press tour con la partecipazione di stakeholders e operatori turistici internazionali per promuovere questo territorio.<\/p>\n<p>\u00abTake It slow \u00e8 un progetto, o meglio un&#8217;esperienza, con un inizio e una fine burocratici ben precisi \u2013 dice Marialucrezia Colucci, Local Community \u2013, ma che pu\u00f2 avere l&#8217;ambizione di mettere le basi per qualcosa di molto concreto e duraturo. C&#8217;\u00e8 una local community of practice, di circa 30 soggetti tra enti di formazione del turismo, imprese e associazioni, di cui Serapia \u00e8 coordinatore, che si confronta, si riunisce, progetta per migliorare le performance sul turismo lento ed esperienziale di questa microdestinazione individuata a livello regionale che \u00e8 Capitolo &#8211; Parco dune costiere- Selva di Fasano. Un &#8220;esercizio&#8221;, una voglia di mettersi in gioco insieme, che se dar\u00e0 buoni frutti, potr\u00e0 diventare una buona pratica e soprattutto potr\u00e0 dare vero valore aggiunto a questo territorio cos\u00ec unico quanto complesso\u00bb.<\/p>\n<p>Il Progetto Take It Slow, a costo zero per il Comune di Fasano, finanziato interamente dal Programma di Cooperazione Transfrontaliera Interreg V-A Italy-Croatia 2014-2020, di cui il Teatro Pubblico Pugliese \u00e8 Partner, insieme a  Regione Puglia &#8211; Dipartimento Turismo, Economia della Cultura e Valorizzazione del Territorio (Partner Associato), altre 6 Regioni italiane e 5 Partner Croati, nasce con l\u2019obiettivo di ideare e mettere in pratica politiche, prodotti e servizi innovativi di turismo sostenibile basati sul patrimonio naturale e culturale della zona Capitolo-Torre Canne-Selva di Fasano. Un progetto con approccio dal basso, realizzato in collaborazione con una \u201cLocal Community of Practice\u201d (LCP), una comunit\u00e0 locale di pratica, formata da ben 37 soggetti tra imprese, associazioni, comunit\u00e0 scientifica, attivi nel territorio su indicato e coordinati da Coop. Serapia. <\/p>\n<p>Grazie alla cooperazione transfrontaliera, il progetto Take it Slow vuole promuovere e incentivare l\u2019offerta turistica sostenibile, in una sfida comune che unisce azioni strategiche complesse e la creazione di una nuova sensibilit\u00e0, pi\u00f9 inclusiva e consapevole, per soddisfare i bisogni dei viaggiatori e dei territori ospitanti. Tanto lungo gli splendidi litorali italiani e croati dell\u2019Adriatico, quanto nelle aree interne, ogni partner \u00e8 impegnato con iniziative finalizzate a soddisfare le esigenze del proprio territorio, in accordo con gli obiettivi strategici comuni.<\/p>\n<p>Ufficio Stampa<br \/>\nCitt\u00e0 di Fasano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 \u00abTerre di Fasano\u00bb il nome scelto dai cittadini fasanesi per la destinazione turistica del territorio. Con 393 voti \u00e8 stato il brand pi\u00f9 votato. Al secondo posto \u00abFasano &#8211; Belvedere di Puglia\u00bb (305 voti) e al terzo \u00abFasano &#8211; The heart of Puglia\u00bb (224). Seguono: \u00abFasano &#8211; Le vie di Egnazia\u00bb (211), \u00abFasano &#8211; Dalla collina al mare\u00bb (196), \u00abFasano &#8211; Terre del Faso\u00bb (179), \u00abFasano &#8211; Colliammare\u00bb (165), \u00abFasano &#8211; MarEColli\u00bb (158), \u00abFasano &#8211; TerrEmozioni\u00bb (152), \u00abFasano &#8211; Terra mezz\u2019aria\u00bb (141). Il nome designer\u00e0 la zona compresa tra Capitolo, Torre Canne e Selva di Fasano (nello specifico: Capitolo, Pezze di Greco, Pozzo Faceto, Savelletri, Montalbano, Fasano, Selva di Fasano, Laureto, Cocolicchio, Speziale, Canale di Pirro). La comunit\u00e0 \u00e8 stata chiamata a votare il brand pi\u00f9 rappresentativo lo scorso weekend in piazza Ciaia in una quatto giorni di eventi animata da talk dedicati ai temi della sostenibilit\u00e0 e della promozione legata al turismo. I cittadini hanno votato il nome nel Punto info posizionato in piazza Ciaia, su smartphone, inquadrando&#8230;<\/p>\n","protected":false},"author":2,"featured_media":201007,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-201006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=201006"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201006\/revisions"}],"predecessor-version":[{"id":201008,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201006\/revisions\/201008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/201007"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=201006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=201006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=201006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}