{"id":201037,"date":"2022-04-16T11:43:17","date_gmt":"2022-04-16T09:43:17","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=201037"},"modified":"2022-04-16T17:43:59","modified_gmt":"2022-04-16T15:43:59","slug":"taurino-confimpreseitalia-rossi-e-melucci-sono-fuori-dal-mondo-e-negano-al-territorio-occasioni-occupazionali-concrete","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/taurino-confimpreseitalia-rossi-e-melucci-sono-fuori-dal-mondo-e-negano-al-territorio-occasioni-occupazionali-concrete\/","title":{"rendered":"Taurino (ConfImpreseItalia): &#8220;Rossi e Melucci sono fuori dal mondo e negano al territorio occasioni occupazionali concrete&#8221;"},"content":{"rendered":"<p>Siamo diventanti lo zimbello d\u2019Italia e d\u2019Europa. Sui giornali regionali e nazionali si muovono critiche aspre sulle posizioni assunte dai \u201cverdi\u201d Rossi e Melucci (non a caso entrambi orbitanti presso il 100esimo posto nella classifica dei sindaci stilata da IlSole24Ore), che continuano ad opporsi agli investimenti legati al gas (depositi gnl e rigassificatori) mentre la Germania stanzia 3 miliardi di euro per acquistare terminali galleggianti. Rossi e Melucci sono fuori dal mondo e negano al territorio occasioni occupazionali concrete.<\/p>\n<p>Il governatore Emiliano ha accolto favorevolmente l\u2019assist del ministro Cingolani circa l\u2019ormeggio della nave di rigassificazione nei pressi dei porti di Brindisi o Taranto. Perfino il Pd locale lo ha capito e per bocca del segretario cittadino e del vicesindaco si dice favorevole al rigassificatore offshore. Il Pd regionale propone addirittura una mozione per spingere su tutti gli investimenti legati al gas: anche il deposito Edison tanto avversato dal Pd Brindisino.<\/p>\n<p>Altrove il PD fa i fatti. A Ravenna il sindaco (in quota Pd) da settimane si reca presso i ministeri quasi ad implorare il governo e Snam di scegliere Ravenna (che tra l\u2019altro ospita gi\u00e0 un deposito gnl di Edison). Contestualmente dichiara di volere anche l\u2019eolico offshore.<\/p>\n<p>Praticamente l\u2019idea del polo energetico lanciata da ConfimpreseItalia nelle scorse settimane. Rossi, invece, ne inventa una al giorno per bloccare gli investimenti su Brindisi: addirittura sostiene che l\u2019impianto di Falck e la nave di rigassificazione potrebbero entrare in conflitto. Come suo solito, lancia queste elucubrazioni propagandistiche senza spiegare tecnicamente la ratio delle sue affermazioni. Il sindaco, non contento, si lascia anche andare a commenti sullo scarso impatto occupazione del rigassificatore, giusto per il gusto di contraddire il presidente dell\u2019Autorit\u00e0 di sistema, il Prof. Ugo Patroni Griffi. Basti pensare a tutte le posizioni assunte dal Comune contro l\u2019ente portuale e il porto di Brindisi: tutte, e ripeto tutte, sconfessate dalla magistratura e dagli organi tecnici. \u00c8 ora di smetterla con la politica delle bugie, del rancore e delle \u00e9lite, perch\u00e9 questo \u00e8 quanto di pi\u00f9 tossico si possa respirare in citt\u00e0. Basta compiacere il proprio elettorato ed assecondare le proprie fisime ideologiche adolescenziali.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>\u00a0Paolo Taurino<\/strong><\/em><br \/>\n<em><strong>Coordinatore Puglia<\/strong><\/em><br \/>\n<em><strong>Presidente Brindisi Confimpreseitalia<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siamo diventanti lo zimbello d\u2019Italia e d\u2019Europa. Sui giornali regionali e nazionali si muovono critiche aspre sulle posizioni assunte dai \u201cverdi\u201d Rossi e Melucci (non a caso entrambi orbitanti presso il 100esimo posto nella classifica dei sindaci stilata da IlSole24Ore), che continuano ad opporsi agli investimenti legati al gas (depositi gnl e rigassificatori) mentre la Germania stanzia 3 miliardi di euro per acquistare terminali galleggianti. Rossi e Melucci sono fuori dal mondo e negano al territorio occasioni occupazionali concrete. Il governatore Emiliano ha accolto favorevolmente l\u2019assist del ministro Cingolani circa l\u2019ormeggio della nave di rigassificazione nei pressi dei porti di Brindisi o Taranto. Perfino il Pd locale lo ha capito e per bocca del segretario cittadino e del vicesindaco si dice favorevole al rigassificatore offshore. Il Pd regionale propone addirittura una mozione per spingere su tutti gli investimenti legati al gas: anche il deposito Edison tanto avversato dal Pd Brindisino. Altrove il PD fa i fatti. A Ravenna il sindaco (in quota Pd) da settimane si reca presso i ministeri&#8230;<\/p>\n","protected":false},"author":2,"featured_media":199131,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-201037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=201037"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201037\/revisions"}],"predecessor-version":[{"id":201039,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201037\/revisions\/201039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/199131"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=201037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=201037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=201037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}