{"id":201385,"date":"2022-04-27T17:52:35","date_gmt":"2022-04-27T15:52:35","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=201385"},"modified":"2022-04-27T19:56:27","modified_gmt":"2022-04-27T17:56:27","slug":"santelia-a-brindisi-il-primo-palio-urbano-ditalia-dedicato-ad-un-santo-che-non-esiste","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/santelia-a-brindisi-il-primo-palio-urbano-ditalia-dedicato-ad-un-santo-che-non-esiste\/","title":{"rendered":"Sant&#8217;Elia: a Brindisi il primo Palio Urbano d\u2019Italia dedicato ad un Santo che non esiste"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-201388\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/04\/SantElia-176x300.jpg\" alt=\"\" width=\"176\" height=\"300\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/04\/SantElia-176x300.jpg 176w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/04\/SantElia-602x1024.jpg 602w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/04\/SantElia-768x1306.jpg 768w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/04\/SantElia-904x1536.jpg 904w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/04\/SantElia-1205x2048.jpg 1205w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/04\/SantElia-scaled.jpg 1506w\" sizes=\"auto, (max-width: 176px) 100vw, 176px\" \/><br \/>\nSant\u2019Elia, un quartiere periferico tra i pi\u00f9 popolosi delle realt\u00e0 del Sud Italia, Brindisi, una citt\u00e0 di mare complicata e allo stesso tempo bellissima, insieme sono cuore e anima del Primo Palio Urbano d\u2019Italia. Nasce in Puglia il progetto di rigenerazione urbana e sociale \u201cCeloCeloManca \u2013 L\u2019album dei desideri di Sant\u2019Elia\u201d, vincitore della terza edizione di \u201cCreative Living Lab\u201d, avviso pubblico promosso dalla Direzione Generale Creativit\u00e0 Contemporanea del Ministero della Cultura realizzato dal collettivo ImmaginAbile in collaborazione con Comune di Brindisi, Arca Nord Salento, la cooperativa di comunit\u00e0 Legami di Comunit\u00e0 \u2013 Brindisi e Pazlab.<\/p>\n<p>&nbsp;<\/p>\n<p>Sabato 30 aprile 2022, alle ore 18, il Parco Buscicchio di Brindisi ospiter\u00e0 la presentazione ufficiale del progetto di rigenerazione urbana e sociale partecipata. Si tratta di un lavoro corale coordinato e promosso dal collettivo ImmaginAbile che vede la collaborazione di numerose associazioni, partner ed Enti pubblici tra i quali il Comune di Brindisi e Arca Nord Salento. L\u2019idea del progetto \u00e8 nata a partire da un\u2019esperienza di comunit\u00e0 lanciata da qualche anno da Legami di Comunit\u00e0, cooperativa che gestisce il parco pubblico nel cuore del quartiere Sant\u2019Elia (Parco Buscicchio) e dalle pratiche di innovazione sociale messe in campo da ImmaginAbile che fa dell\u2019arte pubblica e urbana una leva di crescita e di contrasto alle devianze. Le attivit\u00e0 di animazione culturale coinvolgono i cittadini, soprattutto i pi\u00f9 giovani, e con il progetto \u201cCeloCeloManca\u201d si armonizzano in un percorso che ha l\u2019obiettivo di valorizzare il senso di appartenenza di chi vive questa area lontana dal centro fino a lanciare una vera e propria sfida: realizzare il \u201cprimo palio urbano d\u2019Italia\u201d, peraltro dedicato a un santo che non esiste. Il Palio di Sant\u2019Elia, che avr\u00e0 luogo a giugno 2022, rappresenta un momento di riflessione sul quartiere e con il quartiere, un percorso di co-creazione e co-progettazione che vedr\u00e0 i residenti, i professionisti, le scuole, le parrocchie, le associazioni, fianco a fianco nell\u2019immaginare un nuovo modo di stare insieme e prendersi cura gli uni degli altri, un nuovo format di progettazione partecipata che si concretizzer\u00e0 in una settimana di giochi, sport, arti visive, artigianato e cucina tradizionale con al centro la comunit\u00e0.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-201387 alignright\" src=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/04\/Quartiere-2-300x135.jpg\" alt=\"\" width=\"300\" height=\"135\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/04\/Quartiere-2-300x135.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/04\/Quartiere-2-1024x461.jpg 1024w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/04\/Quartiere-2-768x346.jpg 768w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/04\/Quartiere-2-1536x691.jpg 1536w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2022\/04\/Quartiere-2.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u201cSiamo partiti dal nome del quartiere oggetto dell\u2019intervento di rigenerazione: Sant\u2019Elia. Abbiamo giocato sul fatto che in realt\u00e0 quest\u2019area della citt\u00e0 prende il nome dall\u2019architetto futurista Antonio Sant\u2019Elia cui gli urbanisti dell\u2019epoca, in cui il quartiere \u00e8 nato, hanno voluto rendere omaggio e ispirarsi, cosa di cui molti abitanti non sono a conoscenza. Nessun Santo quindi ha realmente ispirato la nascita e l\u2019intitolazione del quartiere, ma abbiamo pensato che potesse essere un\u2019operazione d\u2019impatto inventarci la presenza di un Santo che non esiste e creare intorno alla sua figura, un senso di devozione e di comunit\u00e0 legati ai valori che lui incarna.\u201d, spiegano i promotori. Da qualche settimana infatti \u00e8 gi\u00e0 iniziata l\u2019azione di storytelling social per la definizione puntuale del profilo di questa figura che in realt\u00e0 non \u00e8 salvifica ma ispiratrice. \u201cSant\u2019Elia infatti \u00e8 del quartiere ma ha girato il mondo, \u00e8 buono ma non \u00e8 stupido, \u00e8 tatuato, \u00e8 ospitale ma ama farsi ospitare, dice le cose come stanno ma la sua caratteristica principale \u00e8 che non fa miracoli ma \u00e8 in grado di fare in modo che accadano\u201d, aggiungono gli ideatori del progetto. Da queste premesse il racconto si sta sviluppando attraverso le storie di chi vive il quartiere, i cittadini stanno entrando in contatto e in confidenza con il Santo che nel frattempo parla attraverso i suoi personali canali social e lo fa in prima persona, interagendo con i curiosi e spiegando ai \u201cdevoti\u201d che, come diceva Madre Teresa di Calcutta, per cambiare le cose siamo tutti chiamati ad essere un po\u2019 Santi.<\/p>\n<p>Il programma dell\u2019iniziativa di sabato 30 aprile, si aprir\u00e0 alle ore 17 con giochi e laboratori per i pi\u00f9 piccoli a cura degli operatori e dei volontari di Legami di Comunit\u00e0 \u2013 Brindisi.<\/p>\n<p>Alle ore 18, avr\u00e0 luogo la conferenza stampa alla presenza dei rappresentanti istituzionali e dei partner di progetto.<br \/>\nAlle ore 19, dj set e apertura delle iscrizioni al Palio che si svolger\u00e0 a giugno 2022.<\/p>\n<p>&nbsp;<\/p>\n<p>Per seguire il Santo, e il progetto, questi sono i canali social a cui fare riferimento:<br \/>\nFacebook https:\/\/www.facebook.com\/santeliadabrindisi<br \/>\nInstagram https:\/\/www.instagram.com\/santelia_brindisi\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sant\u2019Elia, un quartiere periferico tra i pi\u00f9 popolosi delle realt\u00e0 del Sud Italia, Brindisi, una citt\u00e0 di mare complicata e allo stesso tempo bellissima, insieme sono cuore e anima del Primo Palio Urbano d\u2019Italia. Nasce in Puglia il progetto di rigenerazione urbana e sociale \u201cCeloCeloManca \u2013 L\u2019album dei desideri di Sant\u2019Elia\u201d, vincitore della terza edizione di \u201cCreative Living Lab\u201d, avviso pubblico promosso dalla Direzione Generale Creativit\u00e0 Contemporanea del Ministero della Cultura realizzato dal collettivo ImmaginAbile in collaborazione con Comune di Brindisi, Arca Nord Salento, la cooperativa di comunit\u00e0 Legami di Comunit\u00e0 \u2013 Brindisi e Pazlab. &nbsp; Sabato 30 aprile 2022, alle ore 18, il Parco Buscicchio di Brindisi ospiter\u00e0 la presentazione ufficiale del progetto di rigenerazione urbana e sociale partecipata. Si tratta di un lavoro corale coordinato e promosso dal collettivo ImmaginAbile che vede la collaborazione di numerose associazioni, partner ed Enti pubblici tra i quali il Comune di Brindisi e Arca Nord Salento. L\u2019idea del progetto \u00e8 nata a partire da un\u2019esperienza di comunit\u00e0 lanciata da qualche anno da&#8230;<\/p>\n","protected":false},"author":2,"featured_media":201386,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-201385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=201385"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201385\/revisions"}],"predecessor-version":[{"id":201389,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201385\/revisions\/201389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/201386"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=201385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=201385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=201385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}