{"id":201694,"date":"2022-05-05T15:15:37","date_gmt":"2022-05-05T13:15:37","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=201694"},"modified":"2022-05-09T15:27:52","modified_gmt":"2022-05-09T13:27:52","slug":"in-edicola-il-nuovo-numero-di-aprile-di-trezerocinque","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/in-edicola-il-nuovo-numero-di-aprile-di-trezerocinque\/","title":{"rendered":"In edicola il nuovo numero di aprile di Trezerocinque"},"content":{"rendered":"<p>Il mensile di basket diretto da Mino Taveri giunge alla vigilia delle ultime due giornate di campionato e all\u2019indomani della aritmetica salvezza raggiunta dalla New Basket Brindisi. Il torneo attende ora, negli ultimi 40\u2019, di conoscere piazzamenti e incroci per i playoff tricolore.<\/p>\n<p>\u201cUna Final Eight conquistata anche quest\u2019anno e soprattutto la certezza di giocare la prossima stagione nuovamente in Lega A devono considerarsi per Brindisi traguardi di prestigio e non semplici ripieghi o magre consolazioni \u2013 dichiara il direttore di Trezerocinque. Spesso le stagioni, in ogni sport, nascono sotto certi auspici e poi prendono binari differenti. Ma dal presidente Marino all\u2019ultimo dei componenti della societ\u00e0 brindisina, tutti hanno sempre lavorato sodo, con tanto entusiasmo e soprattutto con molti sacrifici, il che deve essere comunque sempre motivo d\u2019orgoglio. I risultati non sempre sono quelli sperati, ma la certezza di aver fatto il massimo \u00e8 comunque un grosso traguardo\u201d<\/p>\n<p>All\u2019interno del numero di aprile il magazine ospita le parole di Matteo Spagnolo, uno dei maggiori talenti della pallacanestro italiana, pronto ad affrontare ogni tipo di palcoscenico. Un gran motivo d\u2019orgoglio per la citt\u00e0 di Brindisi che ha prodotto, dai primi tiri su un campetto di periferia, un giocatore che potrebbe raggiungere traguardi di assoluto livello.<\/p>\n<p>\u201cAuguriamo a Matteo ogni fortuna \u2013 aggiunge Mino Taveri \u2013 la sua eleggibilit\u00e0 per essere scelto in NBA \u00e8 qualcosa da far girar la testa a chiunque, ma il giovane talento brindisino ha tutti le qualit\u00e0 per reggere qualsiasi tipo di pressione.\u201d<\/p>\n<p>In questo numero spazio alle parole di uno dei coach rivelazione del campionato, Marco Ramondino, timoniere della sorprendente Tortona, e a quelle di Sandro Santoro, che dopo l\u2019esperienza di Brescia riparte professionalmente da una delle societ\u00e0 storiche della pallacanestro italiana.<\/p>\n<p>Oltre ovviamente alle consuete rubriche di approfondimento tecnico tattico.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il mensile di basket diretto da Mino Taveri giunge alla vigilia delle ultime due giornate di campionato e all\u2019indomani della aritmetica salvezza raggiunta dalla New Basket Brindisi. Il torneo attende ora, negli ultimi 40\u2019, di conoscere piazzamenti e incroci per i playoff tricolore. \u201cUna Final Eight conquistata anche quest\u2019anno e soprattutto la certezza di giocare la prossima stagione nuovamente in Lega A devono considerarsi per Brindisi traguardi di prestigio e non semplici ripieghi o magre consolazioni \u2013 dichiara il direttore di Trezerocinque. Spesso le stagioni, in ogni sport, nascono sotto certi auspici e poi prendono binari differenti. Ma dal presidente Marino all\u2019ultimo dei componenti della societ\u00e0 brindisina, tutti hanno sempre lavorato sodo, con tanto entusiasmo e soprattutto con molti sacrifici, il che deve essere comunque sempre motivo d\u2019orgoglio. I risultati non sempre sono quelli sperati, ma la certezza di aver fatto il massimo \u00e8 comunque un grosso traguardo\u201d All\u2019interno del numero di aprile il magazine ospita le parole di Matteo Spagnolo, uno dei maggiori talenti della pallacanestro italiana, pronto ad&#8230;<\/p>\n","protected":false},"author":2,"featured_media":201695,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-201694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=201694"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201694\/revisions"}],"predecessor-version":[{"id":201697,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201694\/revisions\/201697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/201695"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=201694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=201694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=201694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}