{"id":201914,"date":"2022-05-14T20:23:20","date_gmt":"2022-05-14T18:23:20","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=201914"},"modified":"2022-05-23T06:40:14","modified_gmt":"2022-05-23T04:40:14","slug":"arpal-puglia-ambito-territoriale-di-brindisi-528-figure-professionali-ricercate-in-vari-settori","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/arpal-puglia-ambito-territoriale-di-brindisi-528-figure-professionali-ricercate-in-vari-settori\/","title":{"rendered":"ARPAL Puglia, Ambito territoriale di Brindisi: 528 figure professionali ricercate in vari settori"},"content":{"rendered":"<p>I Centri Per l\u2019Impiego (d\u2019ora in poi CPI) sono ad oggi i principali erogatori di servizi di politiche attive del lavoro. La provincia di Brindisi ne conta al momento 3 (Brindisi, Ostuni e Francavilla Fontana), con prossima riapertura del CPI di Mesagne. Tutti, in un\u2019ottica di rilancio, sono impegnati nel inserimento\/reinserimento dell\u2019utente all\u2019interno del mercato del lavoro attraverso azioni di orientamento e formazione finalizzate a favorire l\u2019incontro tra domanda e offerta.<br \/>\n\u00abI centri per l\u2019impiego hanno assunto una nuova veste, pi\u00f9 moderna e funzionale\u00bb, dichiara la Dott.ssa Anna Loparco, responsabile unica dei CPI dell\u2019ambito territoriale di Brindisi, \u00abIl match domanda\/offerta di lavoro si realizza attraverso un incontro diretto tra soggetti in cerca di occupazione e aziende in cerca di personale. Stiamo puntando molto sul rilancio dell\u2019utilizzo dei nostri portali istituzionali Sintesi Brindisi, quale portale provinciale, e Lavoro per Te, quale portale regionale. Le Aziende che ricercano personale, contrariamente a quanto si pensi, sono davvero molte; ogni giorno gli operatori pubblicano nuove offerte, consultabili sui nostri portali. Al momento \u2013 continua Loparco &#8211; sono ben 528 le figure professionali ricercate sul nostro territorio, nel settore sociale, alberghiero, tessile, immobiliare, dell\u2019edilizia, della ristorazione, del turismo, del commercio, dell\u2019industria e tanto altro. Chiunque fosse interessato, pu\u00f2 candidarsi in piena autonomia, inserendo il proprio CV ed altre informazioni relative alle proprie competenze e conoscenze\u00bb.<br \/>\nDa poco \u00e8 disponibile anche l\u2019 App gratuita di Lavoro per te, tramite la quale \u00e8 possibile ricercare le job vacancies (offerte di lavoro) attualmente disponibili nel territorio regionale. L\u2019app \u00e8 molto intuitiva, tramite un semplice clic ci si pu\u00f2 auto-candidare e ottenere un colloquio con le aziende<br \/>\nPer pubblicare le proprie offerte di lavoro o per rispondere agli annunci, aziende e cittadini possono anche rivolgersi direttamente ai CPI dell\u2019Ambito di Brindisi, aperti al pubblico tutti i giorni (dal luned\u00ec al venerd\u00ec dalle 8.30 alle 11.30 e il marted\u00ec anche dalle 15 alle 16.30) presso le sedi dislocate a Brindisi, Ostuni, Francavilla Fontana e presso l\u2019Ufficio collocamento mirato disabili a Brindisi, oppure tramite email ai seguenti indirizzi: cpi.brindisi@regione.puglia.it, cpi.ostuni@regione.puglia.it, cpi.francavilla@regione.puglia.it, coordinamento.brindisi@regione.puglia.it o consultando il sito internet www.arpal.regione.puglia.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Centri Per l\u2019Impiego (d\u2019ora in poi CPI) sono ad oggi i principali erogatori di servizi di politiche attive del lavoro. La provincia di Brindisi ne conta al momento 3 (Brindisi, Ostuni e Francavilla Fontana), con prossima riapertura del CPI di Mesagne. Tutti, in un\u2019ottica di rilancio, sono impegnati nel inserimento\/reinserimento dell\u2019utente all\u2019interno del mercato del lavoro attraverso azioni di orientamento e formazione finalizzate a favorire l\u2019incontro tra domanda e offerta. \u00abI centri per l\u2019impiego hanno assunto una nuova veste, pi\u00f9 moderna e funzionale\u00bb, dichiara la Dott.ssa Anna Loparco, responsabile unica dei CPI dell\u2019ambito territoriale di Brindisi, \u00abIl match domanda\/offerta di lavoro si realizza attraverso un incontro diretto tra soggetti in cerca di occupazione e aziende in cerca di personale. Stiamo puntando molto sul rilancio dell\u2019utilizzo dei nostri portali istituzionali Sintesi Brindisi, quale portale provinciale, e Lavoro per Te, quale portale regionale. Le Aziende che ricercano personale, contrariamente a quanto si pensi, sono davvero molte; ogni giorno gli operatori pubblicano nuove offerte, consultabili sui nostri portali. Al momento \u2013 continua&#8230;<\/p>\n","protected":false},"author":2,"featured_media":201917,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-201914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=201914"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201914\/revisions"}],"predecessor-version":[{"id":201918,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/201914\/revisions\/201918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/201917"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=201914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=201914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=201914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}