{"id":202089,"date":"2022-05-23T06:22:42","date_gmt":"2022-05-23T04:22:42","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=202089"},"modified":"2022-05-23T06:22:42","modified_gmt":"2022-05-23T04:22:42","slug":"la-dinamo-brindisi-vince-gara-1-della-finale-playoff-contro-monopoli-mercoledi-in-campo-per-gara-2","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/la-dinamo-brindisi-vince-gara-1-della-finale-playoff-contro-monopoli-mercoledi-in-campo-per-gara-2\/","title":{"rendered":"La Dinamo Brindisi vince gara 1 della finale playoff contro Monopoli.  Mercoled\u00ec in campo per gara 2"},"content":{"rendered":"<p>Limongelli Dinamo Basket Brindisi \u2013 AP Monopoli 80-66 (24-21, 42-38, 64-50, 80-66)<\/p>\n<p>Dinamo Brindisi: Greco 5, Staselis 18, Epifani, Pellecchia 11, Rollo 4, Pulli 9, Caloia 1, Labate 1, Leo 8, Martino 5, Scivales, Kibildis 23. All. Cristofaro<\/p>\n<p>Monopoli: Pennetta, Loprieno 3, Bruni 4, Manchisi 7, Lasorte 3, Lamanna 6, Rodriguez 20, Olocco 19, Brunetti 4, Vacca. All. Romano<\/p>\n<p>Arbitri: Di Vittorio di Ruvo di Puglia (BA) e Caposiena di San Severo (FG)<\/p>\n<p>Non si ferma il cammino della Limongelli Dinamo Basket Brindisi nei playoff del campionato di Serie C Silver: nel primo match della finale promozione, i ragazzi di coach Antonio Cristofaro hanno avuto la meglio sul Monopoli per 80-66.<\/p>\n<p>Cornice di pubblico magnifica per un campionato minors, grazie ad un PalaZumbo strabordante di tifosi ed appassionati che per 40 minuti hanno sostenuto incessantemente la squadra brindisina.<\/p>\n<p>Primo quarto di sostanziale equilibrio tra le due formazioni con la Dinamo che sfrutta le buone percentuali al tiro da oltre l\u2019arco mentre Monopoli, grazie ad una maggiore fisicit\u00e0 dei suoi lunghi, resta in scia \u2013 sul 24-21\u2013 sfruttando l\u2019ottima percentuale nei tiri liberi. Nel secondo quarto \u00e8 Darius Kibildis (23 punti per lui) a caricarsi l\u2019attacco brindisino sulle spalle, mentre gli ospiti si affidano al duo straniero Rodriguez-Olocco per chiudere il primo tempo sotto solo di 4 lunghezze sul 42-38.<br \/>\nAl rientro dagli spogliatoi, la Limongelli traccia il solco sul match: grazie ad una straordinaria difesa e ai canestri di Staselis e compagni, i padroni di casa volano sul 64-50 a 10 minuti dal termine. Ultimo parziale dove la Dinamo tocca anche il + 20 (73-53), prima del tentativo di rientro degli ospiti ancora con Rodriguez, ma le due triple in fila di Leo e Pellecchia fanno calare il sipario sul match, con squadra e tifosi festanti per l\u201980-66 finale.<\/p>\n<p>Staff e giocatori da luned\u00ec torneranno in palestra per preparare al meglio la gara che pu\u00f2 valere una stagione: mercoled\u00ec 25 maggio alle ore 20:30 si disputer\u00e0 gara 2 sul parquet della tendostruttura di Via Pesce a Monopoli, in una serie al meglio dei 3 incontri.<br \/>\nTanti saranno i tifosi brindisini in trasferta per sostenere la squadra dopo questa grande annata: per chi non potr\u00e0 seguire la squadra fuori casa, la gara sar\u00e0 trasmessa in live streaming a partire dalle 20:25 sulla pagina www.facebook.com\/dinamobrindisi.<\/p>\n<p>&nbsp;<\/p>\n<p>Ufficio Comunicazione &#8211; Limongelli Dinamo Basket Brindisi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Limongelli Dinamo Basket Brindisi \u2013 AP Monopoli 80-66 (24-21, 42-38, 64-50, 80-66) Dinamo Brindisi: Greco 5, Staselis 18, Epifani, Pellecchia 11, Rollo 4, Pulli 9, Caloia 1, Labate 1, Leo 8, Martino 5, Scivales, Kibildis 23. All. Cristofaro Monopoli: Pennetta, Loprieno 3, Bruni 4, Manchisi 7, Lasorte 3, Lamanna 6, Rodriguez 20, Olocco 19, Brunetti 4, Vacca. All. Romano Arbitri: Di Vittorio di Ruvo di Puglia (BA) e Caposiena di San Severo (FG) Non si ferma il cammino della Limongelli Dinamo Basket Brindisi nei playoff del campionato di Serie C Silver: nel primo match della finale promozione, i ragazzi di coach Antonio Cristofaro hanno avuto la meglio sul Monopoli per 80-66. Cornice di pubblico magnifica per un campionato minors, grazie ad un PalaZumbo strabordante di tifosi ed appassionati che per 40 minuti hanno sostenuto incessantemente la squadra brindisina. Primo quarto di sostanziale equilibrio tra le due formazioni con la Dinamo che sfrutta le buone percentuali al tiro da oltre l\u2019arco mentre Monopoli, grazie ad una maggiore fisicit\u00e0 dei suoi lunghi,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":202099,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-202089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/202089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=202089"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/202089\/revisions"}],"predecessor-version":[{"id":202100,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/202089\/revisions\/202100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/202099"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=202089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=202089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=202089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}