{"id":202111,"date":"2022-05-23T16:36:37","date_gmt":"2022-05-23T14:36:37","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=202111"},"modified":"2022-05-23T17:42:42","modified_gmt":"2022-05-23T15:42:42","slug":"riabilitazione-creditizia-confesercenti-brindisi-sigla-accordo-con-crc-milano","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/riabilitazione-creditizia-confesercenti-brindisi-sigla-accordo-con-crc-milano\/","title":{"rendered":"Riabilitazione creditizia: Confesercenti Brindisi sigla accordo con CRC Milano"},"content":{"rendered":"<p>Si \u00e8 tenuta gioved\u00ec 19 maggio c.a. la conferenza stampa organizzata dalla Confesercenti di Brindisi, per presentare l\u2019accordo stretto con CRC Milano S.r.l. (www.centroriabilitazionicreditizie.com) finalizzato ad ampliare il caleidoscopio di opportunit\u00e0 messe a disposizione dei propri soci.<\/p>\n<p>Consapevoli del fatto che la crisi possa diventare pi\u00f9 dura per quelle imprese che, non essendo riuscite a mantenersi in regola col pagamento di un finanziamento, sono finite nelle black list dei \u201ccattivi pagatori\u201d di tutti gli istituti di credito, l\u2019Associazione si \u00e8 rivolta ad una delle aziende leader nel settore della riabilitazione creditizia per offrire sostegno legale, ad un prezzo riservato, ai propri soci.<\/p>\n<p>Alla conferenza, in occasione della quale si \u00e8 formalizzata la convenzione fra l\u2019Associazione e la Societ\u00e0, erano presenti il presidente provinciale Confesercenti Michele Piccirillo, il Direttore Angelo Colella e il Dott. Rino Nimis, fondatore e Presidente di CRC Milano s.r.l., unitamente ad altri componenti della giunta Confesercenti.<\/p>\n<p>Siglando l\u2019accordo in oggetto, Confesercenti si \u00e8 prefissata l\u2019obbiettivo di favorire le imprese associate ed i loro familiari, dipendenti e collaboratori diretti nel difficile processo di riabilitazione creditizia garantendo loro, ove ne ricorrano gli estremi, la possibilit\u00e0 di una nuova opportunit\u00e0 per rimettersi in gioco, grazie al sostegno offerto da professionisti esperti altamente qualificati e accreditati presso le maggiori Associazioni di categoria (Confidustria, Conflavoro) etc.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><br \/>\nCOMUNICATO STAMPA CONFESERCENTI PROVINCIA DI BRINDISI<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 tenuta gioved\u00ec 19 maggio c.a. la conferenza stampa organizzata dalla Confesercenti di Brindisi, per presentare l\u2019accordo stretto con CRC Milano S.r.l. (www.centroriabilitazionicreditizie.com) finalizzato ad ampliare il caleidoscopio di opportunit\u00e0 messe a disposizione dei propri soci. Consapevoli del fatto che la crisi possa diventare pi\u00f9 dura per quelle imprese che, non essendo riuscite a mantenersi in regola col pagamento di un finanziamento, sono finite nelle black list dei \u201ccattivi pagatori\u201d di tutti gli istituti di credito, l\u2019Associazione si \u00e8 rivolta ad una delle aziende leader nel settore della riabilitazione creditizia per offrire sostegno legale, ad un prezzo riservato, ai propri soci. Alla conferenza, in occasione della quale si \u00e8 formalizzata la convenzione fra l\u2019Associazione e la Societ\u00e0, erano presenti il presidente provinciale Confesercenti Michele Piccirillo, il Direttore Angelo Colella e il Dott. Rino Nimis, fondatore e Presidente di CRC Milano s.r.l., unitamente ad altri componenti della giunta Confesercenti. Siglando l\u2019accordo in oggetto, Confesercenti si \u00e8 prefissata l\u2019obbiettivo di favorire le imprese associate ed i loro familiari, dipendenti e collaboratori&#8230;<\/p>\n","protected":false},"author":2,"featured_media":202116,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-202111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/202111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=202111"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/202111\/revisions"}],"predecessor-version":[{"id":202117,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/202111\/revisions\/202117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/202116"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=202111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=202111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=202111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}