{"id":202257,"date":"2022-06-09T15:49:06","date_gmt":"2022-06-09T13:49:06","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=202257"},"modified":"2022-06-09T15:49:06","modified_gmt":"2022-06-09T13:49:06","slug":"servizi-sociali-sbloccata-la-vertenza-stipendi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/servizi-sociali-sbloccata-la-vertenza-stipendi\/","title":{"rendered":"Servizi Sociali: sbloccata la vertenza stipendi"},"content":{"rendered":"<p>&#8220;In merito alla problematica degli asili nido siamo felici di comunicare che, grazie al lavoro sinergico svolto tra la Cooperativa Gialla, nella persona del suo presidente, l&#8217;apparato burocratico del Comune di Brindisi e la banca fiduciaria della predetta cooperativa, si \u00e8 raggiunto l&#8217;accordo sulla procedura da utilizzare, a garanzia di tutti, per l&#8217;anticipazione delle fatture, che saranno prontamente pagate dal Comune di Brindisi ad approvazione del bilancio di previsione.<\/p>\n<p>Cos\u00ec sar\u00e0 possibile garantire l&#8217;immediato pagamento delle spettanze a tutti gli operatori del servizio. Contiamo che tutti riceveranno il dovuto entro luned\u00ec 13 giugno\u201d, lo dichiara l\u2019assessore ai Servizi sociali Isabella Lettori.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;In merito alla problematica degli asili nido siamo felici di comunicare che, grazie al lavoro sinergico svolto tra la Cooperativa Gialla, nella persona del suo presidente, l&#8217;apparato burocratico del Comune di Brindisi e la banca fiduciaria della predetta cooperativa, si \u00e8 raggiunto l&#8217;accordo sulla procedura da utilizzare, a garanzia di tutti, per l&#8217;anticipazione delle fatture, che saranno prontamente pagate dal Comune di Brindisi ad approvazione del bilancio di previsione. Cos\u00ec sar\u00e0 possibile garantire l&#8217;immediato pagamento delle spettanze a tutti gli operatori del servizio. Contiamo che tutti riceveranno il dovuto entro luned\u00ec 13 giugno\u201d, lo dichiara l\u2019assessore ai Servizi sociali Isabella Lettori.<\/p>\n","protected":false},"author":2,"featured_media":196038,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-202257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/202257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=202257"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/202257\/revisions"}],"predecessor-version":[{"id":202259,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/202257\/revisions\/202259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/196038"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=202257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=202257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=202257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}