{"id":202591,"date":"2022-06-16T10:23:11","date_gmt":"2022-06-16T08:23:11","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=202591"},"modified":"2022-06-20T10:27:19","modified_gmt":"2022-06-20T08:27:19","slug":"san-pietro-il-campo-democratico-si-organizza-per-essere-alternativo-alla-maggioranza-rizzo","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/san-pietro-il-campo-democratico-si-organizza-per-essere-alternativo-alla-maggioranza-rizzo\/","title":{"rendered":"San Pietro: il campo democratico si organizza per essere alternativo alla maggioranza Rizzo"},"content":{"rendered":"<p>Luned\u00ec 6 giugno, su iniziativa dell\u2019ex consigliere regionale Pino Romano, si \u00e8 svolta una riunione a San Pietro Vernotico avente come oggetto l\u2019ipotesi conoscitiva di un campo democratico alternativo all\u2019attuale maggioranza che governa San Pietro Vernotico.<\/p>\n<p>&nbsp;<\/p>\n<p>Nell\u2019introduzione Pino Romano ha illustrato gli obiettivi del progetto politico e cio\u00e8 dare vita ad una alternativa programmatica e politica in grado di aggregare tutte le energie (singoli, associazioni, movimenti, partiti) interessate. Il progetto politico ha come collante il giudizio pesantemente negativo sull\u2019operato dell\u2019attuale amministrazione e la volont\u00e0 di voltare pagina rispetto all\u2019attuale malgoverno del paese. A questo primo incontro sono stati invitati i consiglieri comunali di minoranza, gli ex sindaci Rollo e Renna, gli ex vice sindaci Pecoraro Angeletti, Argentieri, Esposito, l\u2019ex parlamentare Elisa Mariano, gli assessori, i consiglieri e i candidati delle maggioranza Rollo e Renna, l\u2019Associazione \u201cPer San Pietro\u201d, il PD e il Movimento 5 Stelle.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019iniziativa, molto partecipata, ha registrato il generale apprezzamento per la convocazione e la volont\u00e0 di continuare su questa strada con l\u2019obiettivo di allargare il campo a tutti coloro, singoli o associati, interessati a costruire un progetto di cambiamento alternativo alla maggioranza Rizzo.<\/p>\n<p>&nbsp;<\/p>\n<p>I partecipanti, condividendo il documento, intendono prossimamente dare vita ad un coordinamento che rappresenti le diverse partecipazioni ed assuma l\u2019impegno a proseguire sulla strada intrapresa.<\/p>\n<p>&nbsp;<\/p>\n<p>Hanno annunciato la propria adesione anche il Movimento 5 Stelle e l\u2019Associazione \u201cPer San Pietro\u201d. I sottoscrittori del documento si sono dati appuntamento per i prossimi giorni per definire un \u201ccomitato di coordinamento\u201d al quale affidare la costruzione del progetto politico e programmatico per la \u201cSan Pietro del domani\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Il documento \u00e8 stato sottoscritto da Angelo Esposito, Valentina Carella, Fabrizio Carella, Giuseppe Pecoraro, Sergio Palma, Franco Simone, Danilo Gargano, Andrea Fiorentino, Oronzo Giordano, Samuel Politi, Pietro Solazzo, Francesco Angeletti, Stefano Notarnicola e da Miro Civilla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luned\u00ec 6 giugno, su iniziativa dell\u2019ex consigliere regionale Pino Romano, si \u00e8 svolta una riunione a San Pietro Vernotico avente come oggetto l\u2019ipotesi conoscitiva di un campo democratico alternativo all\u2019attuale maggioranza che governa San Pietro Vernotico. &nbsp; Nell\u2019introduzione Pino Romano ha illustrato gli obiettivi del progetto politico e cio\u00e8 dare vita ad una alternativa programmatica e politica in grado di aggregare tutte le energie (singoli, associazioni, movimenti, partiti) interessate. Il progetto politico ha come collante il giudizio pesantemente negativo sull\u2019operato dell\u2019attuale amministrazione e la volont\u00e0 di voltare pagina rispetto all\u2019attuale malgoverno del paese. A questo primo incontro sono stati invitati i consiglieri comunali di minoranza, gli ex sindaci Rollo e Renna, gli ex vice sindaci Pecoraro Angeletti, Argentieri, Esposito, l\u2019ex parlamentare Elisa Mariano, gli assessori, i consiglieri e i candidati delle maggioranza Rollo e Renna, l\u2019Associazione \u201cPer San Pietro\u201d, il PD e il Movimento 5 Stelle. &nbsp; L\u2019iniziativa, molto partecipata, ha registrato il generale apprezzamento per la convocazione e la volont\u00e0 di continuare su questa strada con l\u2019obiettivo di allargare&#8230;<\/p>\n","protected":false},"author":2,"featured_media":18316,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-202591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/202591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=202591"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/202591\/revisions"}],"predecessor-version":[{"id":202592,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/202591\/revisions\/202592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/18316"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=202591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=202591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=202591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}