{"id":20309,"date":"2014-08-20T17:40:58","date_gmt":"2014-08-20T15:40:58","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=20309"},"modified":"2014-08-20T22:55:55","modified_gmt":"2014-08-20T20:55:55","slug":"rifiuti-baresi-ad-autigno-centrodestra-persi-milioni-di-euro","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/rifiuti-baresi-ad-autigno-centrodestra-persi-milioni-di-euro\/","title":{"rendered":"Rifiuti baresi ad Autigno, centrodestra: &#8220;persi milioni di euro&#8221;"},"content":{"rendered":"<p>Il 12 settembre 2013, un anno fa, i gruppi consiliari di PDL (oggi Forza Italia), FLI, Brindisi Avanti Veloce, Puglia prima di tutto e Movimento Regione Salento, depositarono una circostanziata interrogazione rispetto a quanto si stava verificando ad Autigno con i rifiuti provenienti da Bari.<\/p>\n<p>&nbsp;<\/p>\n<p>La interrogazione rivolta al Sindaco Consales riguardava infatti il conferimento dei rifiuti provenienti, da ormai oltre 6 mesi (all&#8217;epoca. Oggi quasi due anni) dai comuni dell&#8217;ex ATO BA\/5 ad Autigno.<\/p>\n<p>&nbsp;<\/p>\n<p>Con la interrogazione si chiedeva al Sindaco di sapere a quanto ammontavano gli incassi straordinari percepiti dal soggetto aggiudicatario (la ditta Nubile srl) per il solo conferimento dei rifiuti da parte dei comuni del bacino BA\/5.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Questa domanda &#8211; dichiara Massimiliano Oggiano, capogruppo de La Puglia prima di tutto &#8211; venne posta in quanto, a pare dei gruppi, non si capivano le motivazioni che avevano portato l\u2019Amministrazione comunale a non gestire direttamente, in qualit\u00e0 di proprietaria della discarica di Autigno, il rapporto convenzionale con quei comuni e di conseguenza le motivazioni per le quali l&#8217;amministrazione Consales non aveva previsto un affidamento secondario della gestione dei rifiuti che disciplinasse l\u2019incasso di una quota parte a favore del Comune stesso&#8221;<\/p>\n<p>&nbsp;<\/p>\n<p>Poich\u00e8 tale scelta costituisce un&#8217;evidente esposizione al rischio di danno erariale, i gruppi chiesero anche al Sindaco di fornirsi, dal Collegio dei revisori dei Conti e dalla Procura della Corte dei conti, del parere su tutta la vicenda descritta nella interrogazione presentata.<\/p>\n<p>&#8220;Niente di tutto ci\u00f2 &#8211; conclude Oggiano &#8211; \u00e8 stato fatto. Oggi Brindisi \u00e8 ancora discarica di rifiuti da Bari senza alcun ritorno economico e con il dubbio che il Comune di Brindisi non ha incassato somme che invece sono state incassate dal gestore privato interamente. Consales oggi si lamenta con Vendola, ma se ci avesse ascoltati non saremmo arrivati a questo punto&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMUNICATO STAMPA GRUPPI CONSILIARI DI CENTRODESTRA DI BRINDISI<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 12 settembre 2013, un anno fa, i gruppi consiliari di PDL (oggi Forza Italia), FLI, Brindisi Avanti Veloce, Puglia prima di tutto e Movimento Regione Salento, depositarono una circostanziata interrogazione rispetto a quanto si stava verificando ad Autigno con i rifiuti provenienti da Bari. &nbsp; La interrogazione rivolta al Sindaco Consales riguardava infatti il conferimento dei rifiuti provenienti, da ormai oltre 6 mesi (all&#8217;epoca. Oggi quasi due anni) dai comuni dell&#8217;ex ATO BA\/5 ad Autigno. &nbsp; Con la interrogazione si chiedeva al Sindaco di sapere a quanto ammontavano gli incassi straordinari percepiti dal soggetto aggiudicatario (la ditta Nubile srl) per il solo conferimento dei rifiuti da parte dei comuni del bacino BA\/5. &nbsp; &#8220;Questa domanda &#8211; dichiara Massimiliano Oggiano, capogruppo de La Puglia prima di tutto &#8211; venne posta in quanto, a pare dei gruppi, non si capivano le motivazioni che avevano portato l\u2019Amministrazione comunale a non gestire direttamente, in qualit\u00e0 di proprietaria della discarica di Autigno, il rapporto convenzionale con quei comuni e di conseguenza le motivazioni per&#8230;<\/p>\n","protected":false},"author":2,"featured_media":653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1714,865],"class_list":["post-20309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-discarica-autigno","tag-oggiano"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/20309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=20309"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/20309\/revisions"}],"predecessor-version":[{"id":20310,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/20309\/revisions\/20310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/653"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=20309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=20309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=20309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}