{"id":204709,"date":"2022-10-12T15:33:00","date_gmt":"2022-10-12T13:33:00","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=204709"},"modified":"2022-10-12T17:16:37","modified_gmt":"2022-10-12T15:16:37","slug":"lippolis-confindustria-inconcepibile-perdere-risorse-per-le-nostre-aree-industriali-siamo-senza-parole","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/lippolis-confindustria-inconcepibile-perdere-risorse-per-le-nostre-aree-industriali-siamo-senza-parole\/","title":{"rendered":"Lippolis (Confindustria): &#8220;Inconcepibile perdere risorse per le nostre aree industriali. Siamo senza parole!&#8221;"},"content":{"rendered":"<p>La notizia della perdita di 9,7 milioni di euro di finanziamenti del Fondo di Sviluppo e Coesione per manutenere e infrastrutturare con servizi di primaria necessit\u00e0 le nostre aree industriali ci lascia senza parole.<\/p>\n<p>Parliamo di interventi ammessi a finanziamento nel lontano 2018, che avrebbero consentito di realizzare opere di urbanizzazione per acqua e fogna, di migliorare e completare la viabilit\u00e0, di intervenire con opere di efficientamento energetico. Mai come adesso c\u2019\u00e8 estremo bisogno di colmare gli svantaggi competitivi dei nostri territori e di renderli quanto pi\u00f9 possibile accessibili e attrattivi.<\/p>\n<p>Confindustria opera quotidianamente per creare le condizioni affinch\u00e9 vengano colte nuove occasioni di crescita, ma diventa difficile se non si riesce neppure ad utilizzare le risorse a disposizione.<\/p>\n<p>Recuperare questi finanziamenti nel prossimo ciclo del Fsc non rappresenterebbe comunque una notizia che consentirebbe di rallegrarsi particolarmente, perch\u00e9 a furia di perdere tempo e traslare investimenti da una misura ad un\u2019altra &#8211; cos\u00ec come accaduto ad esempio per le opere portuali, anche a causa dei continui rallentamenti burocratici &#8211; si priva il territorio di potenziali risorse aggiuntive.<\/p>\n<p>\u00c8 un gioco a somma zero che dobbiamo tutti assieme impegnarci a interrompere se vogliamo davvero ambire ad un futuro pi\u00f9 prospero.<\/p>\n<p>&nbsp;<\/p>\n<p>CONFINDUSTRIA BRINDISI<br \/>\nArea Comunicazione, Digital, Marketing e Formazione<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La notizia della perdita di 9,7 milioni di euro di finanziamenti del Fondo di Sviluppo e Coesione per manutenere e infrastrutturare con servizi di primaria necessit\u00e0 le nostre aree industriali ci lascia senza parole. Parliamo di interventi ammessi a finanziamento nel lontano 2018, che avrebbero consentito di realizzare opere di urbanizzazione per acqua e fogna, di migliorare e completare la viabilit\u00e0, di intervenire con opere di efficientamento energetico. Mai come adesso c\u2019\u00e8 estremo bisogno di colmare gli svantaggi competitivi dei nostri territori e di renderli quanto pi\u00f9 possibile accessibili e attrattivi. Confindustria opera quotidianamente per creare le condizioni affinch\u00e9 vengano colte nuove occasioni di crescita, ma diventa difficile se non si riesce neppure ad utilizzare le risorse a disposizione. Recuperare questi finanziamenti nel prossimo ciclo del Fsc non rappresenterebbe comunque una notizia che consentirebbe di rallegrarsi particolarmente, perch\u00e9 a furia di perdere tempo e traslare investimenti da una misura ad un\u2019altra &#8211; cos\u00ec come accaduto ad esempio per le opere portuali, anche a causa dei continui rallentamenti burocratici &#8211; si&#8230;<\/p>\n","protected":false},"author":2,"featured_media":204713,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-204709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/204709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=204709"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/204709\/revisions"}],"predecessor-version":[{"id":204714,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/204709\/revisions\/204714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/204713"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=204709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=204709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=204709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}