{"id":2061,"date":"2014-01-05T20:52:19","date_gmt":"2014-01-05T19:52:19","guid":{"rendered":"http:\/\/www.seltest.info\/brun\/?p=2061"},"modified":"2014-01-06T08:56:54","modified_gmt":"2014-01-06T07:56:54","slug":"nuovi-contenuti-per-il-sito-web-della-protezione-civile-di-brindisi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/nuovi-contenuti-per-il-sito-web-della-protezione-civile-di-brindisi\/","title":{"rendered":"Nuovi contenuti per il sito web della Protezione Civile di Brindisi"},"content":{"rendered":"<p>Il sito web del <strong>Dipartimento della Protezione Civile<\/strong> rinnova la sezione meteo, creandola a misura di cittadino: condensati in una unica pagina web si trovano i bollettini meteo, le allerta e le informazioni su come comportarsi e prevenire danni e rischi.<br \/>\nLe previsioni meteo a fini di protezione civile sono diverse dalle classiche &#8220;previsioni del tempo&#8221; perch\u00e9 evidenziano situazioni potenzialmente dannose per persone o cose.<br \/>\n\u00c8 compito delle Regioni e delle Province Autonome diramare le allerte per i sistemi locali di protezione civile, mentre spetta ai Sindaci informare i cittadini sulle situazioni di rischio e decidere le azioni da intraprendere per tutelare la popolazione.<\/p>\n<p>Dal sito della protezione civile del Comune di Brindisi <a href=\"http:\/\/www.comune.brindisi.it\/protezionecivile\/\" target=\"_blank\">http:\/\/www.comune.brindisi.it\/protezionecivile\/<\/a> alla sezione &#8220;<strong><em>ALLERTAMENTO METEO-IDRO NAZIONALE<\/em><\/strong>&#8221; sar\u00e0 possibile collegarsi direttamente alla sezione meteo del Dipartimento.<br \/>\nEssere consapevoli e preparati \u00e8 il modo migliore per prevenire e ridurre i rischi e allo stesso tempo per tutelarsi dai possibili danni.<\/p>\n<p><strong>COMUNICATO STAMPA PROTEZIONE CIVILE BRINDISI<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sito web del Dipartimento della Protezione Civile rinnova la sezione meteo, creandola a misura di cittadino: condensati in una unica pagina web si trovano i bollettini meteo, le allerta e le informazioni su come comportarsi e prevenire danni e rischi. Le previsioni meteo a fini di protezione civile sono diverse dalle classiche &#8220;previsioni del tempo&#8221; perch\u00e9 evidenziano situazioni potenzialmente dannose per persone o cose. \u00c8 compito delle Regioni e delle Province Autonome diramare le allerte per i sistemi locali di protezione civile, mentre spetta ai Sindaci informare i cittadini sulle situazioni di rischio e decidere le azioni da intraprendere per tutelare la popolazione. Dal sito della protezione civile del Comune di Brindisi http:\/\/www.comune.brindisi.it\/protezionecivile\/ alla sezione &#8220;ALLERTAMENTO METEO-IDRO NAZIONALE&#8221; sar\u00e0 possibile collegarsi direttamente alla sezione meteo del Dipartimento. Essere consapevoli e preparati \u00e8 il modo migliore per prevenire e ridurre i rischi e allo stesso tempo per tutelarsi dai possibili danni. COMUNICATO STAMPA PROTEZIONE CIVILE BRINDISI<\/p>\n","protected":false},"author":2,"featured_media":2062,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[33,128],"class_list":["post-2061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-brindisi","tag-protezione-civile"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/2061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=2061"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/2061\/revisions"}],"predecessor-version":[{"id":2063,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/2061\/revisions\/2063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/2062"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=2061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=2061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=2061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}