{"id":20809,"date":"2014-08-28T13:14:21","date_gmt":"2014-08-28T11:14:21","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=20809"},"modified":"2014-08-28T13:14:21","modified_gmt":"2014-08-28T11:14:21","slug":"riscossione-tributi-cgil-e-cisl-chiedono-incontro-al-comune-di-brindisi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/riscossione-tributi-cgil-e-cisl-chiedono-incontro-al-comune-di-brindisi\/","title":{"rendered":"Riscossione Tributi: Cgil e Cisl chiedono incontro al Comune di Brindisi"},"content":{"rendered":"<p>Come OO.SS. di categoria, FILCAMS\/CGIL e FISASCAT\/CISL, abbiamo rinnovato la richiesta d\u2019incontro al Sindaco, agli Assessori Tributi e Contratti e ai rispettivi Funzionari, per discutere nel merito del capitolato d\u2019appalto tributi locali al fine di evitare l\u2019ennesima guerra tra l\u2019eventuale ditta aggiudicataria dell\u2019appalto e lavoratori che a ogni cambio aziendale chiedono il rispetto della salvaguardia occupazionale e la conferma dei contratti in essere.<\/p>\n<p>&nbsp;<\/p>\n<p>Purtroppo il bando di gara \u00e8 stato gi\u00e0 pubblicato nell\u2019albo pretorio senza aver avuto modo di discutere ma, non demordiamo, proprio negli interessi dei lavoratori e, auspichiamo ci sia un passaggio urgente con l\u2019Amministrazione che, intanto, nelle condizioni di gara, contraddice il riconoscimento di un diritto di civilt\u00e0 espresso gi\u00e0 dal Consiglio Comunale del capoluogo, che votava all\u2019unanimit\u00e0 la richiesta che fosse applicata la clausola di salvaguardia dei lavoratori negli appalti.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel Bando invece si crea un discrimine tra gli stessi, non garantendo tutti i 21 lavoratori gi\u00e0 impegnati sull\u2019appalto alle dipendenze della ditta uscente ABACO, i loro diritti e il margine di guadagno all\u2019eventuale ditta aggiudicataria senza che questa possa ledere i diritti dei lavoratori e anche la qualit\u00e0 del servizio offerto.<\/p>\n<p>&nbsp;<\/p>\n<p>COMUNICATO STAMPA FILCAMS\/CGIL e FISASCAT\/CISL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come OO.SS. di categoria, FILCAMS\/CGIL e FISASCAT\/CISL, abbiamo rinnovato la richiesta d\u2019incontro al Sindaco, agli Assessori Tributi e Contratti e ai rispettivi Funzionari, per discutere nel merito del capitolato d\u2019appalto tributi locali al fine di evitare l\u2019ennesima guerra tra l\u2019eventuale ditta aggiudicataria dell\u2019appalto e lavoratori che a ogni cambio aziendale chiedono il rispetto della salvaguardia occupazionale e la conferma dei contratti in essere. &nbsp; Purtroppo il bando di gara \u00e8 stato gi\u00e0 pubblicato nell\u2019albo pretorio senza aver avuto modo di discutere ma, non demordiamo, proprio negli interessi dei lavoratori e, auspichiamo ci sia un passaggio urgente con l\u2019Amministrazione che, intanto, nelle condizioni di gara, contraddice il riconoscimento di un diritto di civilt\u00e0 espresso gi\u00e0 dal Consiglio Comunale del capoluogo, che votava all\u2019unanimit\u00e0 la richiesta che fosse applicata la clausola di salvaguardia dei lavoratori negli appalti. &nbsp; Nel Bando invece si crea un discrimine tra gli stessi, non garantendo tutti i 21 lavoratori gi\u00e0 impegnati sull\u2019appalto alle dipendenze della ditta uscente ABACO, i loro diritti e il margine di guadagno all\u2019eventuale&#8230;<\/p>\n","protected":false},"author":2,"featured_media":15519,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1146,33,236,418],"class_list":["post-20809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-abaco","tag-brindisi","tag-cgil","tag-cisl"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/20809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=20809"}],"version-history":[{"count":0,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/20809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/15519"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=20809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=20809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=20809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}