{"id":21330,"date":"2014-09-04T12:35:48","date_gmt":"2014-09-04T10:35:48","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=21330"},"modified":"2014-09-04T14:41:07","modified_gmt":"2014-09-04T12:41:07","slug":"rapina-tra-rumeni-un-arresto-ed-una-denuncia","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/rapina-tra-rumeni-un-arresto-ed-una-denuncia\/","title":{"rendered":"Rapina tra rumeni: un arresto ed una denuncia"},"content":{"rendered":"<p>I carabinieri della Stazione di Brindisi, coadiuvati e supportati dal personale del n.o.rm. della locale Compagnia, hanno tratto in arresto in flagranza di reato Nicolae Caldarar, 28enne di origine romena, in Italia senza fissa dimora.<\/p>\n<p>L&#8217;uomo dovr\u00e0 rispondere di tentata rapina per aver aggredito un suo connazionale 19enne tentando, dopo averlo violentemente percosso, di strappargli una borsetta portata a tracolla contenente la somma contante di 50,00 euro.<\/p>\n<p>I fatti sono accaduti il 3 Agosto scorso in una via del centro di Brindisi.<\/p>\n<p>In seguito alla rapina, la vittima \u00e8 stata trasportata presso l&#8217;ospedale Perrino di Brindisi per le cure del caso.<br \/>\nNel corso delle indagini sono emersi indizi di reit\u00e0 a carico di un terzo individuo coinvolto identificato in C.T., 25enne di origine romena, per aver partecipato alla rapina.<\/p>\n<p>Caldarar, dopo le formalit\u00e0 di rito, \u00e8 stato associato alla casa circondariale di Brindisi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I carabinieri della Stazione di Brindisi, coadiuvati e supportati dal personale del n.o.rm. della locale Compagnia, hanno tratto in arresto in flagranza di reato Nicolae Caldarar, 28enne di origine romena, in Italia senza fissa dimora. L&#8217;uomo dovr\u00e0 rispondere di tentata rapina per aver aggredito un suo connazionale 19enne tentando, dopo averlo violentemente percosso, di strappargli una borsetta portata a tracolla contenente la somma contante di 50,00 euro. I fatti sono accaduti il 3 Agosto scorso in una via del centro di Brindisi. In seguito alla rapina, la vittima \u00e8 stata trasportata presso l&#8217;ospedale Perrino di Brindisi per le cure del caso. Nel corso delle indagini sono emersi indizi di reit\u00e0 a carico di un terzo individuo coinvolto identificato in C.T., 25enne di origine romena, per aver partecipato alla rapina. Caldarar, dopo le formalit\u00e0 di rito, \u00e8 stato associato alla casa circondariale di Brindisi.<\/p>\n","protected":false},"author":2,"featured_media":21333,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1447,33,2572],"class_list":["post-21330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-aurora-brindisi","tag-brindisi","tag-rumeni"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/21330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=21330"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/21330\/revisions"}],"predecessor-version":[{"id":21334,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/21330\/revisions\/21334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/21333"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=21330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=21330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=21330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}