{"id":21347,"date":"2014-09-04T17:00:09","date_gmt":"2014-09-04T15:00:09","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=21347"},"modified":"2014-09-04T17:45:50","modified_gmt":"2014-09-04T15:45:50","slug":"tempodestate2014-open-days-sabato-al-map-ce-babelica-1","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/tempodestate2014-open-days-sabato-al-map-ce-babelica-1\/","title":{"rendered":"#tempodestate2014, Open Days: sabato al MAP c&#8217;\u00e8 &#8220;Babelica 1&#8221;"},"content":{"rendered":"<p>\u00ab#tempodestate2014\u00bb, la rassegna di iniziative culturali e di spettacolo promossa dall\u2019Amministrazione comunale per l\u2019estate 2014, chiude i battenti sabato 6 settembre (ore 21) con il terzo appuntamento degli \u00abOpen Days\u00bb in programma nel \u00abMuseo Mediterraneo dell\u2019Arte Presente\u00bb, presso la chiesa di San Michele Arcangelo delle Scuole Pie (via Giovanni Tarantini, 37).<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abBabelica 1\u00bb, da un\u2019idea di Massimo Guastella e Ilaria Miccoli, \u00e8 un\u2019inattesa \u201cdrammaturgia compartecipata\u201d, di multiformi \u201cstorie nel contemporaneo\u201d, formulata da un variegato collettivo, di volta in volta occasionale. Artisti visivi, performer dello sconfinamento, attori, musicisti, poeti con condotta sottile e dissacratoria, intendono comunicare nell\u2019unica o nelle tante espressioni dell\u2019arte. Scevre da inflessioni ricercate e incomprensibili, ma dirette, semplici, di contatto umano, piece, performance, reading, intromissioni sonore, installazioni compongono il carrozzone di Babelica 1.<\/p>\n<p>L\u2019intento \u00e8 di esprimere e partecipare la bellezza o la bruttezza della creativit\u00e0 artistica nella contemporaneit\u00e0: stranezze e contrasti, conflitti e ricchezze dei linguaggi e dei media che diversificano questo nuovo millennio. \u00abBabelica 1\u00bb \u00e8 un\u2019azione artistica collettiva di disuguali suggestioni e momenti: gesti, pause, reiterazioni, intervalli periodici o rapsodici.<\/p>\n<p>Produzioni note o inedite di variegati percorsi espressi nel presente e che si proiettano nel futuro. In un abbinamento trans generazionale si esibiscono il performer Angelo Raffaele Antelmi (\u00abLa comunione\u00bb), l\u2019artista visiva Anna Candido (\u00abIl peso della cultura\u00bb), il poeta e artista visivo Francesco Faraone accompagnato da una originale rock band (\u00abVide Cor Meum\u00bb), le azioni performative del duo \u00abLuedo\u00bb di Domenico Arces e Lucia Macr\u00ec (\u00abOmaggio a Ipazia\u00bb e \u00abY with Y, l&#8217;opporsi degli opposti\u00bb), il poeta Gigi Mangia (poesie di Vittorio Bodini, Luciano Folgore e Aldo Palazzeschi), l\u2019artista visivo Alberto Moscara (\u00abTreppo\u00bb).<\/p>\n<p>&nbsp;<\/p>\n<p>COMUNICATO STAMPA AMMINISTRAZIONE COMUNALE DI BRINDISI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab#tempodestate2014\u00bb, la rassegna di iniziative culturali e di spettacolo promossa dall\u2019Amministrazione comunale per l\u2019estate 2014, chiude i battenti sabato 6 settembre (ore 21) con il terzo appuntamento degli \u00abOpen Days\u00bb in programma nel \u00abMuseo Mediterraneo dell\u2019Arte Presente\u00bb, presso la chiesa di San Michele Arcangelo delle Scuole Pie (via Giovanni Tarantini, 37). &nbsp; \u00abBabelica 1\u00bb, da un\u2019idea di Massimo Guastella e Ilaria Miccoli, \u00e8 un\u2019inattesa \u201cdrammaturgia compartecipata\u201d, di multiformi \u201cstorie nel contemporaneo\u201d, formulata da un variegato collettivo, di volta in volta occasionale. Artisti visivi, performer dello sconfinamento, attori, musicisti, poeti con condotta sottile e dissacratoria, intendono comunicare nell\u2019unica o nelle tante espressioni dell\u2019arte. Scevre da inflessioni ricercate e incomprensibili, ma dirette, semplici, di contatto umano, piece, performance, reading, intromissioni sonore, installazioni compongono il carrozzone di Babelica 1. L\u2019intento \u00e8 di esprimere e partecipare la bellezza o la bruttezza della creativit\u00e0 artistica nella contemporaneit\u00e0: stranezze e contrasti, conflitti e ricchezze dei linguaggi e dei media che diversificano questo nuovo millennio. \u00abBabelica 1\u00bb \u00e8 un\u2019azione artistica collettiva di disuguali suggestioni e momenti: gesti,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":21348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2420],"class_list":["post-21347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-tempodestate2014"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/21347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=21347"}],"version-history":[{"count":0,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/21347\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/21348"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=21347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=21347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=21347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}