{"id":21375,"date":"2014-09-05T06:59:48","date_gmt":"2014-09-05T04:59:48","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=21375"},"modified":"2014-09-14T10:47:32","modified_gmt":"2014-09-14T08:47:32","slug":"in_chiostri-oggi-la-terza-ed-ultima-giornata-il-programma","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/in_chiostri-oggi-la-terza-ed-ultima-giornata-il-programma\/","title":{"rendered":"IN_CHIOSTRI, oggi la terza ed ultima giornata: il programma"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/in_chiostri-scalinata-.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-21172\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/in_chiostri-scalinata--300x225.png\" alt=\"in_chiostri scalinata\" width=\"300\" height=\"225\" data-id=\"21172\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/in_chiostri-scalinata--300x225.png 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/in_chiostri-scalinata-.png 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Si avvia alla sua conclusione, nonostante il maltempo, la prima edizione di \u201cIn_Chiostri\u201d, il percorso culturale attraverso il centro storico di Brindisi alla scoperta di libri, gusti e storie.<\/p>\n<p>&nbsp;<\/p>\n<p>La giornata di oggi, venerd\u00ec 5 settembre, rappresenta infatti il culmine di una tre giorni durante la quale \u00e8 stato possibile tra l&#8217;altro incontrare ed ascoltare, nei chiostri e nelle strade, gli autori e i loro libri, porre domande e conoscerli meglio.<\/p>\n<p>La manifestazione, infatti, rappresenta un percorso dalla scalinata Virgiliana a Porta Mesagne o, se si preferisce, viceversa, per far vivere testi, parole, narrazioni e gusti: muovere i sensi, rileggere parole che hanno descritto, nei secoli, la citt\u00e0 e il territorio, ascoltare la voce del mare e dei poeti con recital e letture collettive.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/In_Chiostri-logo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-21178\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/In_Chiostri-logo-290x300.jpg\" alt=\"In_Chiostri logo\" width=\"167\" height=\"173\" data-id=\"21178\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/In_Chiostri-logo-290x300.jpg 290w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/In_Chiostri-logo-991x1024.jpg 991w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/In_Chiostri-logo.jpg 1712w\" sizes=\"auto, (max-width: 167px) 100vw, 167px\" \/><\/a>Nel programma spiccano le letture dello scrittore ed autore teatrale Emiliano Poddi (Chiesa di San Benedetto alle 18.15);<\/p>\n<p>la presentazione, con l&#8217;autore Francesco Romanelli, del volume \u201cSciabbicoti questi sconosciuti\u201d, sugli antichi abitanti di Brindisi (Chiostro dell&#8217;ex convento delle Scuole Pie alle 18.30);<\/p>\n<p>il seminario \u201cLa svolta: dalla narrativa alla poesia &#8216;per colpa&#8217; di Vittorio Bodini\u201d con la scrittrice Clara Nubile (Seminario di piazza Duomo alle 18.30);<\/p>\n<p>la presentazione della rivista di antropologia post-globale \u201cDada\u201d con Antonio Palmisano e Vitantonio Gioia (Chiesa di San Benedetto alle 19.00).<\/p>\n<p>Spazio anche alla poesia grazie all&#8217;incontro con Gianpaolo Papi, Osvaldo Capraro, Natale Buonarota, Aldo Cal\u00f2 Gabrielli e Maria Gallinari (Seminario di piazza Duomo alle 19.15).<\/p>\n<p>Infine, Francesco Fistetti presenta il \u201cManifesto Convivialista\u201d con Franco Botta e Nicola Costantino (Chiesa di San Benedetto alle 19.45).<\/p>\n<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/culturazioni.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-21044 size-medium\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/culturazioni-300x178.jpg\" alt=\"culturazioni\" width=\"300\" height=\"178\" data-id=\"21044\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/culturazioni-300x178.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/08\/culturazioni.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Alle ore 21.00 Marco Greco presenta Culturazioni, con Mino Pica, autore di diverse ed interessanti opere editoriali, accompagnato dalla voce narrante di Daniela Errico e dalle musiche di Silvia La Grotta (violino), Doriana De Luca (flauto) e Dino Panza (aronica).<\/p>\n<p>&nbsp;<\/p>\n<p>Ma \u201cIn_Chiostri\u201d, come hanno gi\u00e0 avuto modo di notare i tanti visitatori, non \u00e8 solo un appuntamento dedicato ai libri, che pure sono protagonisti della rassegna.<\/p>\n<p>Non manca, infatti, lo spazio dedicato a musica, teatro e performance di ogni genere.<\/p>\n<p>&nbsp;<\/p>\n<p>Tra gli appuntamenti di oggi, quello itinerante con i \u201cLibri di vetro\u201d della compagnia Formediterra e quello con \u201cEndrigo incontra Rodari\u201d, con le chitarre di Angelo Di Muri e Gianluigi Cosi (Via Colonne alle 19, alle 20 e alle 21).<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cIn_Chiostri\u201d si chiude in piazza Duomo, alle 21.30, con il primo evento scenico del \u201cMedieval Fest\u201d, con Alessandro Haber, Beppe Lo Parco e Jusy Effen che interpreteranno brani da \u201cIl Ben de&#8217; Fiori\u201d (dedicato a Carmelo Bene), ma anche dell&#8217;Inferno di Dante Alighieri e del Canzoniere di Cecco Angiolieri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si avvia alla sua conclusione, nonostante il maltempo, la prima edizione di \u201cIn_Chiostri\u201d, il percorso culturale attraverso il centro storico di Brindisi alla scoperta di libri, gusti e storie. &nbsp; La giornata di oggi, venerd\u00ec 5 settembre, rappresenta infatti il culmine di una tre giorni durante la quale \u00e8 stato possibile tra l&#8217;altro incontrare ed ascoltare, nei chiostri e nelle strade, gli autori e i loro libri, porre domande e conoscerli meglio. La manifestazione, infatti, rappresenta un percorso dalla scalinata Virgiliana a Porta Mesagne o, se si preferisce, viceversa, per far vivere testi, parole, narrazioni e gusti: muovere i sensi, rileggere parole che hanno descritto, nei secoli, la citt\u00e0 e il territorio, ascoltare la voce del mare e dei poeti con recital e letture collettive. &nbsp; Nel programma spiccano le letture dello scrittore ed autore teatrale Emiliano Poddi (Chiesa di San Benedetto alle 18.15); la presentazione, con l&#8217;autore Francesco Romanelli, del volume \u201cSciabbicoti questi sconosciuti\u201d, sugli antichi abitanti di Brindisi (Chiostro dell&#8217;ex convento delle Scuole Pie alle 18.30); il seminario&#8230;<\/p>\n","protected":false},"author":2,"featured_media":21178,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2512],"class_list":["post-21375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-in_chiostri"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/21375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=21375"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/21375\/revisions"}],"predecessor-version":[{"id":21378,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/21375\/revisions\/21378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/21178"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=21375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=21375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=21375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}