{"id":21393,"date":"2014-09-05T11:31:55","date_gmt":"2014-09-05T09:31:55","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=21393"},"modified":"2014-09-05T11:31:55","modified_gmt":"2014-09-05T09:31:55","slug":"domenica-a-ceglie-passeggiata-nel-benessere-tra-cultura-e-alimentazione","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/domenica-a-ceglie-passeggiata-nel-benessere-tra-cultura-e-alimentazione\/","title":{"rendered":"Domenica a Ceglie &#8220;Passeggiata nel Benessere tra Cultura e Alimentazione&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/salute-e-benessere-ceglie.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-21394\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/salute-e-benessere-ceglie-212x300.png\" alt=\"salute e benessere ceglie\" width=\"212\" height=\"300\" data-id=\"21394\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/salute-e-benessere-ceglie-212x300.png 212w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/salute-e-benessere-ceglie-724x1024.png 724w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/salute-e-benessere-ceglie.png 1698w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a>La Commissione Pari Opportunit\u00e0 di Ceglie Messapica, organizza per il giorno Domenica 7 Settembre 2014 l&#8217;evento \u201cSalute e Benessere \u2013 Passeggiata nel Benessere tra Cultura e Alimentazione\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Il programma prevede alle ore 16.00 la \u201cPasseggiata nel Benessere\u201d, che partir\u00e0 da Largo Monterrone e si svolger\u00e0 nel Centro Storico della citt\u00e0. Le iscrizioni potranno essere effettuate sul luogo di partenza dalle ore 15.00.<br \/>\nAi primi cento iscritti sar\u00e0 consegnato un omaggio.<\/p>\n<p>&nbsp;<\/p>\n<p>Al termine della \u201cpasseggiata\u201d, alle ore 19.00 presso il Castello Ducale di Ceglie Messapica, seguir\u00e0 un convegno-dibattito che affronter\u00e0 diversi temi su alimentazione, salute e benessere. \u201cMedicina e Sport: nuove prospettive per il benessere\u201d a cura del Dott. Donato Carlucci (Medico Chirurgo); \u201cIl Diritto all&#8217;Alimentazione\u201d a cura dell&#8217;Avv. Eleonora Rottola; \u201cLa Dieta Mediterranea: quando il benessere inizia a tavola\u201d a cura della Dott.ssa Tiziana Barletta (Biologa Nutrizionista); \u201cMangiare senza freni. Perch\u00e9? Fattori che influenzano il comportamento alimentare in Adulti e Bambini\u201d a cura della Dott.ssa Agata Evelina Carriero (Psicoterapeuta \u2013 Esperta in Disturbi del Comportamento Alimentari).<\/p>\n<p>Modera la Presidente della Commissione Pari Opportunit\u00e0 di Ceglie Messapica, Dott.ssa Anna Gabriella Rodio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Commissione Pari Opportunit\u00e0 di Ceglie Messapica, organizza per il giorno Domenica 7 Settembre 2014 l&#8217;evento \u201cSalute e Benessere \u2013 Passeggiata nel Benessere tra Cultura e Alimentazione\u201d. &nbsp; Il programma prevede alle ore 16.00 la \u201cPasseggiata nel Benessere\u201d, che partir\u00e0 da Largo Monterrone e si svolger\u00e0 nel Centro Storico della citt\u00e0. Le iscrizioni potranno essere effettuate sul luogo di partenza dalle ore 15.00. Ai primi cento iscritti sar\u00e0 consegnato un omaggio. &nbsp; Al termine della \u201cpasseggiata\u201d, alle ore 19.00 presso il Castello Ducale di Ceglie Messapica, seguir\u00e0 un convegno-dibattito che affronter\u00e0 diversi temi su alimentazione, salute e benessere. \u201cMedicina e Sport: nuove prospettive per il benessere\u201d a cura del Dott. Donato Carlucci (Medico Chirurgo); \u201cIl Diritto all&#8217;Alimentazione\u201d a cura dell&#8217;Avv. Eleonora Rottola; \u201cLa Dieta Mediterranea: quando il benessere inizia a tavola\u201d a cura della Dott.ssa Tiziana Barletta (Biologa Nutrizionista); \u201cMangiare senza freni. Perch\u00e9? Fattori che influenzano il comportamento alimentare in Adulti e Bambini\u201d a cura della Dott.ssa Agata Evelina Carriero (Psicoterapeuta \u2013 Esperta in Disturbi del Comportamento Alimentari). Modera la&#8230;<\/p>\n","protected":false},"author":2,"featured_media":21394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[577],"class_list":["post-21393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-ceglie"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/21393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=21393"}],"version-history":[{"count":0,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/21393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/21394"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=21393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=21393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=21393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}