{"id":21788,"date":"2014-09-10T22:31:38","date_gmt":"2014-09-10T20:31:38","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=21788"},"modified":"2014-09-11T13:34:11","modified_gmt":"2014-09-11T11:34:11","slug":"rifiuti-baresi-ad-autigno-oggiano-altro-regalo-di-vendola","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/rifiuti-baresi-ad-autigno-oggiano-altro-regalo-di-vendola\/","title":{"rendered":"Rifiuti baresi ad Autigno, Oggiano: &#8220;altro regalo di Vendola&#8221;"},"content":{"rendered":"<p>La Regione Puglia continua ad scaricare tonnellate di rifiuti sul nostro territorio: l&#8217;ultimo schiaffo e&#8217; rappresentato dall&#8217;ordinanza n. 11 del 5 settembre. Vendola ordina il conferimento di circa 100 tonnellate al giorno di rifiuti assimilati agli urbani destinati alla discarica di Trani, chiusa dal 3 settembre per rischio ambientale, presso la discarica di rifiuti speciali di Formica! Siamo alla follia!<\/p>\n<p>Dopo che da circa un anno e mezzo e stato ordinato e prorogato lo sversamento dei rifiuti dei comuni dell&#8217;ATO BA 5 ad Auitgno, dopo l&#8217;autorizzazione all&#8217;esercizio della discarica di Formica, sottoposta a procedimento penale che pare si chiuder\u00e0 a giorni con la confisca, Vendola ci regala altre 100 tonnellate al giorno di rifiuti!<\/p>\n<p>Cosa grave nel silenzio pi\u00f9 assoluto di chi ci dovrebbe rappresentare e tutelare in seno all&#8217;organismo regionale! Che fine hanno fatto i consiglieri regionali, soprattutto quelli che sostengono Vendola e pi\u00f9 precisamente chi ne e&#8217; diretta espressione???<\/p>\n<p>Ad oggi le istituzionali locali, Provincia in primis deputata al controllo ambientale, ancora non sono state notiziate dello scempio a cui ci hanno sottoposto!<\/p>\n<p>Che intende fare il Sindaco Consales per tutelare il nostro territorio? Quale sar\u00e0 questa volta l&#8217;elemosina che la Regione intende dare al territorio per io ristoro ambientale?<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dott. Massimiliano Oggiano<\/strong><br \/>\n<strong> Capogruppo La Puglia prima di tutto<\/strong><\/p>\n<p><strong>Gruppi consiliari centrodestra FI BAV MRS FLI<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Regione Puglia continua ad scaricare tonnellate di rifiuti sul nostro territorio: l&#8217;ultimo schiaffo e&#8217; rappresentato dall&#8217;ordinanza n. 11 del 5 settembre. Vendola ordina il conferimento di circa 100 tonnellate al giorno di rifiuti assimilati agli urbani destinati alla discarica di Trani, chiusa dal 3 settembre per rischio ambientale, presso la discarica di rifiuti speciali di Formica! Siamo alla follia! Dopo che da circa un anno e mezzo e stato ordinato e prorogato lo sversamento dei rifiuti dei comuni dell&#8217;ATO BA 5 ad Auitgno, dopo l&#8217;autorizzazione all&#8217;esercizio della discarica di Formica, sottoposta a procedimento penale che pare si chiuder\u00e0 a giorni con la confisca, Vendola ci regala altre 100 tonnellate al giorno di rifiuti! Cosa grave nel silenzio pi\u00f9 assoluto di chi ci dovrebbe rappresentare e tutelare in seno all&#8217;organismo regionale! Che fine hanno fatto i consiglieri regionali, soprattutto quelli che sostengono Vendola e pi\u00f9 precisamente chi ne e&#8217; diretta espressione??? Ad oggi le istituzionali locali, Provincia in primis deputata al controllo ambientale, ancora non sono state notiziate dello scempio&#8230;<\/p>\n","protected":false},"author":2,"featured_media":653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1714,865],"class_list":["post-21788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-discarica-autigno","tag-oggiano"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/21788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=21788"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/21788\/revisions"}],"predecessor-version":[{"id":21789,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/21788\/revisions\/21789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/653"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=21788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=21788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=21788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}