{"id":22816,"date":"2014-09-24T16:36:40","date_gmt":"2014-09-24T14:36:40","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=22816"},"modified":"2014-09-24T22:32:11","modified_gmt":"2014-09-24T20:32:11","slug":"sara-bevilacqua-con-gianrico-carofiglio-al-teatro-petruzzelli-di-bari","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/sara-bevilacqua-con-gianrico-carofiglio-al-teatro-petruzzelli-di-bari\/","title":{"rendered":"Sara Bevilacqua con Gianrico Carofiglio al Teatro Petruzzelli di Bari"},"content":{"rendered":"<p>Marted\u00ec 30 settembre alle 21.00 al Teatro Petruzzelli \u00e8 in cartellone Rach 2.<br \/>\nIl concerto rientra nella Stagione Sinfonica 2014. Diriger\u00e0 l\u2019Orchestra del Teatro John Axelrod.<\/p>\n<p>In programma la prima esecuzione assoluta de \u201cIl bordo vertiginoso delle cose\u201d, melologo per due voci recitanti e orchestra con musica di Fabio Vacchi, tratto dall\u2019omonimo romanzo di Gianrico Carofiglio. Voci recitanti Gianrico Carofiglio e Sara Bevilacqua.<\/p>\n<p>La seconda parte del programma sar\u00e0 dedicata al Concerto n. 2 per pianoforte ed Orchestra in do minore op. 18 di Sergej Rachmaninov, solista Benedetto Lupo.<\/p>\n<p>I biglietti sono gi\u00e0 disponibili al Botteghino del Teatro Petruzzelli.<br \/>\nInformazioni: 080.975.28.10<br \/>\nIl botteghino sar\u00e0 chiuso per la pausa estiva da luned\u00ec 28 luglio a domenica 24 agosto, le vendite continueranno on line su www.bookingshow.it.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_22820\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/John-Axelrod-5.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-22820\" class=\"size-medium wp-image-22820\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/John-Axelrod-5-300x239.jpg\" alt=\"John Axelrod \" width=\"300\" height=\"239\" data-id=\"22820\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/John-Axelrod-5-300x239.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/John-Axelrod-5-1024x817.jpg 1024w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/John-Axelrod-5.jpg 1159w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-22820\" class=\"wp-caption-text\">John Axelrod<\/p><\/div>\n<p><strong>John Axelrod, direttore<\/strong><br \/>\nGrazie al suo vasto repertorio, ai programmi innovativi ed allo stile carismatico, John Axelrod \u00e8 considerato uno dei direttori pi\u00f9 interessanti del panorama odierno ed \u00e8 richiesto dalle orchestre di tutto il mondo.<br \/>\nDopo aver completato con successo la sua carica quinquennale come direttore principale della Luzerner Sinfonie Orchester e direttore musicale del Teatro di Lucerna ed essere stato nominato Direttore Musicale dell\u2019Orchestre National des Pays de la Loire (ONPL), John Axelrod \u00e8 stato nominato Direttore Principale dell\u2019Orchestra Sinfonica di Milano \u201cG. Verdi\u201d.<br \/>\nSin dal 2000, ha diretto oltre 150 orchestre, fra cui la Rundfunk-Sinfonieorchester di Berlino, NDR Symphony di Amburgo, Gewandhaus Orchestra, Israel Philharmonic, Orchestre de Paris, Orchestre National de Lyon, Royal Philharmonic of London, London Philharmonia, Orchestre de la Suisse Romande, Orchestra dell\u2019Accademia Nazionale di Santa Cecilia, Orchestra Sinfonica Nazionale della RAI di Torino, Orchestra del Teatro La Fenice di Venezia, Orchestra del Teatro di San Carlo di Napoli, Royal Stockholm Philharmonic, Oslo Philharmonic, Swedish Radio Orchestra, National Philharmonic of Russia, ORF di Vienna, Salzburg Mozarteum, Camerata Salzburg, Warsaw Philharmonic, Washington National Symphony, Los Angeles Philharmonic, Philadelphia Orchestra, Chicago Symphony, NHK Symphony Orchestra di Tokyo.<br \/>\nLa sua attivit\u00e0 operistica comprende nuove produzioni del Candide di Bernstein al Th\u00e9\u00e2tre du Ch\u00e2telet ed alla Scala. Nelle recenti stagioni ha diretto Tristano e Isotta ad Angers\/Nantes, Kehraus um St. Stephan di Krenek al Festival di Bregenz, le nuove produzioni di Kaiser von Atlantis, Rigoletto, Rake\u2019s Progress, Don Giovanni, L\u2019opera da tre soldi, Idomeneo, tutte per il Festival di Lucerna. Nel febbraio 2014 ha diretto Evgenij Onegin al di San Carlo di Napoli.<br \/>\nIncide sia il repertorio di tradizione sia quello contemporaneo con artisti quali V. Gens, R. Kolly d\u2019Alba, M. Grubinger, P. Kopatchinskaja e D. Henschel, per etichette quali Sony Classical, Warner Classics, Ondine, Universal, Naive e Nimbus. Il prossimo progetto discografico Brahms Beloved vede l\u2019integrale delle Sinfonie di Brahms, con l\u2019Orchestra Sinfonica di Milano \u201cG. Verdi\u201d, abbinate ai Lieder di C. Schumann per la Telarc in uscita nella stagione 2013\/14.<br \/>\nLaureato alla Harvard University nel 1988 e formatosi nella tradizione di Bernstein, ha studiato al Conservatorio di San Pietroburgo con I. Musin nel 1996 ed ha partecipato al programma dell\u2019American Symphony Orchestra League.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_22818\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Benedetto-Lupo-3.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-22818\" class=\"wp-image-22818 size-medium\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Benedetto-Lupo-3-300x199.jpg\" alt=\"Benedetto Lupo\" width=\"300\" height=\"199\" data-id=\"22818\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Benedetto-Lupo-3-300x199.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Benedetto-Lupo-3-1024x681.jpg 1024w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Benedetto-Lupo-3.jpg 1700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-22818\" class=\"wp-caption-text\">Benedetto Lupo<\/p><\/div>\n<p><strong>Benedetto Lupo, pianoforte<\/strong><br \/>\nConsiderato dalla critica internazionale come uno dei talenti pi\u00f9 interessanti e completi della sua generazione, ha debuttato a tredici anni con il Concerto n.1 di Beethoven, imponendosi subito in numerosi concorsi internazionali, tra i quali il Cortot ed il Ciudad de Ja\u00e9n in Europa, il Robert Casadesus, Gina Bachauer e Van Cliburn negli Stati Uniti. Nel 1992, quando la sua intensa attivit\u00e0 concertistica lo vedeva gi\u00e0 impegnato nelle Americhe, in Giappone ed in Europa, ha vinto a Londra il Premio \u201cTerence Judd\u201d.<br \/>\nOspite delle pi\u00f9 prestigiose istituzioni internazionali: Lincoln Center a New York, Salle Pleyel a Parigi, Wigmore Hall a Londra, Philharmonie a Berlino, Benedetto Lupo ha suonato con la Chicago Symphony, Philadelphia Orchestra, Boston Symphony, Los Angeles Philharmonic, Baltimore Symphony, Montreal Symphony, London Philharmonic, Gewandhaus Orchester di Lipsia, Rotterdam Philharmonic, Hall\u00e9 Orchestra, Deutsches Symphonie-Orchester, Orquesta Nacional de Espa\u00f1a e, in Italia, per le istituzioni pi\u00f9 prestigiose, come il Teatro alla Scala di Milano, l\u2019Accademia di S. Cecilia, l\u2019Orchestra Nazionale della RAI e l\u2019Orchestra \u201cVerdi\u201d di Milano, il San Carlo di Napoli, la Fenice di Venezia, i Teatri Comunali di Bologna e di Firenze, il Carlo Felice di Genova, il Regio di Torino e il Verdi di Trieste.<br \/>\nHa inciso per Teldec, Bmg, Vai, Nuova Era e, per la Arts, l\u2019integrale delle composizioni per pianoforte e orchestra di Schumann. Nel 2005 la sua nuova incisione del Concerto Soir\u00e9e di Nino Rota per Harmonia Mundi ha ottenuto ben cinque premi internazionali, tra i quali il \u201cDiapason d\u2019Or\u201d.<br \/>\nNato a Bari, dopo un\u2019audizione con Nino Rota, ha iniziato gli studi con Michele Marvulli al Conservatorio Piccinni, per poi proseguire con Pierluigi Camicia, Marisa Somma, Sergio Perticaroli e Aldo Ciccolini. Ha frequentato le master classe di Carlo Zecchi, Nikita Magaloff, Jorge Bolet, Murray Perahia. Svolge anche un\u2019importante attivit\u00e0 cameristica e didattica: insegna al Conservatorio \u201cNino Rota\u201d di Monopoli, tiene master classe in importanti istituzioni, \u00e8 spesso invitato nelle giurie di concorsi internazionali e, dall\u2019anno accademico 2013\/2014, \u00e8 titolare della cattedra di pianoforte nell\u2019ambito dei corsi di perfezionamento dell\u2019Accademia Nazionale di Santa Cecilia.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_22819\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Gianrico-Carofiglio-C-Francesco-Carofiglio1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-22819\" class=\"size-medium wp-image-22819\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Gianrico-Carofiglio-C-Francesco-Carofiglio1-300x222.jpg\" alt=\"Gianrico Carofiglio\" width=\"300\" height=\"222\" data-id=\"22819\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Gianrico-Carofiglio-C-Francesco-Carofiglio1-300x222.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Gianrico-Carofiglio-C-Francesco-Carofiglio1-270x200.jpg 270w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Gianrico-Carofiglio-C-Francesco-Carofiglio1.jpg 945w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-22819\" class=\"wp-caption-text\">Gianrico Carofiglio<\/p><\/div>\n<p><strong>Gianrico Carofiglio, voce recitante<\/strong><br \/>\n\u00c8 nato a Bari nel 1961. \u00c8 stato a lungo un pubblico ministero, specializzato in indagini sulla criminalit\u00e0 organizzata. Nel 2007 viene nominato consulente della commissione parlamentare antimafia e dal 2008 al 2013 \u00e8 senatore della Repubblica.<br \/>\nEsordisce nella narrativa nel 2002 con Testimone inconsapevole (Premio del Gioved\u00ec \u201cMarisa Rusconi\u201d, Premio Rhegium Iulii, Premio Citt\u00e0 di Cuneo, Premio Citt\u00e0 di Chiavari), creando il personaggio dell\u2019avvocato Guido Guerrieri, molto amato dai lettori e protagonista di tre successivi romanzi: Ad occhi chiusi (2003, Premio Lido di Camaiore, Premio delle Biblioteche di Roma e \u201cMiglior noir internazionale dell\u2019anno 2007\u201d in Germania secondo una giuria di librai e giornalisti), Ragionevoli dubbi (2006, Premio Fregene e Premio Viadana 2007, Premio Tropea 2008) e Le perfezioni provvisorie (2010, Premio Selezione Campiello). Nel 2004 Testimone inconsapevole e Ad occhi chiusi diventano due film per la televisione con la regia di Alberto Sironi e, a partire dal 2007, i quattro romanzi sono pubblicati anche in versione audiolibro, con la voce narrante dello stesso autore.<br \/>\nTra le altre opere di narrativa e saggistica: i romanzi Il passato \u00e8 una terra straniera (2004, Premio Bancarella 2005) da cui nel 2008 \u00e8 tratto l\u2019omonimo film di Daniele Vicari, con Elio Germano e Michele Riondino (miglior film e miglior attore al Miami Film Festival), N\u00e9 qui n\u00e9 altrove. Una notte a Bari (2008) e Il silenzio dell&#8217;onda (2011), finalista al Premio Strega 2012; il graphic novel Cacciatori nelle tenebre (2007, Premio Martoglio), di cui \u00e8 coautore con il fratello Francesco; il dialogo Il paradosso del poliziotto (2009); la raccolta di racconti Non esiste saggezza (2010, Premio Chiara); i saggi L\u2019arte del dubbio (2007) e La manomissione delle parole (2010), da cui \u00e8 tratto uno spettacolo teatrale da lui stesso interpretato; il racconto La velocit\u00e0 dell\u2019angelo nel volume Cocaina (Einaudi Stile Libero 2013, con testi di Massimo Carlotto e Giancarlo De Cataldo).<br \/>\nI libri di Gianrico Carofiglio, con oltre quattro milioni di copie vendute in Italia, sono tradotti in ventiquattro lingue.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_22817\" style=\"width: 226px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Sara-Bevilacqua-4.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-22817\" class=\"wp-image-22817 size-medium\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Sara-Bevilacqua-4-216x300.jpg\" alt=\"Sara Bevilacqua \" width=\"216\" height=\"300\" data-id=\"22817\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Sara-Bevilacqua-4-216x300.jpg 216w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/09\/Sara-Bevilacqua-4.jpg 575w\" sizes=\"auto, (max-width: 216px) 100vw, 216px\" \/><\/a><p id=\"caption-attachment-22817\" class=\"wp-caption-text\">Sara Bevilacqua<\/p><\/div>\n<p><strong>Sara Bevilacqua, voce recitante<\/strong><br \/>\nDiplomata all\u2019Accademia d\u2019Arte Drammatica della Calabria. Ha partecipato a numerosi stage di teatro, danza, poesia e canto, tra cui tre stage all\u2019Accademia d\u2019Arte Drammatica di Varsavia.<br \/>\nTra i suoi lavori recenti: il pluripremiato Furie de sanghe, per la regia di Licia Lanera (Fibre parallele teatro progetto ETI Nuove creativit\u00e0) in tourn\u00e8e europea, Astri e disastri per la regia di Enzo Toma, Rondini e pinguini di E. Toma e Studio su un Barbabl\u00f9 di Antonio Vigan\u00f2, Ulisse il narratore di Ettore Catalano produzione del Teatro Abeliano di Bari, Adriatic express 9-99 de La casa del mare della riserva Marina dello Stato di Torre Guaceto e Leg\u00e0mi riadattamento dell\u2019Antigone.<br \/>\nHa curato la regia di: Italiano prigioniero sono, Torno subito e Revolution, drammaturgia di Emiliano Poddi e Invito a cena con delitto dei Meridiani Perduti, dei corti teatrali Salvatore mio! e Ferita, vincitore del Premio Sardegna in.corto 2010; del concerto spettacolo Delitti quasi perfetti, liberamente ispirato alle atmosfere di Delitti esemplari di Max Aub e dello spettacolo di teatrodanza Ritratti.<br \/>\nAnnovera una breve partecipazione al film La terra di Sergio Rubini. Protagonista del corto Extra di Paola Crescenzo vincitore del premio Briff \u2013 PugliaUnderground. Ha fondato l\u2019associazione artistica culturale Meridiani Perduti. Collabora con la cooperativa Thalassia nel progetto \u201cTeatri abitati\u201d al Teatro comunale di Mesagne e con la Riserva Marina dello Stato di Torre Guaceto. \u00c8 formatrice di Accademia Verdi, progetto per la formazione del pubblico del Nuovo Teatro Verdi di Brindisi. Nel suo percorso artistico alterna l\u2019esperienza di formatrice a quella di esperta teatrale, nell\u2019ambito di progetti didattici ed educativi, finanziati da scuole di ogni ordine e grado ed associazioni cittadine. Da oltre due anni conduce un laboratorio di teatro handicap per Oltre l\u2019orizzonte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marted\u00ec 30 settembre alle 21.00 al Teatro Petruzzelli \u00e8 in cartellone Rach 2. Il concerto rientra nella Stagione Sinfonica 2014. Diriger\u00e0 l\u2019Orchestra del Teatro John Axelrod. In programma la prima esecuzione assoluta de \u201cIl bordo vertiginoso delle cose\u201d, melologo per due voci recitanti e orchestra con musica di Fabio Vacchi, tratto dall\u2019omonimo romanzo di Gianrico Carofiglio. Voci recitanti Gianrico Carofiglio e Sara Bevilacqua. La seconda parte del programma sar\u00e0 dedicata al Concerto n. 2 per pianoforte ed Orchestra in do minore op. 18 di Sergej Rachmaninov, solista Benedetto Lupo. I biglietti sono gi\u00e0 disponibili al Botteghino del Teatro Petruzzelli. Informazioni: 080.975.28.10 Il botteghino sar\u00e0 chiuso per la pausa estiva da luned\u00ec 28 luglio a domenica 24 agosto, le vendite continueranno on line su www.bookingshow.it. &nbsp; John Axelrod, direttore Grazie al suo vasto repertorio, ai programmi innovativi ed allo stile carismatico, John Axelrod \u00e8 considerato uno dei direttori pi\u00f9 interessanti del panorama odierno ed \u00e8 richiesto dalle orchestre di tutto il mondo. Dopo aver completato con successo la sua carica quinquennale&#8230;<\/p>\n","protected":false},"author":2,"featured_media":22821,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[198,7,162],"tags":[511],"class_list":["post-22816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-2","category-news","category-teatro","tag-sara-bevilacqua"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/22816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=22816"}],"version-history":[{"count":4,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/22816\/revisions"}],"predecessor-version":[{"id":22870,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/22816\/revisions\/22870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/22821"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=22816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=22816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=22816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}