{"id":24057,"date":"2014-10-06T18:44:15","date_gmt":"2014-10-06T16:44:15","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=24057"},"modified":"2014-10-06T18:44:15","modified_gmt":"2014-10-06T16:44:15","slug":"protocollo-dintesa-commercialisti-equitalia-attivato-sportello-telematico","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/protocollo-dintesa-commercialisti-equitalia-attivato-sportello-telematico\/","title":{"rendered":"Protocollo d&#8217;intesa Commercialisti-Equitalia: attivato sportello telematico"},"content":{"rendered":"<p>Equitalia Sud conferma la collaborazione con l\u2019Ordine dei Dottori Commercialisti e degli Esperti Contabili di Brindisi. Il protocollo d\u2019intesa, firmato oggi, prevede l\u2019attivazione dello sportello telematico, un canale dedicato che consente di favorire, migliorare e semplificare i rapporti con i professionisti e i loro assistiti.<\/p>\n<p>&nbsp;<\/p>\n<p>Gli iscritti all\u2019ODCEC di Brindisi potranno accedere allo sportello telematico dal sito <a href=\"http:\/\/www.gruppoequitalia.it\/\">www.gruppoequitalia.it<\/a>. Compilando il Form presente nella sezione \u201c<a href=\"http:\/\/www.gruppoequitalia.it\/equitalia\/opencms\/it\/cittadini\/AccordiEnti\/\">Accordi con Enti, Associazioni e Ordini<\/a>\u201d e allegando la documentazione necessaria, potranno richiedere informazioni, consulenza e fissare un appuntamento per le situazioni pi\u00f9 complesse e delicate.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab<em>L\u2019accordo che avr\u00e0 una durata di due anni <\/em>\u2013 dichiara Leonardo Arrigoni direttore regionale Puglia di Equitalia Sud \u2013<em> s\u2019inserisce nel percorso di collaborazione e ascolto intrapreso dal Gruppo Equitalia. Lo sportello telematico garantisce servizi efficaci e facilmente fruibili e consente di migliorare costantemente i rapporti con i professionisti e con i cittadini da loro assistiti. La collaborazione con l\u2019ODCEC di Brindisi permetter\u00e0 inoltre, di organizzare incontri tematici volti a rafforzare lo scambio di informazioni sui temi della riscossione<\/em>\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab<em>Con l\u2019intesa sottoscritta oggi <\/em>\u2013 dichiara Giovanni Fabio Aiello, presidente dell\u2019ODCEC di Brindisi \u2013<em> si riafferma la centralit\u00e0 dei Dottori Commercialisti ed Esperti Contabili nei rapporti con le Istituzioni e si riconosce la competenza del professionista nei rapporti con il sistema esattivo, a beneficio non solo delle piccole e medie imprese ma anche dei privati cittadini. Gli iscritti al nostro Ordine &#8211; conclude Aiello &#8211; hanno gi\u00e0 avuto modo di rilevare e tanto, sono certo, sar\u00e0 confermato anche in futuro, che con i canali riservati in via esclusiva, si ottiene una decisa semplificazione delle procedure di accesso ai servizi con un enorme risparmio di tempo e di energie. Il tutto nell\u2019ottica della trasparenza nei rapporti fra Equitalia e cittadini<\/em>\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Equitalia Sud conferma la collaborazione con l\u2019Ordine dei Dottori Commercialisti e degli Esperti Contabili di Brindisi. Il protocollo d\u2019intesa, firmato oggi, prevede l\u2019attivazione dello sportello telematico, un canale dedicato che consente di favorire, migliorare e semplificare i rapporti con i professionisti e i loro assistiti. &nbsp; Gli iscritti all\u2019ODCEC di Brindisi potranno accedere allo sportello telematico dal sito www.gruppoequitalia.it. Compilando il Form presente nella sezione \u201cAccordi con Enti, Associazioni e Ordini\u201d e allegando la documentazione necessaria, potranno richiedere informazioni, consulenza e fissare un appuntamento per le situazioni pi\u00f9 complesse e delicate. &nbsp; \u00abL\u2019accordo che avr\u00e0 una durata di due anni \u2013 dichiara Leonardo Arrigoni direttore regionale Puglia di Equitalia Sud \u2013 s\u2019inserisce nel percorso di collaborazione e ascolto intrapreso dal Gruppo Equitalia. Lo sportello telematico garantisce servizi efficaci e facilmente fruibili e consente di migliorare costantemente i rapporti con i professionisti e con i cittadini da loro assistiti. La collaborazione con l\u2019ODCEC di Brindisi permetter\u00e0 inoltre, di organizzare incontri tematici volti a rafforzare lo scambio di informazioni sui temi della&#8230;<\/p>\n","protected":false},"author":2,"featured_media":24058,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2710,1215],"class_list":["post-24057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-commercialisti","tag-equitalia"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/24057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=24057"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/24057\/revisions"}],"predecessor-version":[{"id":24059,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/24057\/revisions\/24059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/24058"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=24057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=24057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=24057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}