{"id":24079,"date":"2014-10-07T10:15:15","date_gmt":"2014-10-07T08:15:15","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=24079"},"modified":"2014-10-07T10:36:51","modified_gmt":"2014-10-07T08:36:51","slug":"citta-europea-dello-sport-venerdi-festa-dello-sport-alla-scuola-media-pacuvio","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/citta-europea-dello-sport-venerdi-festa-dello-sport-alla-scuola-media-pacuvio\/","title":{"rendered":"Citt\u00e0 Europea dello Sport: venerdi Festa dello Sport alla Scuola Media Pacuvio"},"content":{"rendered":"<p>Venerd\u00ec prossimo, 10 ottobre, a partire dalle ore 9, nel giardino della scuola media <em>Pacuvio<\/em> in viale Togliatti 4, ha luogo la <em>Festa dello Sport <\/em>nell&#8217;ambito delle iniziative legate a Brindisi <strong><em>Citt\u00e0 europea dello sport 2014<\/em><\/strong>.<\/p>\n<p>La manifestazione \u00e8 stata progettata dalla dirigente scolastica, Elvira D\u2019Al\u00f2 e dalla professoressa Rosa D\u2019Al\u00f2 e realizzata grazie al contributo del Comune di Brindisi all\u2019interno del progetto che ha riconosciuto Brindisi citt\u00e0 europea dello sport.<\/p>\n<p>Vari discipline previste per la Festa dello Sport: un percorso degli alunni delle classi quarte e quinte della scuola primaria <em>Don Milani<\/em> e delle classi seconde della scuola media <em>Pacuvio,<\/em> preparato dalle professoresse Daniela Petrolo, Michela Cosolo ed Emere Pennetta; un\u2019esibizione di ginnastica ritmica coordinata dalla professoressa Silvia Lapomarda; un\u2019esibizione della squadra di rugby di Brindisi <em>Nafta<\/em>; e un f<em>lash mob<\/em> sulle note di <em>Party rock Anthem<\/em>, <a href=\"http:\/\/it.wikipedia.org\/wiki\/Brano_musicale\">brano musicale<\/a> del duo <em><a href=\"http:\/\/it.wikipedia.org\/wiki\/Elettrorap\">elettrorap<\/a><\/em> <a href=\"http:\/\/it.wikipedia.org\/wiki\/Stati_Uniti\">statunitense<\/a> <em><a href=\"http:\/\/it.wikipedia.org\/wiki\/LMFAO\">LMFAO<\/a><\/em>, eseguito da alunni di tutte le classi della scuola media.<\/p>\n<p>Sono stati invitati alla Festa dello Sport il sindaco di Brindisi dott. Mimmo Consales, il dirigente dell\u2019Ufficio Scolastico Provinciale dott. Vincenzo Melilli, il presidente del Coni dott. Nicola Cainazzo, sua Eccellenza l\u2019arcivescovo monsignor Domenico Caliandro, il dirigente della Pubblica Istruzione Gaetano Padula, il geometra Carlo Pesari, l\u2019assessore alla pubblica Istruzione prof. Gioacchino Margarito, l\u2019assessore allo Sport dott. Antonio Ingrosso, l\u2019assessore ai lavori pubblici dott. Cosimo D\u2019Angelo, il Presidente nazionale della Lega Basket dott. Nando Marino insieme ai dirigenti dell\u2019Enel Basket Brindisi dott. Alessandro Giuliani, dott. Renato Nicolai e dott. Claudio Olivieri e tutti i giocatori della squadra che milita in serie A.<\/p>\n<p>Non possono mancare alla grande festa dello sport i genitori dell\u2019Istituto Comprensivo Santa Chiara.<\/p>\n<p>La Dirigente ha invitato con grande piacere i colleghi degli Istituti Comprensivi di Brindisi e si augura che soprattutto gli abitanti del quartiere possano entrare volentieri nel giardino della scuola incuriositi dal clima di festa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec prossimo, 10 ottobre, a partire dalle ore 9, nel giardino della scuola media Pacuvio in viale Togliatti 4, ha luogo la Festa dello Sport nell&#8217;ambito delle iniziative legate a Brindisi Citt\u00e0 europea dello sport 2014. La manifestazione \u00e8 stata progettata dalla dirigente scolastica, Elvira D\u2019Al\u00f2 e dalla professoressa Rosa D\u2019Al\u00f2 e realizzata grazie al contributo del Comune di Brindisi all\u2019interno del progetto che ha riconosciuto Brindisi citt\u00e0 europea dello sport. Vari discipline previste per la Festa dello Sport: un percorso degli alunni delle classi quarte e quinte della scuola primaria Don Milani e delle classi seconde della scuola media Pacuvio, preparato dalle professoresse Daniela Petrolo, Michela Cosolo ed Emere Pennetta; un\u2019esibizione di ginnastica ritmica coordinata dalla professoressa Silvia Lapomarda; un\u2019esibizione della squadra di rugby di Brindisi Nafta; e un flash mob sulle note di Party rock Anthem, brano musicale del duo elettrorap statunitense LMFAO, eseguito da alunni di tutte le classi della scuola media. Sono stati invitati alla Festa dello Sport il sindaco di Brindisi dott. Mimmo Consales, il&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5891,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1070],"class_list":["post-24079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-citta-europea-dello-sport"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/24079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=24079"}],"version-history":[{"count":0,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/24079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/5891"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=24079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=24079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=24079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}