{"id":24126,"date":"2014-10-08T09:42:42","date_gmt":"2014-10-08T07:42:42","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=24126"},"modified":"2014-10-07T19:44:06","modified_gmt":"2014-10-07T17:44:06","slug":"nasce-il-movimento-la-ceglie-che-mi-piace","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/nasce-il-movimento-la-ceglie-che-mi-piace\/","title":{"rendered":"Nasce il movimento &#8220;La Ceglie che mi piace&#8221;"},"content":{"rendered":"<p>E\u2019 nato nella citt\u00e0 di Ceglie Messapica un nuovo movimento politico-culturale, \u201cLa Ceglie che mi piace\u201d.<\/p>\n<p>Si tratta di un gruppo di giovani donne e uomini che hanno scelto di impegnarsi per Ceglie e di contribuire in modo determinante al cambiamento e al rinnovamento della citt\u00e0.<br \/>\n\u201cLa Ceglie che mi piace\u201d vuol dire riscoprire le nostre radici e mettere le ali al futuro; recuperare le tradizioni con un sguardo all\u2019innovazione; ritornare alla politica fatta per passione facendo rifiorire il desiderio di riavvicinarsi alle istituzioni che si distinguono per la \u201cpolitica del fare\u201d.<br \/>\nIl gruppo vuole distinguersi per la straordinaria voglia di impegnarsi per il bene comune e fa appello a chiunque voglia aderire. Nessuno si senta escluso. La nostra unica prerogativa deve essere l\u2019attaccamento alla nostra amata citt\u00e0.<br \/>\nLa nostra missione sar\u00e0 ridare la parola ai giovani, restituire ai cittadini la giusta attenzione che meritano. La nostra missione sar\u00e0 convincere i giovani a tornare a guardare al futuro come piacere e come sfida. Alziamoci dalla sedia della indifferenza e insieme continuiamo a far crescere la nostra citt\u00e0, cos\u00ec ognuno di noi potr\u00e0 dire con orgoglio : \u00e8 questa \u201cla Ceglie che mi piace\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMUNICATO STAMPA<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 nato nella citt\u00e0 di Ceglie Messapica un nuovo movimento politico-culturale, \u201cLa Ceglie che mi piace\u201d. Si tratta di un gruppo di giovani donne e uomini che hanno scelto di impegnarsi per Ceglie e di contribuire in modo determinante al cambiamento e al rinnovamento della citt\u00e0. \u201cLa Ceglie che mi piace\u201d vuol dire riscoprire le nostre radici e mettere le ali al futuro; recuperare le tradizioni con un sguardo all\u2019innovazione; ritornare alla politica fatta per passione facendo rifiorire il desiderio di riavvicinarsi alle istituzioni che si distinguono per la \u201cpolitica del fare\u201d. Il gruppo vuole distinguersi per la straordinaria voglia di impegnarsi per il bene comune e fa appello a chiunque voglia aderire. Nessuno si senta escluso. La nostra unica prerogativa deve essere l\u2019attaccamento alla nostra amata citt\u00e0. La nostra missione sar\u00e0 ridare la parola ai giovani, restituire ai cittadini la giusta attenzione che meritano. La nostra missione sar\u00e0 convincere i giovani a tornare a guardare al futuro come piacere e come sfida. Alziamoci dalla sedia della indifferenza e insieme&#8230;<\/p>\n","protected":false},"author":2,"featured_media":24127,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[577],"class_list":["post-24126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-ceglie"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/24126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=24126"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/24126\/revisions"}],"predecessor-version":[{"id":24128,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/24126\/revisions\/24128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/24127"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=24126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=24126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=24126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}