{"id":24747,"date":"2014-10-14T11:28:43","date_gmt":"2014-10-14T09:28:43","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=24747"},"modified":"2014-10-14T11:31:04","modified_gmt":"2014-10-14T09:31:04","slug":"torre-guaceto-matarrelli-un-delitto-ai-danni-della-nostra-umanita","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/torre-guaceto-matarrelli-un-delitto-ai-danni-della-nostra-umanita\/","title":{"rendered":"Torre Guaceto, Matarrelli: &#8220;un delitto ai danni della nostra umanit\u00e0&#8221;"},"content":{"rendered":"<p>L\u2019autorizzazione allo scarico delle acque reflue dell\u2019impianto consortile di trattamento a servizio dell\u2019agglomerato di Carovigno direttamente nel cuore dell\u2019Area Marina Protetta \u00e8 pi\u00f9 di un errore marchiano al quale pure occorre porre rapido rimedio, \u00e8 un delitto ai danni della nostra umanit\u00e0, del nostro futuro quindi di uomini degni. Non mi soffermer\u00f2 sugli aspetti legali della questione, sui quali sarebbe in ogni caso necessario riflettere, dato che Torre Guaceto \u00e8 una riserva naturale dello Stato su cui insistono vincoli severissimi, condizione di cui non si \u00e8, con tutta evidenza, tenuto conto. Considero per\u00f2 grave che il governo regionale abbia omesso di effettuare la Valutazione di Incidenza Ambientale sullo scarico temporaneo nel canale Reale del nuovo depuratore consortile di Carovigno ed auspico una rapida soluzione alternativa allo scarico a mare.<\/p>\n<p>&nbsp;<\/p>\n<p>Mi preme invece sottolineare che Torre Guaceto rappresenta una risorsa da tutelare ad ogni costo, sia per il valore intrinseco dell\u2019oasi, sul piano culturale, naturalistico, paesaggistico, turistico ed insomma economico, sia perch\u00e9 costituisce un modello, peraltro riuscito, di sviluppo sostenibile che eroga valore per il territorio. Oltre ai positivi impatti sul turismo e sull\u2019immagine della provincia di Brindisi e di tutta la Puglia, l\u2019esperienza di Torre Guaceto dimostra che \u00e8 possibile coniugare il rispetto dell\u2019ambiente con lo sviluppo e con il lavoro.<\/p>\n<p>&nbsp;<\/p>\n<p>Le diverse produzioni biologiche del parco &#8211; tra cui l\u2019ormai noto \u201cpomodoro fiaschetto di Torre Guaceto\u201d, coltivazione storica dell&#8217;area, dimenticata e quasi persa &#8211; hanno trovato felici riscontri a livello nazionale ed internazionale con importanti ricadute occupazionali ed economiche. Torre Guaceto non \u00e8 solo una parentesi immaginifica, una proiezione fugace che ci discolpa dal nostro martoriare le restanti parti della Puglia (e qui penso certamente all&#8217;insolenza degli impianti fotovoltaici), \u00e8 invece un modello da rilevare ed esportare altrove.<\/p>\n<p>&nbsp;<\/p>\n<p>Questa sgraziata vicenda, peraltro, ha indotto ad emergere altri problemi importanti e finora sottovalutati.<\/p>\n<p>Mi riferisco all\u2019esistenza di un impianto di raffinazione delle acque, costruito con fondi provinciali da circa due decenni e collocato nel territorio di Mesagne, che inspiegabilmente l&#8217;Acquedotto Pugliese non ha mai messo in funzione. L\u2019attivazione di tale struttura consentirebbe di ottenere acqua utile all\u2019irrigazione agricola con un vantaggio di carattere ambientale (riduzione dello sfruttamento della falda ed abbattimento del versamento in mare di acque inquinate), ed uno di matrice economica per i nostri agricoltori.<\/p>\n<p>Vi \u00e8 infine la presenza, sempre nel territorio di Mesagne, sul percorso del Canale Reale, di una voragine naturale che assorbirebbe le acque reflue dei depuratori dei comuni di Latiano, Francavilla Fontana e Ceglie Messapica che in tal modo di fatto sversano in falda, con conseguenze di cui non \u00e8 facile prevedere la portata ma che non possono non inquietare.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Toni Matarrelli<\/strong><\/p>\n<p><strong>Deputato della Repubblica<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019autorizzazione allo scarico delle acque reflue dell\u2019impianto consortile di trattamento a servizio dell\u2019agglomerato di Carovigno direttamente nel cuore dell\u2019Area Marina Protetta \u00e8 pi\u00f9 di un errore marchiano al quale pure occorre porre rapido rimedio, \u00e8 un delitto ai danni della nostra umanit\u00e0, del nostro futuro quindi di uomini degni. Non mi soffermer\u00f2 sugli aspetti legali della questione, sui quali sarebbe in ogni caso necessario riflettere, dato che Torre Guaceto \u00e8 una riserva naturale dello Stato su cui insistono vincoli severissimi, condizione di cui non si \u00e8, con tutta evidenza, tenuto conto. Considero per\u00f2 grave che il governo regionale abbia omesso di effettuare la Valutazione di Incidenza Ambientale sullo scarico temporaneo nel canale Reale del nuovo depuratore consortile di Carovigno ed auspico una rapida soluzione alternativa allo scarico a mare. &nbsp; Mi preme invece sottolineare che Torre Guaceto rappresenta una risorsa da tutelare ad ogni costo, sia per il valore intrinseco dell\u2019oasi, sul piano culturale, naturalistico, paesaggistico, turistico ed insomma economico, sia perch\u00e9 costituisce un modello, peraltro riuscito, di sviluppo sostenibile&#8230;<\/p>\n","protected":false},"author":2,"featured_media":23153,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[534,1126],"class_list":["post-24747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-matarrelli","tag-torre-guaceto"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/24747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=24747"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/24747\/revisions"}],"predecessor-version":[{"id":24748,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/24747\/revisions\/24748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/23153"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=24747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=24747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=24747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}