{"id":248269,"date":"2025-07-30T16:50:21","date_gmt":"2025-07-30T14:50:21","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=248269"},"modified":"2025-08-07T11:18:17","modified_gmt":"2025-08-07T09:18:17","slug":"la-musica-a-brindisi-quale-futuro-di-marco-greco","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/la-musica-a-brindisi-quale-futuro-di-marco-greco\/","title":{"rendered":"La musica a Brindisi. Quale futuro? Di Marco Greco"},"content":{"rendered":"<p>Abbiamo appreso con stupore e tristezza della chiusura del negozio di strumenti musicali \u201cIdee Musicali\u201d di Antonio Baldassarre.<\/p>\n<p>L\u2019esercizio era una delle ultime e coraggiose realt\u00e0 rimasta in citt\u00e0 che si occupava anche di partiture per l\u2019insegnamento, riparazioni, accordature e noleggi per gli spettacoli.<\/p>\n<p>La crisi di questo settore \u00e8 un tema attuale. Ci sono diversi segnali di difficolt\u00e0 e chiusure in tutte le citt\u00e0 italiane. Il Covid ha accentuato le problematiche, ma il commercio on line ha indebolito il settore non potendo competere con i prezzi delle piattaforme musicali.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel mondo della musica molti negozi di dischi faticano a vivere. Anche a Brindisi, nonostante la variet\u00e0 e la ricchezza di alcuni negozi storici degli anni passati, il mercato dei vinile e del CD si \u00e8 trasferito in alcune librerie ma soprattutto sulle piattaforme online.<\/p>\n<p>Entrare oggi in un negozio di dischi o di strumenti musicali \u00e8 come andare al museo e respirare la storia della musica. Cominciano a farsi notare la mancanza di vetrine variopinte con addosso la curiosit\u00e0 di provare uno strumento o di spulciare gli scaffali dei dischi con il gesto del castoro.<\/p>\n<p>In un periodo di consumo di musica liquida, auto tune e cover band, continuare a respirare musica vera e originale significa mettere nelle condizioni la comunit\u00e0 di vivere in maniera creativa condividendo incontri, concerti e seminari, anche attraverso le risorse locali.<\/p>\n<p>Essere propositivi nella propria terra pu\u00f2 rappresentare una forma potente di rivoluzione culturale e di sostegno costante a tutte le attivit\u00e0, anche a quelle commerciali.<\/p>\n<p>Un sogno che aveva preso forma negli anni passati grazie alla tenacia di alcuni soggetti innamorati del territorio.<\/p>\n<p>&nbsp;<\/p>\n<p>La musica nella nostra citt\u00e0 ha nuovamente bisogno di fiducia e calore. Pu\u00f2 essere ravvivata nei numerosi locali del centro storico attraverso nuovi incontri propositivi e risolutivi tra i gestori, gli abitanti e le Istituzioni locali.<\/p>\n<p>La scena musicale brindisina conserva un\u2019anima autentica.<\/p>\n<p>Una vibrazione sottile che ha attraversato il tempo senza aver mai ricevuto il giusto valore e soprattutto continuit\u00e0 ai suoi festival e spettacoli musicali.<\/p>\n<p>&nbsp;<\/p>\n<p>Negli ultimi anni si sono persi alcuni concerti di notevole qualit\u00e0 e spessore come il Festival del Blues Citt\u00e0 di Brindisi, Yeahjasi! Brindisi Pop Fest, le rassegne dedicate al jazz, fino a quell\u2019esperimento ben riuscito del Maestro Stefano Miceli di organizzare per la prima volta un\u2019Orchestra stabile nel Nuovo Teatro Verdi con le esibizioni al Concerto di Capodanno e inaugurando la stagione sinfonica con i concerti dedicati all\u2019ONU e alla Polizia di Stato.<\/p>\n<p>Oggi ben vengano i dj set nelle piazze, le cover band, i saggi di fine anno e il vernacolo nelle periferie. Ma per rendere una citt\u00e0 attrattiva, valorizzare artisti, luoghi e spettacoli, far crescere una comunit\u00e0 serve di pi\u00f9, molto di pi\u00f9.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>MARCO GRECO<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abbiamo appreso con stupore e tristezza della chiusura del negozio di strumenti musicali \u201cIdee Musicali\u201d di Antonio Baldassarre. L\u2019esercizio era una delle ultime e coraggiose realt\u00e0 rimasta in citt\u00e0 che si occupava anche di partiture per l\u2019insegnamento, riparazioni, accordature e noleggi per gli spettacoli. La crisi di questo settore \u00e8 un tema attuale. Ci sono diversi segnali di difficolt\u00e0 e chiusure in tutte le citt\u00e0 italiane. Il Covid ha accentuato le problematiche, ma il commercio on line ha indebolito il settore non potendo competere con i prezzi delle piattaforme musicali. &nbsp; Nel mondo della musica molti negozi di dischi faticano a vivere. Anche a Brindisi, nonostante la variet\u00e0 e la ricchezza di alcuni negozi storici degli anni passati, il mercato dei vinile e del CD si \u00e8 trasferito in alcune librerie ma soprattutto sulle piattaforme online. Entrare oggi in un negozio di dischi o di strumenti musicali \u00e8 come andare al museo e respirare la storia della musica. Cominciano a farsi notare la mancanza di vetrine variopinte con addosso la&#8230;<\/p>\n","protected":false},"author":2,"featured_media":248270,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,189,7],"tags":[],"class_list":["post-248269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interventi","category-musica-2","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/248269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=248269"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/248269\/revisions"}],"predecessor-version":[{"id":248271,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/248269\/revisions\/248271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/248270"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=248269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=248269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=248269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}