{"id":248698,"date":"2025-09-03T10:53:03","date_gmt":"2025-09-03T08:53:03","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=248698"},"modified":"2025-09-03T11:40:38","modified_gmt":"2025-09-03T09:40:38","slug":"francavilla-fontana-si-prepara-a-vivere-la-sua-festa-patronale-in-onore-di-maria-ss-della-fontana","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/francavilla-fontana-si-prepara-a-vivere-la-sua-festa-patronale-in-onore-di-maria-ss-della-fontana\/","title":{"rendered":"Francavilla Fontana si prepara a vivere la sua Festa Patronale in onore di Maria SS. della Fontana"},"content":{"rendered":"<p>Francavilla Fontana si prepara a vivere la sua Festa Patronale in onore di Maria SS. della Fontana nei giorni 11, 12, 13 e 14 settembre 2025, con un programma che intreccia fede, tradizione, cultura e spettacolo.<\/p>\n<p>Ma quest\u2019anno, la festa inizier\u00e0 ben prima. L\u2019edizione 2025 \u00e8 promossa dal Comitato Festa Patronale, con il sostegno dell\u2019Amministrazione Comunale e la partnership della Pro Loco di Francavilla Fontana, a conferma di un impegno condiviso per rendere la festa un vero patrimonio della comunit\u00e0.<\/p>\n<p>Ad anticipare il cuore dei festeggiamenti sar\u00e0 infatti un \u201cpre-festa\u201d diffuso, costruito con il contributo delle associazioni cittadine e di realt\u00e0 culturali come il MAFF di Francavilla Fontana. Giornate dedicate allo sport, all\u2019inclusione, alla cura della memoria collettiva e a momenti di partecipazione condivisa, pensati per avvicinare progressivamente la citt\u00e0 al suo appuntamento pi\u00f9 atteso. Fra gli eventi in programma, la Partita del Cuore allo Stadio Giovanni Paolo II, i tornei di basket e volley in villa, attivit\u00e0 per bambini, laboratori, incontri e visite guidate.<\/p>\n<p>Alcune di queste saranno dedicate alla riscoperta degli antichi mestieri francavillesi, come quello del cartapestaio, con il supporto delle realt\u00e0 locali impegnate nella valorizzazione del patrimonio immateriale.<\/p>\n<p>&nbsp;<\/p>\n<p>In questa edizione, la Festa si riappropria anche della sua leggenda fondativa: un principe in cerca, una Madonna che appare alla fonte, un cervo che si inginocchia. Una narrazione che oggi diventa simbolo di scelta, ascolto e cammino condiviso. Un messaggio che verr\u00e0 evocato simbolicamente anche nella serata di apertura, come atto di fondazione collettiva di una festa che vuole unire, non solo intrattenere. Il programma civile \u2013 ancora in evoluzione \u2013 trover\u00e0 il suo culmine nelle quattro giornate centrali.<\/p>\n<p>&nbsp;<\/p>\n<p>Gioved\u00ec 11 settembre, il pomeriggio sar\u00e0 animato dai giochi tradizionali nel centro storico, con il grande momento di \u201cUn, due, tre&#8230; stella!\u201d su tutta Via Roma, promosso da Casa Armonica di Ceglie Messapica. In Piazza Umberto I si terr\u00e0, poco prima dell\u2019inaugurazione ufficiale,\u00a0 una raccolta solidale di peluche in collaborazione con l\u2019hotspot di Lampedusa, per portare un gesto di vicinanza concreta ai pi\u00f9 piccoli che affrontano il viaggio pi\u00f9 difficile. Alle 20.30, si terr\u00e0 l\u2019apertura ufficiale della Festa, con l\u2019accensione delle luminarie; seguir\u00e0 alle 21.00 il concerto dell\u2019Orchestra Mancina in cassarmonica, che dar\u00e0 ufficialmente il via alla musica della festa.<\/p>\n<p>&nbsp;<\/p>\n<p>Venerd\u00ec 12, laboratori, attivit\u00e0 inclusive, corsi di pizzica, giochi per bambini e momenti di convivialit\u00e0 animeranno il pomeriggio cittadino. Tra gli appuntamenti pi\u00f9 sentiti della giornata, il Color Party in programma su Via Roma: un\u2019esplosione di colori e sorrisi pensata per promuovere l\u2019inclusione attraverso il gioco, l\u2019accessibilit\u00e0 e il coinvolgimento attivo dei pi\u00f9 piccoli. Alle 20.30, in cassarmonica, un concerto di musica popolare a cura del gruppo Ha\u00ectra dar\u00e0 inizio alla serata e accompagner\u00e0 il pubblico verso l\u2019evento principale della giornata. Nel frattempo, in Piazza Vittorio Emanuele II, una sagra di specialit\u00e0 locali curata dalla Pro Loco offrir\u00e0 un\u2019occasione di convivialit\u00e0 all\u2019insegna dei sapori della tradizione.<\/p>\n<p>Alle 22.00, in Piazza Giovanni XXIII, il concerto di Antonio Castrignan\u00f2 con il suo spettacolo \u201cBabilonia\u201d: un\u2019esplosione di ritmo e visione, in cui la tradizione salentina incontra il respiro del mondo, rendendo la musica un ponte tra identit\u00e0 e futuro.<\/p>\n<p>&nbsp;<\/p>\n<p>Sabato 13, Francavilla sar\u00e0 attraversata da un intreccio di proposte che coinvolgeranno attivamente i partecipanti: laboratori, spettacoli e attivit\u00e0 diffuse pensate per ogni fascia d\u2019et\u00e0. Il centro citt\u00e0 si trasformer\u00e0 in un circuito vivo, pronto ad accogliere i visitatori in un\u2019atmosfera calda e festosa, tra concerti e spettacoli itineranti che accompagneranno la serata fino al grande show dei Nine Beat in Piazza Umberto I. Domenica 14, giorno della Madonna della Fontana, sar\u00e0 il cuore spirituale della Festa. Le celebrazioni religiose saranno accompagnate, al mattino, dal concerto bandistico in cassarmonica con la partecipazione della Banda \u201cCitt\u00e0 di Francavilla Fontana\u201d diretta dal M\u00b0 Ermir Krantja e della Banda di Lanciano diretta dal M\u00b0 Michele Milone. Nel pomeriggio si rinnover\u00e0 l\u2019omaggio floreale alla Madonna, a cui seguir\u00e0 la Solenne Processione per le vie della citt\u00e0. Al rientro, le bande torneranno in cassarmonica per un secondo grande concerto, in attesa del corteo verso Parapallo e del consueto, attesissimo spettacolo pirotecnico di mezzanotte.<\/p>\n<p>&nbsp;<\/p>\n<p>Luned\u00ec 15 settembre, alle ore 19.00, in cassarmonica si terr\u00e0 il momento ufficiale di ringraziamento con la consegna dei riconoscimenti a sponsor e autorit\u00e0. A chiudere l\u2019edizione 2025, Max Gazz\u00e8 in Piazza Giovanni XXIII, a cura dell\u2019Amministrazione Comunale di Francavilla Fontana. Quella che sta per arrivare non \u00e8 solo una festa, \u00e8 un\u2019esperienza collettiva, un racconto di comunit\u00e0, un patto simbolico tra memoria e futuro. Francavilla \u00e8 pronta. Il cervo ci guida. La luce si accende.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Francavilla Fontana si prepara a vivere la sua Festa Patronale in onore di Maria SS. della Fontana nei giorni 11, 12, 13 e 14 settembre 2025, con un programma che intreccia fede, tradizione, cultura e spettacolo. Ma quest\u2019anno, la festa inizier\u00e0 ben prima. L\u2019edizione 2025 \u00e8 promossa dal Comitato Festa Patronale, con il sostegno dell\u2019Amministrazione Comunale e la partnership della Pro Loco di Francavilla Fontana, a conferma di un impegno condiviso per rendere la festa un vero patrimonio della comunit\u00e0. Ad anticipare il cuore dei festeggiamenti sar\u00e0 infatti un \u201cpre-festa\u201d diffuso, costruito con il contributo delle associazioni cittadine e di realt\u00e0 culturali come il MAFF di Francavilla Fontana. Giornate dedicate allo sport, all\u2019inclusione, alla cura della memoria collettiva e a momenti di partecipazione condivisa, pensati per avvicinare progressivamente la citt\u00e0 al suo appuntamento pi\u00f9 atteso. Fra gli eventi in programma, la Partita del Cuore allo Stadio Giovanni Paolo II, i tornei di basket e volley in villa, attivit\u00e0 per bambini, laboratori, incontri e visite guidate. Alcune di queste saranno dedicate&#8230;<\/p>\n","protected":false},"author":2,"featured_media":248700,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-248698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/248698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=248698"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/248698\/revisions"}],"predecessor-version":[{"id":248701,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/248698\/revisions\/248701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/248700"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=248698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=248698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=248698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}